{"id":962027,"date":"2026-05-13T07:16:49","date_gmt":"2026-05-13T11:16:49","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/"},"modified":"2026-05-13T07:16:49","modified_gmt":"2026-05-13T11:16:49","slug":"kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/","title":{"rendered":"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year"},"content":{"rendered":"<div class=\"mw_release\">\n<ul>\n<li style=\"text-align:justify\">\n          <em>Q1-2026 Revenue of $45.2 Million, up 3% Year-over-Year; Adjusted EBITDA of $11.6 Million, representing a Robust 26% Margin of Revenues<\/em><br \/>\n          <em>; Net Income of $4.1 Million, up 4% Year-over-Year<\/em>\n        <\/li>\n<li style=\"text-align:justify\">\n          <em>Underlying Demand for the Company\u2019s Products Continues to Increase,<\/em><br \/>\n          <em> Supporting the Company\u2019s Expectation for a Significantly Stronger Remainder of 2026<\/em>\n        <\/li>\n<li style=\"text-align:justify\">\n          <em>Company Affirms <\/em><br \/>\n          <em>2026 Annual Guidance of $200 Million \u2013 $205 Million in Revenues and $50 Million \u2013 $53 Million of Adjusted EBITDA, Representing Annual Double-Digit Organic Profitable Growth<\/em>\n        <\/li>\n<li style=\"text-align:justify\">\n          <em>Q1-2026 Results Impacted by Temporary Shipment Delay of a Single Order, Subsequently Delivered during April\u00a0 <\/em>\n        <\/li>\n<li style=\"text-align:justify\">\n          <em>Company Continues to Evaluate Near-Term Business Development and M&amp;A Transactions to Further Enhance Long-Term Profitable Growth<\/em>\n        <\/li>\n<li style=\"text-align:justify\">\n          <em>Conference Call and Live Webcast Today at 8:30am ET<br \/><\/em>\n        <\/li>\n<\/ul>\n<p align=\"justify\">REHOVOT, Israel, and HOBOKEN, N.J., May  13, 2026  (GLOBE NEWSWIRE) &#8212; Kamada Ltd. (NASDAQ: KMDA; TASE: KMDA.TA), a global biopharmaceutical company with a portfolio of marketed products indicated for rare and serious conditions and a leader in the specialty plasma-derived therapies field, today announced financial results for the three months ended March 31, 2026.<\/p>\n<p align=\"justify\">\u201cOur operational and financial performance in 2026 is off to a solid start, with first quarter revenues and adjusted EBITDA in line with our expectations,\u201d said Amir London, Kamada\u2019s Chief Executive Officer. \u201cTotal revenues for the first quarter were $45.2 million, an increase of approximately 3% year-over-year, and adjusted EBITDA was $11.6 million, representing a robust 26% margin of revenue. Net income for the quarter was $4.1 million, up 4% year-over-year. While temporary shipment delay of a single order, subsequently delivered during April, affected first quarter financial results, importantly, the underlying demand of our products, including for KEDRAB<sup>\u00ae<\/sup> in the U.S. market as well as KAMRAB<sup>\u00ae<\/sup> and VARIZIG<sup>\u00ae<\/sup> in ex-U.S. markets, continues to increase, supporting our confidence for a significantly stronger remainder of 2026. We are reiterating our 2026 annual guidance of $200 million to $205 million in revenues and $50 million to $53 million of adjusted EBITDA, respectively, representing 12% and 23% growth when comparing 2026 guidance mid-points to 2025 results.\u201d<\/p>\n<p align=\"justify\">\u201cIn 2026, our focus remains on the expansion of our entire commercial product portfolio, including our six FDA-approved specialty plasma-derived products. In our Distribution segment, growth is supported by the launch of additional biosimilar products in the Israeli market, as well our expansion of the Distribution business to the MENA region. We are ramping up plasma collection in our three FDA-approved Texas-based plasma centers, which are expected to provide significant capacity of specialty and normal source plasma collection, strengthening our vertical integration and supporting continued growth. Lastly, we continue to make progress evaluating and securing near-term new business development and M&amp;A opportunities that will enrich our current portfolio and generate synergies with our existing commercial operations,\u201d concluded Mr. London.<\/p>\n<p align=\"justify\">\n        <strong>Financial Highlights for the Three Months Ended March 31, 2026<\/strong>\n      <\/p>\n<ul type=\"disc\">\n<li style=\"text-align:justify\">Total revenues were $45.2 million in the first quarter of 2026, an increase of 3% compared to $44.0 million in the first quarter of 2025. The increase in revenues year-over-year was primarily driven by increased sales of KEDRAB, as well as increased sales in our Distribution segment. \u00a0<\/li>\n<li style=\"text-align:justify\">Gross profit and gross margins were $19.1 million and 42%, respectively, in the first quarter of 2026, compared to $20.7 million and 47%, respectively, in the first quarter of 2025. The reduction in gross margin year-over-year was affected by products and markets&#8217; sales mix.<\/li>\n<li style=\"text-align:justify\">Operating expenses, including R&amp;D, S&amp;M, G&amp;A and other expenses, totaled $12.1 million in the first quarter of 2026, compared to $13.0 million in the first quarter of 2025. The decrease was driven by a reduction in R&amp;D expense related to the termination of the Phase 3 InnovAATe clinical trial, offset by increases in S&amp;M and G&amp;A expenses related to our investments in the overall growth of the commercial product portfolio. \u00a0<\/li>\n<li style=\"text-align:justify\">Net income was $4.1 million, or $0.07 per diluted share, in the first quarter of 2026, up 4% as compared to $4.0 million, or $0.07 per diluted share, in the first quarter of 2025.<\/li>\n<li style=\"text-align:justify\">Adjusted EBITDA, as detailed in the tables below, was $11.6 million in the first quarter of 2026, equivalent to the adjusted EBITDA reported in the first quarter of 2025.<\/li>\n<li style=\"text-align:justify\">Cash used in operating activities was $0.3 million in the first quarter of 2026, as compared to cash used in operating activities of $0.5 million in the first quarter of 2025.\n<\/li>\n<\/ul>\n<p align=\"justify\">\n        <strong>Balance Sheet Highlights<\/strong><br \/>\n        <br \/>As of March 31, 2026, Kamada had cash and cash equivalents and short-term investment totaling $73.1 million, as compared to $75.5 million as of December 31, 2025. The Company recorded $0.3 million in cash used in operating activities, net cash used in investment activities of $1.0 million, net cash used in financing activities of $0.9 million and exchange differences on balances of cash and cash equivalent of $0.2 million, collectively resulting in an overall decrease in cash balance.<\/p>\n<p align=\"justify\">\n        <strong>Recent Corporate Highlights<\/strong>\n      <\/p>\n<ul type=\"disc\">\n<li style=\"text-align:justify\">Announced U.S. Food and Drug Administration (FDA) approval of Kamada Plasma\u2019s collection center in San Antonio, TX. The approval was obtained following an on-site inspection made by the FDA during February 2026. The center is now cleared to commence commercial sales of normal source plasma.<\/li>\n<li style=\"text-align:justify\">Announced the payment of a cash dividend of $0.25 (approximately NIS 0.77) per share on the Company\u2019s ordinary shares (totaling approximately $14.4 million). The cash dividend was paid on April 7, 2026, to shareholders of record at the close of business on March 23, 2026.\n<\/li>\n<\/ul>\n<p align=\"justify\">\n        <strong>Fiscal 2026 Guidance<\/strong><br \/>\n        <br \/>Kamada is reiterating its 2026 annual financial guidance of total revenues in the range of $200 million to $205 million and adjusted EBITDA in the range of $50 million to $53 million, representing year-over-year increase of 12% in revenues and 23% in adjusted EBITDA based on mid-point of 2026 annual guidance.<\/p>\n<p align=\"justify\">\n        <strong>Conference Call Details<\/strong><br \/>\n        <br \/>Kamada management will host an investment community conference call on Wednesday, May 13, at 8:30am Eastern Time to discuss these results and answer questions. Shareholders and other interested parties may participate in the call by dialing 1-877-407-0792 (from within the U.S.), 1-809-406-247 (from Israel), or 1-201-689- 8263 (International) using conference I.D. 13760232. The call will be webcast live on the internet at: <a href=\"https:\/\/www.globenewswire.com\/Tracker?data=Yq2rYNFAhyfhk6iEsztbY-X4dDe_-2vxyINX2OclY8ojv_mo9Q64RwwU1n1_Bx2fiJUi_2m_BO90_DV5sMH2lq9pjAsK-qfkyQ6d8nhNfxNxXqapwWHL0zG27CTM64DqK3zf2UKE7To8CuGLxF0KPZstty5AthcyXYWm6h0y9bSDNaQPkXS81bOfhU0iYCClcpRhb4ePesZGn4e7m4Q4ViNsT6ptQIXDqwX80Zsy0eo=\" rel=\"nofollow\" target=\"_blank\">https:\/\/viavid.webcasts.com\/starthere.jsp?ei=1760803&amp;tp_key=7219e3b56c<\/a><\/p>\n<p align=\"justify\">\n        <strong>Non-IFRS financial measures<\/strong><br \/>\n        <br \/>We present EBITDA and adjusted EBITDA because we use these non-IFRS financial measures to assess our operational performance, for financial and operational decision-making, and as a means to evaluate period-to-period comparisons on a consistent basis. Management believes these non-IFRS financial measures are useful to investors because: (1) they allow for greater transparency with respect to key metrics used by management in its financial and operational decision-making and provide investors with a meaningful perspective on the current underlying performance of the Company\u2019s core ongoing operations; and (2) they exclude the impact of certain items that are not directly attributable to our core operating performance and that may obscure trends in the core operating performance of the business. Non-IFRS financial measures have limitations as an analytical tool and should not be considered in isolation from, or as a substitute for, our IFRS results. We expect to continue reporting non-IFRS financial measures, adjusting for the items described below, and we expect to continue to incur expenses similar to certain of the non-cash, non-IFRS adjustments described below. Accordingly, unless otherwise stated, the exclusion of these and other similar items in the presentation of non-IFRS financial measures should not be construed as an inference that these items are unusual, infrequent or non-recurring. EBITDA and adjusted EBITDA are not recognized terms under IFRS and do not purport to be an alternative to IFRS terms as an indicator of operating performance or any other IFRS measure. Moreover, because not all companies use identical measures and calculations, the presentation of EBITDA and adjusted EBITDA may not be comparable to other similarly titled measures of other companies. EBITDA is defined as net income (loss), plus income tax expense, plus or minus financial income or expenses, net, plus or minus income or expense in respect of securities measured at fair value, net, plus or minus income or expenses in respect of currency exchange differences and derivatives instruments, net, plus depreciation and amortization expense, whereas adjusted EBITDA is the EBITDA plus non-cash share-based compensation expenses and certain other costs.<\/p>\n<p align=\"justify\">For the projected 2026 adjusted EBITDA information presented herein, the Company is unable to provide a reconciliation of this forward measure to the most comparable IFRS financial measure because the information for these measures is dependent on future events, many of which are outside of the Company\u2019s control. Additionally, estimating such forward-looking measures and providing a meaningful reconciliation consistent with the Company\u2019s accounting policies for future periods is meaningfully difficult and requires a level of precision that is unavailable for these future periods and cannot be accomplished without unreasonable effort. Forward-looking non-IFRS measures are estimated in a manner consistent with the relevant definitions and assumptions noted in the Company\u2019s adjusted EBITDA for historical periods.<\/p>\n<p align=\"justify\">\n        <strong>About Kamada <\/strong><br \/>\n        <br \/>Kamada Ltd. (the \u201cCompany\u201d) is a global biopharmaceutical company with a portfolio of marketed products indicated for rare and serious conditions and a leader in the specialty plasma-derived therapies field. FIMI Opportunity Funds, the leading private equity firm in Israel, is the Company\u2019s controlling shareholder, beneficially owning approximately 38% of the outstanding ordinary shares. The Company\u2019s strategy is focused on driving profitable growth through four primary growth pillars: First, organic growth of its commercial portfolio, including continued investment in the commercialization and life cycle management of its proprietary products, consisting of six FDA-approved specialty plasma-derived products: KEDRAB\u00ae, GLASSIA\u00ae, CYTOGAM\u00ae, VARIZIG\u00ae, WINRHO SDF\u00ae and HEPAGAM B\u00ae, as well as KAMRAB\u00ae, and two equine-based anti-snake venom products. Second, distribution of third parties&#8217; pharmaceutical products in Israel &amp; the MENA region through in-licensing partnerships, including the launch of several biosimilar products in Israel. Third, the Company is ramping up its plasma collection operations to support revenue growth through the sale of normal source plasma to other plasma-derived manufacturers, and to support its increasing demand for hyper-immune plasma. The Company currently owns three FDA approved operating plasma collection centers in the United States, in Beaumont, Houston, and San Antonio, Texas. Fourth, the Company aims to secure new mergers and acquisitions, business development, in-licensing and\/or collaboration opportunities, which are anticipated to enhance the Company\u2019s marketed products portfolio and leverage its financial strength and existing commercial infrastructure to drive long-term profitable growth. The Company is leveraging its manufacturing, research and development expertise to advance the development and commercialization of additional product candidates, targeting areas of significant unmet medical need.<\/p>\n<p align=\"justify\">\n        <strong>Cautionary Note Regarding Forward-Looking Statements <\/strong><br \/>\n        <br \/>This release includes forward-looking statements within the meaning of Section 21E of the U.S. Securities Exchange Act of 1934, as amended, and the safe harbor provisions of the U.S. Private Securities Litigation Reform Act of 1995. Forward-looking statements are statements that are not historical facts, including statements regarding: 1) the Company\u2019s expectation for a significantly stronger remainder of 2026, 2) the Company\u2019s reiterated 2026 annual guidance of $200 million to $205 million in revenues and $50 million to $53 million of adjusted EBITDA; 3) continued increase in underlying demand for the Company\u2019s products, including KEDRAB\u00ae in the U.S. market and KAMRAB\u00ae and VARIZIG\u00ae in ex-U.S. markets; 4) the expansion of the Company\u2019s entire commercial product portfolio and the Distribution segment, including expansion to the MENA region and launch of additional biosimilar products in Israel; 5) ramp-up of plasma collection operations at the Company\u2019s plasma collection centers and the expected contribution of such operations to the Company\u2019s vertical integration and continued growth; 6) the Company\u2019s evaluation of and securing near-term new business development and M&amp;A opportunities to further enhance long-term profitable growth; 7) the anticipated enrichment of the Company\u2019s marketed products portfolio and generation of synergies with its existing commercial operations; and 8) the development and commercialization of additional product candidates targeting areas of significant unmet medical need. Forward-looking statements are based on Kamada\u2019s current knowledge and its present beliefs and expectations regarding possible future events and are subject to risks, uncertainties and assumptions. Actual results and the timing of events could differ materially from those anticipated in these forward-looking statements as a result of several factors including, but not limited to the evolving nature of the conflicts in the Middle East and the impact of such conflicts in Israel, the Middle East and the rest of the world, the impact of these conflicts on market conditions and the general economic, industry and political conditions in Israel, the U.S. and globally, effect of tariffs on overall international trade and specifically on Kamada\u2019s ability to continue maintaining expected sales and profit levels in light of such tariffs, the effect on establishment and timing of business initiatives, Kamada\u2019s ability to find near-term business development and M&amp;A transactions and leverage such opportunities and successfully integrate such opportunities with its existing product portfolio, unexpected results of clinical and development programs, regulatory delays,\u00a0 and other risks detailed in Kamada\u2019s filings with the U.S. Securities and Exchange Commission (the \u201cSEC\u201d) including those discussed in its most recent Annual Report on Form 20-F and in any subsequent reports on Form 6-K, each of which is on file or furnished with the SEC and available at the SEC\u2019s website at <a href=\"https:\/\/www.globenewswire.com\/Tracker?data=ms6pHODg3zgU6iqgUlRD_1_1Lcb8JUJRZg5qkgSfSw96NpWapXl6BUBjuVyjgEpsGpxvk5ODMT_AcvhLqiyMFw==\" rel=\"nofollow\" target=\"_blank\">www.sec.gov<\/a>. The forward-looking statements made herein speak only as of the date of this announcement and Kamada undertakes no obligation to update publicly such forward-looking statements to reflect subsequent events or circumstances, except as otherwise required by law.<\/p>\n<p align=\"justify\">\n        <strong>CONTACTS:<\/strong><br \/>\n        <br \/>Chaime Orlev<br \/>Chief Financial Officer<br \/><a href=\"https:\/\/www.globenewswire.com\/Tracker?data=-bI2Xh13eQ21YbI_sNyOK3pd5vaLfuse6o1gNEXUhTCxmknRbYdK7di6qOq6yked5XffJnEzYc4EsRSMub5M8A==\" rel=\"nofollow\" target=\"_blank\">IR@kamada.com<\/a><\/p>\n<p align=\"justify\">Brian Ritchie<br \/>LifeSci Advisors, LLC<br \/>212-915-2578<br \/><a href=\"https:\/\/www.globenewswire.com\/Tracker?data=I2FmKz_Uhp5klBFq0qwJAyEWcAOddkJiLccxt1teYW5rwZpjLczse-k6tFiNHwOfhjCMDu5LXlS11LUGjkmaDEWB3EyLwQ2SI4J-I7uDQ4D1mnKSVXSmATksvC0BeoVA\" rel=\"nofollow\" target=\"_blank\">britchie@LifeSciAdvisors.com<\/a><\/p>\n<p align=\"justify\">\n        \n      <\/p>\n<table style=\"border-collapse: collapse;width:100%;border-collapse:collapse\">\n<tr>\n<td colspan=\"12\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"border-bottom: solid black 1pt\">\n            <strong>CONSOLIDATED STATEMENTS OF FINANCIAL POSITION<br \/><\/strong>\n          <\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"width:100%\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:25.9857%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>As of<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.3656%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>As of<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:25.9857%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>March 31,<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.3656%;text-align: center;vertical-align: middle;border-bottom: solid black 1pt;vertical-align: bottom\">\n            <strong>December\u00a031,<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:12.9928%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2026<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0072%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2025<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.3656%;text-align: center;vertical-align: middle;border-bottom: solid black 1pt;vertical-align: bottom\">\n            <strong>2025<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:25.9857%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Unaudited<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.3656%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"10\" style=\"width:40.3226%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>U.S. Dollars in Thousands<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <u>Assets<\/u>\n          <\/td>\n<td colspan=\"2\" style=\"width:12.0072%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0072%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.3656%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\n            <u>Current Assets<\/u>\n          <\/td>\n<td colspan=\"2\" style=\"width:12.0072%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0072%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.3656%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"max-width:59%;width:58.6918%;min-width:59%;vertical-align: bottom\">Cash and cash equivalents<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">32,922<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">76,250<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.34409%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:11.0215%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">75,469<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Short-term investments<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">40,225<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Trade receivables, net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">36,515<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">27,876<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">27,007<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Other accounts\u00a0receivables<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">4,136<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">6,016<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">5,656<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Inventories<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">85,437<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">78,358<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">84,943<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total Current Assets<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">199,235<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">188,500<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">193,075<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\n            <u>Non-Current Assets<\/u>\n          <\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Property, plant and equipment, net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">41,463<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">37,406<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">41,367<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Right-of-use assets<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">8,908<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">9,539<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">8,900<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Intangible assets and other long-term assets<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">95,676<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">101,422<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">97,511<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Goodwill<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">30,313<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">30,313<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">30,313<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Contract assets<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">7,426<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">7,925<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">7,544<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total Non-Current Assets<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">183,786<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">186,605<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">185,635<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total Assets<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">383,021<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">375,105<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">378,710<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <u>Liabilities<\/u>\n          <\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\n            <u>Current Liabilities<\/u>\n          <\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Current maturities of lease liabilities<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,198<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,780<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,121<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Current maturities of other long term liabilities<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">10,643<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">10,889<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">9,923<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Trade payables<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">21,938<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">24,854<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">23,242<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Other accounts payables<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">24,930<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">19,319<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">12,108<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Deferred revenues<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">67<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">205<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 20.0px;vertical-align: bottom\">Total Current Liabilities<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">59,776<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">57,047<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">47,394<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\n            <u>Non-Current Liabilities<\/u>\n          <\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Lease liabilities<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">9,443<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">9,318<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">9,440<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Contingent consideration<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">20,910<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">21,216<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">20,372<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Other long-term liabilities<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">29,925<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">32,990<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">30,113<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Deferred taxes<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,866<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,061<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,651<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Employee benefit liabilities, net<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">714<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">516<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">670<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total Non-Current Liabilities<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">63,858<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">66,101<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">62,246<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <u>Shareholder\u2019s Equity<\/u>\n          <\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Ordinary shares<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">15,078<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">15,074<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">15,078<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Additional paid in capital \u00a0net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">268,360<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">268,160<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">268,283<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Capital reserve due to translation to presentation currency<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(3,490<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(3,490<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">(3,490<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Capital reserve from hedges<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(6<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(117<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">177<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Capital reserve from share-based payments<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">6,434<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">5,266<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">5,711<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Capital reserve from employee benefits<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">374<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">372<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">385<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Accumulated deficit<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(27,363<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(33,308<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(17,074<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total Shareholder\u2019s Equity<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">259,387<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">251,957<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">269,070<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total Liabilities and Shareholder\u2019s Equity<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">383,021<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">375,105<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">378,710<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p align=\"justify\">\n        \n      <\/p>\n<table style=\"border-collapse: collapse;width:100%;border-collapse:collapse\">\n<tr>\n<td colspan=\"12\" style=\"width:100.09%\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"width:100.09%;border-bottom: solid black 1pt\">\n            <strong>CONSOLIDATED STATEMENTS OF PROFIT OR LOSS AND OTHER COMPREHENSIVE INCOME\u00a0<br \/><\/strong>\n          <\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"width:100.09%;border-bottom: solid black 1pt\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" rowspan=\"2\" style=\"width:25.9857%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Three months period<br \/>Ended <\/strong><br \/>\n            <strong>March\u00a031,<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.4552%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Year Ended<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.4552%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>December\u00a031,<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:12.9928%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2026<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0072%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2025<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.4552%;text-align: center;vertical-align: middle;border-bottom: solid black 1pt;vertical-align: bottom\">\n            <strong>2025<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:25.9857%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Unaudited<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.4552%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: middle;text-align: left;padding-left: 10.0px;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"10\" style=\"width:40.4122%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>U.S. Dollars in Thousands<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"max-width:59%;width:58.6918%;min-width:59%;text-align: justify;vertical-align: middle;vertical-align: bottom\">Revenues from proprietary products<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">36,227<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">40,017<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.43369%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:11.0215%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">156,206<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: justify;vertical-align: middle;vertical-align: bottom\">Revenues from distribution<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">9,013<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">4,001<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">24,254<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total revenues<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">45,240<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">44,018<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">180,460<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: justify;vertical-align: middle;vertical-align: bottom\">Cost of revenues from proprietary products<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">18,202<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">19,738<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">83,928<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: justify;vertical-align: middle;vertical-align: bottom\">Cost of revenues from distribution<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">7,922<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">3,531<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">20,125<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total cost of revenues<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">26,124<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">23,269<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">104,053<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Gross profit<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">19,116<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">20,749<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">76,407<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Research and development expenses<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,181<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">4,246<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">12,995<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Selling and marketing expenses<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">4,753<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">4,510<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">18,455<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">General and administrative expenses<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">5,229<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">4,198<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">18,724<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Other expenses<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Operating income (loss)<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">6,953<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">7,795<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">26,233<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Financial income<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">425<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">534<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,921<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Income (expenses) in respect of currency exchange differences and derivatives instruments, net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(261<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">251<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,171<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Financial Income (expense) in respect of contingent consideration and other long- term liabilities.<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,538<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,775<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">(2,652<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Financial expenses<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(188<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(192<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(864<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Income before tax on income<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">5,391<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">6,613<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">23,467<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Taxes on income<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,259<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(2,649<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(3,269<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Net Income (loss)<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">4,132<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">3,964<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">20,198<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Other Comprehensive Income (loss):<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Amounts that will be or that have been reclassified to profit or loss when specific conditions are met<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Gain (loss) on cash flow hedges<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">90<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(114<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,069<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Net amounts transferred to the statement of profit or loss for cash flow hedges<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(273<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(54<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">(943<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Items that will not be reclassified to profit or loss in subsequent periods:<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Remeasurement gain (loss) from defined benefit plan<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(11<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">8<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">21<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Total comprehensive income (loss)<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">3,938<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">3,804<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">20,345<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Earnings per share attributable to equity holders of the Company:<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Basic net earnings per share<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">0.07<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">0.07<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">0.35<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Diluted net earnings per share<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">0.07<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">0.07<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.43369%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">0.35<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p align=\"justify\">\n        \n      <\/p>\n<table style=\"border-collapse: collapse;width:100%;border-collapse:collapse\">\n<tr>\n<td colspan=\"12\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"border-bottom: solid black 1pt\">\n            <strong>CONSOLIDATED STATEMENTS OF CASH FLOWS<br \/><\/strong>\n          <\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"width:99.8208%\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:26.0753%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Three months period<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Year Ended<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:26.0753%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Ended March 31,<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>December\u00a031,<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:12.9928%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2026<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2025<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;text-align: center;vertical-align: middle;border-bottom: solid black 1pt;vertical-align: bottom\">\n            <strong>2025<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:12.9928%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Unaudited<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Unaudited<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:13.0824%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"10\" style=\"width:40.1434%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>U.S. Dollars in Thousands<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\n            <u>Cash Flows from Operating Activities<\/u>\n          <\/td>\n<td colspan=\"2\" style=\"width:12.0072%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"max-width:59%;width:58.6918%;min-width:59%;vertical-align: bottom\">Net income<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">4,132<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.16487%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,964<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.16487%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">20,198<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Adjustments to reconcile net income to net cash provided by operating activities:<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Adjustments to the profit or loss items:<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Depreciation and amortization<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,851<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,611<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">14,918<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Financial expenses, net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,562<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,182<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,766<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Cost of share-based payment<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">800<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">175<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">845<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Taxes on income<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,259<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,649<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,269<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Gain from sale of property and equipment<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(8<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(8<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Change in employee benefit liabilities, net<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">31<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">16<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">183<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">7,503<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">7,625<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">21,973<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Changes in asset and liability items:<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Increase in trade receivables, net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(9,757<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(6,557<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(5,407<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Decrease (increase) in other accounts receivables<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,288<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(671<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(535<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Decrease (increase) in inventories<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(494<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">461<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(6,124<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Decrease in deferred expenses<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">119<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">94<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">475<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Decrease in trade payables<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,446<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(3,748<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(6,870<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Increase (decrease) in other accounts payables<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,897<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(2,044<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">950<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Increase (decrease) in deferred revenues<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">67<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">34<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(171<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(12,120<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(12,431<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(17,682<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Cash received (paid) during the period for:<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Interest paid<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(187<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(176<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(864<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Interest received<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">425<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">534<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,921<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">Taxes paid<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(44<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(29<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(56<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">194<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">329<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">1,001<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.6918%;vertical-align: bottom\">\n            <u>Net cash provided by (used in) operating activities<\/u>\n          <\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(291<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(513<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">25,490<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p align=\"justify\">\n        \n      <\/p>\n<table style=\"border-collapse: collapse;width:100%;border-collapse:collapse\">\n<tr>\n<td colspan=\"12\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"border-bottom: solid black 1pt\">\n            <strong>CONSOLIDATED STATEMENTS OF CASH FLOWS (continued)<br \/><\/strong>\n          <\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"width:99.8208%\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:26.0753%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Three months period<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.276%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Year Ended<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:26.0753%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Ended March, 31<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.276%;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>December\u00a031,<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:12.9928%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2026<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2025<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.276%;text-align: center;vertical-align: middle;border-bottom: solid black 1pt;vertical-align: bottom\">\n            <strong>2025<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:12.9928%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Unaudited<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Unaudited<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:13.2616%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"10\" style=\"width:40.3226%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>U.S. Dollars in Thousands<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\n            <u>Cash Flows from Investing Activities<\/u>\n          <\/td>\n<td colspan=\"2\" style=\"width:12.0072%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0968%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.276%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"max-width:59%;width:58.5125%;min-width:59%;vertical-align: bottom\">Purchase of property and equipment and intangible assets<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">(973<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">)<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.16487%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,468<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">)<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.34409%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">(9,846<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Investment in short term investments, net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(40,225<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Proceeds from sale of property and equipment<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">8<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">8<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Net cash used in investing activities<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(41,198<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(1,460<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(9,838<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\n            <u>Cash Flows from Financing Activities<\/u>\n          <\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Proceeds from exercise of share base payments<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">46<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">50<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Repayment of lease liabilities<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(389<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(14<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(972<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Dividends Paid<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">&#8211;<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(11,534<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Repayment of other long-term liabilities<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(467<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(325<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(5,889<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Net cash used in financing activities<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(856<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(293<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(18,345<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Exchange differences on balances of cash and cash equivalent<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(202<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">81<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">(273<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Decrease in cash and cash equivalents<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(42,547<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(2,185<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">(2,966<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\n            <u>Cash and cash equivalents at the beginning of the period<\/u>\n          <\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">75,469<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">78,435<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">78,435<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\n            <u>Cash and cash equivalents at the end of the period<\/u>\n          <\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">32,922<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">76,250<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">75,469<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">\n            <u>Significant non-cash transactions<\/u>\n          <\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Right-of-use asset recognized with corresponding lease liability<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">439<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">352<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">1,221<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.5125%;vertical-align: bottom\">Purchase of property and equipment and Intangible assets<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">683<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">1,103<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.34409%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">2,523<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p align=\"justify\">\n        \n      <\/p>\n<table style=\"border-collapse: collapse;width:100%;border-collapse:collapse\">\n<tr>\n<td colspan=\"12\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"border-bottom: solid black 1pt\">\n            <strong>NON-IFRS MEASURES<br \/><\/strong>\n          <\/td>\n<\/tr>\n<tr>\n<td colspan=\"12\" style=\"width:99.9104%\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"6\" style=\"width:25.9857%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>Three months period <br \/>Ended\u00a0March 31,<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.1864%;text-align: center;vertical-align: middle;border-bottom: solid black 1pt\">\n            <strong>Year Ended<br \/>December\u00a031,<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"3\" style=\"width:12.9928%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2026<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.0072%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>2025<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%\">\u00a0<\/td>\n<td colspan=\"2\" style=\"width:12.1864%;text-align: center;vertical-align: middle;border-bottom: solid black 1pt\">\n            <strong>2025<\/strong><br \/>\n            \n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;text-align: center;vertical-align: middle;vertical-align: bottom\">\u00a0<\/td>\n<td colspan=\"10\" style=\"width:40.1434%;border-bottom: solid black 1pt;text-align: center;vertical-align: middle;vertical-align: bottom\">\n            <strong>U.S. Dollars in thousands<\/strong>\n          <\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"max-width:59%;width:58.7814%;min-width:59%;vertical-align: bottom\">Net income<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">4,132<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.07527%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:10.9319%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,964<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"max-width:1%;width:1.16487%;min-width:1%;vertical-align: bottom\">$<\/td>\n<td style=\"max-width:11%;width:11.0215%;min-width:11%;text-align: right;vertical-align: middle;vertical-align: bottom\">20,198<\/td>\n<td style=\"max-width:1%;width:0.985663%;min-width:1%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;vertical-align: bottom\">Taxes on income<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,259<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,649<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,269<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;vertical-align: bottom\">Financial expense, net<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,562<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">1,182<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">2,766<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;vertical-align: bottom\">Depreciation and amortization expense<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,851<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;text-align: right;vertical-align: middle;vertical-align: bottom\">3,611<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;text-align: right;vertical-align: middle;vertical-align: bottom\">14,924<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;vertical-align: bottom\">Non-cash share-based compensation expenses<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">800<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:10.9319%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">175<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: solid black 1pt;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:11.0215%;border-bottom: solid black 1pt;text-align: right;vertical-align: middle;vertical-align: bottom\">845<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width:58.7814%;vertical-align: bottom\">Adjusted EBITDA<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">11,604<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.07527%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:10.9319%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">11,581<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<td style=\"width:1.16487%;border-bottom: double black 3pt;vertical-align: bottom\">$<\/td>\n<td style=\"width:11.0215%;border-bottom: double black 3pt;text-align: right;vertical-align: middle;vertical-align: bottom\">42,002<\/td>\n<td style=\"width:0.985663%;vertical-align: bottom\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p>\n        \n      <\/p>\n<p>      <img decoding=\"async\" alt=\"\" class=\"__GNW8366DE3E__IMG\" src=\"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=\" \/><br \/>\n      <br \/>\n      <img decoding=\"async\" alt=\"\" src=\"https:\/\/ml.globenewswire.com\/media\/ZjY1Y2QyNWUtZGQ3YS00MDQ3LTgyZDYtOTk4MjU5YWU0YWNlLTEwMjg3MjUtMjAyNi0wNS0xMy1lbg==\/tiny\/Kamada-Ltd-.png\" \/>\n    <\/div>\n<div class=\"mw_contactinfo\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Q1-2026 Revenue of $45.2 Million, up 3% Year-over-Year; Adjusted EBITDA of $11.6 Million, representing a Robust 26% Margin of Revenues ; Net Income of $4.1 Million, up 4% Year-over-Year Underlying Demand for the Company\u2019s Products Continues to Increase, Supporting the Company\u2019s Expectation for a Significantly Stronger Remainder of 2026 Company Affirms 2026 Annual Guidance of $200 Million \u2013 $205 Million in Revenues and $50 Million \u2013 $53 Million of Adjusted EBITDA, Representing Annual Double-Digit Organic Profitable Growth Q1-2026 Results Impacted by Temporary Shipment Delay of a Single Order, Subsequently Delivered during April\u00a0 Company Continues to Evaluate Near-Term Business Development and M&amp;A Transactions to Further Enhance Long-Term Profitable Growth Conference Call and Live Webcast Today at 8:30am ET REHOVOT, Israel, and &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-962027","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"Q1-2026 Revenue of $45.2 Million, up 3% Year-over-Year; Adjusted EBITDA of $11.6 Million, representing a Robust 26% Margin of Revenues ; Net Income of $4.1 Million, up 4% Year-over-Year Underlying Demand for the Company\u2019s Products Continues to Increase, Supporting the Company\u2019s Expectation for a Significantly Stronger Remainder of 2026 Company Affirms 2026 Annual Guidance of $200 Million \u2013 $205 Million in Revenues and $50 Million \u2013 $53 Million of Adjusted EBITDA, Representing Annual Double-Digit Organic Profitable Growth Q1-2026 Results Impacted by Temporary Shipment Delay of a Single Order, Subsequently Delivered during April\u00a0 Company Continues to Evaluate Near-Term Business Development and M&amp;A Transactions to Further Enhance Long-Term Profitable Growth Conference Call and Live Webcast Today at 8:30am ET REHOVOT, Israel, and &hellip; Continue reading &quot;Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:16:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year\",\"datePublished\":\"2026-05-13T11:16:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/\"},\"wordCount\":2862,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/\",\"name\":\"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=\",\"datePublished\":\"2026-05-13T11:16:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=\",\"contentUrl\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/","og_locale":"en_US","og_type":"article","og_title":"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year - Market Newsdesk","og_description":"Q1-2026 Revenue of $45.2 Million, up 3% Year-over-Year; Adjusted EBITDA of $11.6 Million, representing a Robust 26% Margin of Revenues ; Net Income of $4.1 Million, up 4% Year-over-Year Underlying Demand for the Company\u2019s Products Continues to Increase, Supporting the Company\u2019s Expectation for a Significantly Stronger Remainder of 2026 Company Affirms 2026 Annual Guidance of $200 Million \u2013 $205 Million in Revenues and $50 Million \u2013 $53 Million of Adjusted EBITDA, Representing Annual Double-Digit Organic Profitable Growth Q1-2026 Results Impacted by Temporary Shipment Delay of a Single Order, Subsequently Delivered during April\u00a0 Company Continues to Evaluate Near-Term Business Development and M&amp;A Transactions to Further Enhance Long-Term Profitable Growth Conference Call and Live Webcast Today at 8:30am ET REHOVOT, Israel, and &hellip; Continue reading \"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/","og_site_name":"Market Newsdesk","article_published_time":"2026-05-13T11:16:49+00:00","og_image":[{"url":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year","datePublished":"2026-05-13T11:16:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/"},"wordCount":2862,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/#primaryimage"},"thumbnailUrl":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/","name":"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/#primaryimage"},"thumbnailUrl":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=","datePublished":"2026-05-13T11:16:49+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/#primaryimage","url":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI=","contentUrl":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcxOTMzOCM3NTk5NDcxIzIwMTcxNTI="},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/kamada-reports-first-quarter-2026-financial-results-and-affirms-2026-annual-guidance-expecting-significantly-stronger-remainder-of-the-year\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"Kamada Reports First Quarter 2026 Financial Results and Affirms 2026 Annual Guidance; Expecting Significantly Stronger Remainder of the Year"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/962027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=962027"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/962027\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=962027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=962027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=962027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}