{"id":961862,"date":"2026-05-12T18:37:48","date_gmt":"2026-05-12T22:37:48","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/"},"modified":"2026-05-12T18:37:48","modified_gmt":"2026-05-12T22:37:48","slug":"franco-nevada-reports-record-q1-2026-results","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/","title":{"rendered":"Franco-Nevada Reports Record Q1 2026 Results"},"content":{"rendered":"<div class=\"xn-newslines\">\n<p class=\"xn-distributor\">PR Newswire<\/p>\n<\/p><\/div>\n<div class=\"xn-content\">\n<p>\n        <b>Tom\u00a0Albanese appointed Chair<\/b>\n      <\/p>\n<p>\n        <i>(in U.S. dollars unless otherwise noted)<\/i>\n      <\/p>\n<p>\n        <span class=\"legendSpanClass\">TORONTO<\/span>, <span class=\"legendSpanClass\">May 12, 2026<\/span> \/PRNewswire\/ &#8211;\u00a0Franco-Nevada realized record financial results in the first quarter of 2026, driven by higher commodity prices, contributions from newly acquired assets, a partial buy-back and a refund from the Canada Revenue Agency. &#8220;The sharp rise in oil prices is expected to positively impact our Q2 revenues, while our royalty and streaming model is largely insulated from the impact of energy prices on cost inflation. Franco-Nevada is unique as a mining equity that benefits from rising oil prices. We look forward to further growth from new assets, additional contributions from\u00a0Cobre Panam\u00e1 and the potential for a full resumption of the mine&#8221;, stated Paul Brink, <span>President &amp;<\/span> CEO.<\/p>\n<p>At today&#8217;s AGM, David Harquail gave his last address as Chair before taking on the title of Chair Emeritus. The Board thanked David for leading the IPO of Franco-Nevada and for the tremendous shareholder value he created over the ensuing 18 years.<\/p>\n<p>&#8220;After almost 40 years of being in the gold royalty business, I would like to thank all of the shareholders, portfolio managers, the analysts and brokers who believed in us and helped make this latest version of Franco-Nevada &#8220;the GOLD Investment that WORKS&#8221;&#8221;, commented David\u00a0Harquail. &#8220;In a world confronted by political volatility and financial market instability, having Franco-Nevada as a lower-risk gold investment that is insulated from inflation and with a strong balance sheet is the right business model. I am proud of the wealth that this strategy has generated for our shareholders and that Franco-Nevada today is a financial powerhouse. I am also proud of the strong management team and Board that is in place to continue to deliver decades more of dividends to shareholders.&#8221;<\/p>\n<p>Following the meeting, Tom Albanese was appointed as the independent non-executive Chair of its board of directors. Tom has most recently served as the Lead Independent Director of Franco-Nevada. He is a seasoned mining executive including prior CEO roles at both Rio Tinto plc and Vedanta Resources plc and many corporate director positions.<\/p>\n<p>\n        <b>Financial Highlights \u2013 <\/b><br \/>\n        <b>Q1 2026<\/b><br \/>\n        <b> compared to <\/b><br \/>\n        <b>Q1 2025<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>$650.7 million in revenue, +77% \u2013\u00a0<i>new record.<\/i><\/li>\n<li>136,353 GEOs<sup>1<\/sup> sold, +8%.<\/li>\n<li>126,020 Net GEOs<sup>1<\/sup> sold, +11%.<\/li>\n<li>$520.4 million in operating cash flow, +80% \u2013 <i>new record<\/i>. Operating cash flow included a $49.5 million refund from the CRA as a result of the settlement reached in September 2025. \u00a0<\/li>\n<li>$591.9 million ($3.07\/share) in Adjusted EBITDA<sup>2<\/sup>, +84% \u2013 <i>new records<\/i>.<\/li>\n<li>$468.6 million ($2.43\/share) in net income, +123% \u2013 <i>new records<\/i>.<\/li>\n<li>$458.3 million ($2.38\/share) in Adjusted Net Income<sup>2<\/sup>, +123% \u2013 <i>new records<\/i>. Adjusted Net Income included $55.1 million, or $0.28 per share, from the Cascabel buy-backs (net of tax).\u00a0<\/li>\n<li>$3.4 billion in Available Capital<sup>3<\/sup> as at March 31, 2026.<\/li>\n<\/ul>\n<p>\n        <b>GEOs Sold and Revenue <\/b>\n      <\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0Quarterly GEOs sold and revenue by commodity<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"3\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"4\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Q1 2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Q1 2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GEOs Sold<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Revenue<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GEOs Sold<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Revenue<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <i>#<\/i><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <i>(in<\/i><br \/>\n                  <\/b>\u00a0<b><i>millions)<\/i><\/b><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <i>#<\/i><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <i>(in<\/i><br \/>\n                  <\/b>\u00a0<b><i>millions)<\/i><\/b><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>PRECIOUS METALS<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Gold<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>91,158<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>436.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">85,523<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">245.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Silver<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>23,618<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>113.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12,490<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">37.0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">PGM<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3,204<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>17.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,610<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>117,980<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>568.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">100,623<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">290.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>DIVERSIFIED<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Iron ore<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3,794<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>17.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,888<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Other mining assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,403<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>6.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,557<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Oil<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>7,406<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>33.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,494<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">34.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Gas<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,579<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>20.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,499<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">17.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">NGL<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,191<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,524<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>18,373<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>82.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">25,962<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">74.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GEOs and revenue from royalty, stream and working interests<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>136,353<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>650.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">126,585<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">365.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Interest revenue and other interest income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Total GEOs and revenue<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>136,353<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>650.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">126,585<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">368.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>In Q1 2026, we recognized revenue of $650.7 million, an increase of 77% from Q1 2025, and sold 136,353 GEOs, an increase of 8% from Q1 2025. We benefited from record gold and silver prices achieved during the quarter, strong contributions from Antamina, South Arturo, Hemlo, Musselwhite, and incremental contributions from C\u00f4t\u00e9 Gold, Porcupine and Valentine, all of which were acquired or commenced production over the past year. We also benefited from an increase in revenue from our Diversified assets, particularly from our Vale iron ore interest, and our Haynesville and Marcellus gas assets.<\/p>\n<p>Precious Metal assets accounted for 87% of our revenue in Q1 2026 (67% gold, 17% silver, and 3% PGM). Revenue was sourced 87% from the Americas (42% South America, 21% Canada, 15% U.S. and 9% Central America &amp; Mexico).<\/p>\n<p>\n        <b>Portfolio Additions<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>\n          <b>Acquisition of Royalty Portfolio from Victoria Gold Corp.\u2013 Canada and U.S.: <\/b>Subsequent to quarter-end, on April 16, 2026, we closed the previously announced acquisition of a portfolio of six royalties previously held by Victoria Gold Corp. for total cash consideration of $40.0 million (C$55 million). The portfolio includes a 6.0% NSR (subject to a 5.0% buy-back at the operator&#8217;s election) on Banyan Gold Corp.&#8217;s AurMac property and a 1.0% NSR on Banyan Gold&#8217;s Hyland property, both in the Yukon. The portfolio also includes a milestone payment royalty on i-80 Gold Corp.&#8217;s Cove project in Nevada and three additional royalties on earlier stage properties in Nevada and the Yukon.<\/li>\n<li>\n          <b>Partial Buy-Backs of Cascabel Stream and NSR \u2013 Ecuador:<\/b> In March 2026, following the acquisition of SolGold plc (&#8220;SolGold&#8221;) by Jiangxi Copper (Hong Kong) Investment Company Limited, for and on behalf of Jiangxi Copper Company Limited (&#8220;JCC&#8221;), SolGold and JCC exercised their option to buy back 50% of the Cascabel stream and NSR. As a result, Franco-Nevada received the equivalent of $40.7 million (net of the ongoing payment of 20% of spot price per ounce delivered) as a one-time delivery of gold ounces for the buy-back of 50% of the Cascabel stream, and $97.5 million in cash for the buy-back of 50% of the Cascabel NSR. Our acquisition cost (on a proportionate 50% basis) was $23.3 million for the stream and $50.0 million for the NSR. These buy-backs resulted in a gain of $63.8 million recognized in net income and Adjusted Net Income for Q1 2026, but excluded from Adjusted EBITDA.<\/li>\n<li>\n          <b>Acquisition of Stream on Casa Berardi Gold Mine \u2013 Quebec, Canada: <\/b>On March 24, 2026, we closed the previously announced acquisition of a $100 million gold stream from Orezone Gold Corporation to support their acquisition of Hecla Mining&#8217;s producing Casa Berardi gold mine and other Quebec assets, including the Heva-Hosco gold project. Stream deliveries to Franco-Nevada consist of fixed deliveries of 1,625 oz of gold per quarter (6,500 oz of gold per year) for the first five years, with the first delivery received subsequent to quarter-end, on April 15, 2026, followed by variable deliveries of 5.0% of gold produced from Casa\u00a0Berardi and other Quebec assets, and 2.5% of gold produced from Heva-Hosco. Gold ounces delivered will be subject to an ongoing payment of 20% of spot price.<\/li>\n<li>\n          <b>Acquisition of Royalty with i-80 Gold Corp \u2013 Nevada, U.S.: <\/b>On March 16, 2026, we closed the previously announced acquisition of a $250 million NSR from i-80 Gold. The royalty consists of a 1.5% NSR increasing to 3.0% in 2031 on all minerals produced from Granite Creek, the Ruby Hill Property (including Archimedes and Mineral Point), Cove and Lone Tree. Funding of the upfront payment of $225 million was made upon closing, with a further $25 million payable contingent on the incurrence, before the end of 2026, by i-80 Gold of an initial $25 million of budgeted expenditures to advance Mineral Point.<\/li>\n<li>\n          <b>Acquisition of Royalty on Bullabulling Gold Project with Minerals 260 Limited \u2013 Australia: <\/b>On February 26, 2026, we closed the previously announced acquisition of a $120 million (A$170 million) gross royalty from Minerals 260 Limited to support its development of the Bullabulling gold project located in Western Australia. The royalty consists of a 1.45% gross royalty over certain tenements on which Franco-Nevada already held a 1.00% royalty and a new 2.45% gross royalty over tenements where Franco-Nevada did not already hold an existing royalty. Upon production of an aggregate 4.0 Moz Au from royalty lands, the royalties, in aggregate, will step down from 2.45% to 1.63%. Additionally, Franco-Nevada subscribed for $35 million (A$50 million) of Minerals 260&#8217;s ordinary shares at a price of A$0.45 per share.<\/li>\n<\/ul>\n<p>\n        <b>Cobre Panam\u00e1 Update<\/b>\n      <\/p>\n<p>Cobre Panam\u00e1 remains in a phase of Preservation and Safe Management (&#8220;P&amp;SM&#8221;) with production halted. As part of the P&amp;SM plan approved by the government of Panama (the &#8220;GOP&#8221;), import of energy supplies commenced and Cobre Panam\u00e1&#8217;s power plant was restarted. As of the end of Q1 2026, Units 1 and 2 have been commissioned and synchronized to the national grid, and three coal vessels have been successfully received. Both units of the power plant have demonstrated reliable operation, meeting the power demands of the site and excess energy being sold to the national grid.<\/p>\n<p>The integral audit, carried out by SGS Global, is ongoing, with five interim reports having been published, and the sixth report is expected to be published shortly. The integral audit and final seventh consolidated report are expected to be completed and published in Q2 2026.<\/p>\n<p>Subsequent to quarter-end, on April 7, 2026, the GOP authorized the removal, processing, and export of stockpiled ore currently stored on site at the Cobre Panam\u00e1 mine pursuant to the P&amp;SM Plan. As a result, First Quantum estimates that Cobre Panam\u00e1 will produce between 30,000 and 40,000 tonnes of copper in 2026, with the balance to be processed in 2027 for a total of approximately 70,000 tonnes. Based on these estimates, stream deliveries to Franco\u2011Nevada are expected to total approximately 23,100 gold ounces and 265,000 silver ounces. Deliveries of stream ounces to Franco-Nevada, which are determined based on the sale of copper concentrate by First Quantum under its offtake agreements, are expected to commence in Q3 2026, with the majority of deliveries anticipated in 2027.<\/p>\n<p>\n        <b>Sustainability Updates<\/b>\n      <\/p>\n<p>During the quarter, we collaborated with the Young Mining Professionals Scholarship Fund to roll-out a dedicated Franco-Nevada Mining Industry Scholarship and, beginning with the 2026\/27 academic year, will fund up to C$30,000 annually in renewable, merit-based scholarships for students enrolled in mining related university, college or trade school programs in Canada. During the period, we renewed Franco-Nevada&#8217;s commitment to Ense\u00f1a Per\u00fa for the 2026\/27 campaign in support of educational and community development initiatives in Peru. Subsequent to quarter end, we funded a contribution in partnership with i-80 Gold to support the Boys &amp;\u202fGirls Club Early Learning Center in Eureka, Nevada. We continue to rank highly with leading ESG rating agencies, and improved our MSCI ESG rating to &#8220;AAA&#8221; during the quarter, placing us in the top rating tier.<\/p>\n<p>\n        <b>Available Capital<\/b>\n      <\/p>\n<p>We had $3.4 billion in Available Capital as at March 31, 2026. This was comprised of $714.7 million in cash and cash equivalents, $1,142.4 million in equity investments and $1.0 billion in unused credit facility with a $500.0 million accordion available directly to Franco-Nevada Corporation. Available credit was further bolstered subsequent to quarter-end by the addition of a second revolving credit facility of $500.0 million with a $250.0 million accordion, entered into by Franco-Nevada International Corporation, our wholly owned subsidiary.<\/p>\n<p>\n        <b>Guidance<\/b>\n      <\/p>\n<p>\n        <i>The following contains forward-looking statements. For a description of material factors that could cause our actual results to differ materially from the forward-looking statements below, please see the &#8220;Cautionary Statement on Forward-Looking Information&#8221; section at the end of this news release and the &#8220;Risk Factors&#8221; section of our most recent Annual Information Form filed with the Canadian securities regulatory authorities on <a href=\"http:\/\/www.sedarplus.com\" rel=\"nofollow\">www.sedarplus.com<\/a> and our most recent Form 40-F filed with the SEC on <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=en&amp;o=4686157-1&amp;h=2089778219&amp;u=https%3A%2F%2Fwww.sec.gov%2F&amp;a=www.sec.gov\" target=\"_blank\" rel=\"nofollow\">www.sec.gov<\/a>. Our 2026 guidance is based on assumptions including the forecasted state of operations from our assets based on the public statements and other disclosures by the third-party owners and operators of the underlying properties and our assessment thereof.<\/i>\n      <\/p>\n<p>We remain on track to achieve our 2026 GEO sales guidance of 510,000 to 570,000 ounces, which does not include any potential contributions from Cobre Panam\u00e1.<\/p>\n<p>While we expect to benefit from the recent approval of the processing of stockpiled ore at Cobre Panam\u00e1, GEO contributions for 2026 are expected to be relatively moderate, with the majority of deliveries anticipated in 2027. First Quantum estimates it will produce approximately 70,000 tonnes of copper from the processing of stockpiled ore. This would result in stream deliveries to Franco-Nevada of approximately 23,100 gold ounces and 265,000 silver ounces.<\/p>\n<p>As a royalty and streaming company, our revenues are largely insulated from the sharp increase in oil prices. Our guidance continues to be based on the commodity price assumptions used at the beginning of the year. Should oil prices remain elevated, we would expect a positive impact on our Energy revenue. An increase of $10 relative to our assumed WTI price of $70 per barrel would be expected to increase oil revenue by approximately 12%. In Q1 2026, oil revenue amounted to $33.5 million. Natural gas liquids, which have seen similar price appreciation, contributed a further $5.3 million.<\/p>\n<p>The following table presents our Q1 2026 actual performance compared to our 2026 guidance.<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026 Guidance <\/b><br \/>\n                  <b><br \/>\n                    <sup>(1) (2)<\/sup><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Q1 2026 Actual <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Commodity<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Gold ounces sold (oz)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>360,000 to 400,000<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">91,158<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Silver ounces sold (oz)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,700,000 to 5,500,000<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,417,077<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">PGMs ounces sold (oz)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>32,000 to 37,000<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,834<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Diversified revenue (millions)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$245 to $285<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$82.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GEOs Sold (oz)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>510,000 to 570,000<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">136,353<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>1<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>Our 2026 guidance assumes the following commodity prices: $4,500\/oz Au, $75.00\/oz Ag, $2,000\/oz Pt, $1,650\/oz Pd, $100\/tonne Fe 62% CFR China, $70\/bbl WTI oil and $3.00\/mcf Henry Hub natural gas. GEOs for the 2026 period are calculated based on fixed conversion ratios based on the prices assumed in this 2026 guidance.<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>2<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>Our guidance does not reflect any incremental revenue from additional contributions we may make to the Royalty Acquisition Venture with Continental. Our guidance does not reflect any buy-backs which may be elected at the discretion of our operators with the exception of the buy-back of the Cascabel royalty and stream, which occurred in March 2026.<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Q1 2026<\/b><br \/>\n        <b> Portfolio Updates<\/b>\n      <\/p>\n<p>\n        <b>Precious Metal assets:<\/b> GEOs sold from our Precious Metal assets amounted to 117,980 GEOs for Q1 2026, an increase of 17% from 100,623 GEOs in Q1 2025. This was primarily due to robust production at Antamina and South Arturo, and contributions from Porcupine and C\u00f4t\u00e9 Gold which royalties were acquired in April and June 2025, respectively.<\/p>\n<p>\n        <i>South America: <\/i>\n      <\/p>\n<ul type=\"disc\">\n<li>Candelaria <i>(gold and silver stream)<\/i> \u2013 GEOs sold in Q1 2026 were lower than those sold in Q1 2025, as the prior period quarter included the sale of 3,333 GEOs from inventory held at December 31, 2024. In addition, production at the mine was lower compared to last year, which had the benefit of higher-grade ore from Phase 11. Lundin Mining expects production to be weighted towards H2 2026 when it expects to access higher grade ore from Phase 12.<\/li>\n<li>Antapaccay <i>(gold and silver stream)<\/i> \u2013 GEOs sold in Q1 2026 were higher than those sold in Q1 2025, primarily due to mine sequencing and timing of shipments.<\/li>\n<li>Antamina <i>(22.5% silver stream)<\/i> \u2013 Silver ounces sold in Q1 2026 were higher than in Q1 2025. The increase in deliveries is attributable to higher silver grades in the current period and timing of shipments.<\/li>\n<li>Tocantinzinho <i>(gold stream)<\/i> \u2013 GEOs sold in Q1 2026 were relatively consistent with those sold in Q1 2025. Gold production was lower in the quarter than in previous quarters due to planned processing of lower grade ore. G Mining Ventures expects production to be weighted towards H2 2026 as higher-grade\u00a0mineralization becomes available in accordance with the mine plan. GEOs sold in the prior year quarter also included the sale of 667 GEOs from inventory held at December 31, 2024.<\/li>\n<li>Condestable <i>(gold and silver stream)<\/i> \u2013 There were no GEO deliveries from Condestable during the quarter as the stream transitioned from fixed deliveries to variable deliveries. Variable deliveries for the Condestable stream are due 15 days following the end of each quarter. 3,146 GEOs attributable to the mine&#8217;s Q1 2026 production period were received in April 2026. This compares to 2,994 GEOs sold in Q1 2025.<\/li>\n<li>Yanacocha <i>(1.8% royalty)<\/i> \u2013 GEOs from our Yanacocha royalty were higher in Q1 2026 than in Q1 2025, with strong contributions from the mine which produced 144,000 gold ounces in the current period. Newmont anticipates total production for 2026 of approximately 460,000 gold ounces.<\/li>\n<\/ul>\n<p>\n        <i>Central America &amp; Mexico:<\/i>\n      <\/p>\n<ul type=\"disc\">\n<li>Guadalupe-Palmarejo <i>(50% gold stream)<\/i> \u2013 GEOs sold in Q1 2026 were slightly lower than in Q1 2025, as the prior period quarter included the sale of 2,216 GEOs from inventory held at December 31, 2024. In February 2026, Coeur Mining announced an increase in gold mineral reserves of 40%, extending the mine life by approximately five years.<\/li>\n<li>Cobre Panam\u00e1 <i>(gold and silver stream)<\/i> \u2013 During the quarter, we sold 935 GEOs in connection with the sale of concentrate that had remained on site when production was suspended in November 2023. As a result of the approval of the processing of stockpiled ore at Cobre Panam\u00e1, we expect additional stream deliveries of approximately 23,100 gold ounces and 265,000 silver ounces. Deliveries for 2026 are expected to be relatively moderate, with the majority of deliveries anticipated in 2027.<\/li>\n<\/ul>\n<p>\n        <i>Canada:<\/i>\n      <\/p>\n<ul type=\"disc\">\n<li>C\u00f4t\u00e9 Gold <i>(7.5% GMR)<\/i> \u2013 GEOs from C\u00f4t\u00e9 were lower in Q1 2026 than in Q4 2025, as the mine produced 74,700 gold ounces (100% basis) compared to 87,200 ounces in Q4 2025. Throughput in the quarter was limited by unplanned conveyor downtime. Performance improved in April 2026. In addition, gold production is expected to be more heavily weighted towards H2 2026 based on expected higher grades as determined by the scheduled mine sequence. An updated mineral resource estimate for C\u00f4t\u00e9 is planned for Q2 2026, followed by a technical report that is on track by year-end and is expected to outline a larger-scale mine incorporating both the C\u00f4t\u00e9 and Gosselin zones.<\/li>\n<li>Detour Lake <i>(2% royalty)<\/i> \u2013 Agnico Eagle reported strong production from Detour during the quarter driven by higher availability and productivity of the hauling fleet. Development activities for the underground project continued, with the exploration ramp reaching a depth of 147 metres and overburden removal commencing for the conveyor\u2011ramp portal. Exploration drilling, which totalled 39,052 metres during the quarter, continued to expand and infill the mineralization below and to the west of the mineral resource pit.<\/li>\n<li>Hemlo <i>(50% NPI and 3% NSR)<\/i> \u2013 We earned 5,841 GEOs in Q1 2026, a decrease compared to 6,347 GEOs in Q1 2025. GEOs recognized in the current period included 2,100 GEOs related to Q4 2025. Hemlo Mining Corporation continued to advance several optimization initiatives during the quarter, including transitioning to an owner-operated model, launching a 130,000-metre drill program, and advancing an updated mineral resource estimate and mine plan.<\/li>\n<li>Porcupine <i>(4.25% royalty)<\/i> \u2013 In April 2026, Discovery Silver reported strong exploration results at all operations, including multiple high-grade intersections from resource conversion and extension drilling at Hoyle Pond and Borden, favourable drill results within and along strike of current resources at Pamour, and encouraging results from district exploration drilling at Owl Creek. In March 2026, Discovery announced the acquisition of Glencore&#8217;s Kidd Operations which will provide Discovery with the ability to potentially double production from their Timmins complex.<\/li>\n<li>Greenstone <i>(3% royalty)<\/i> \u2013 Equinox Gold reported operational improvements in Q1 2026, with winter mining rates averaging 180 ktpd, consistent with expectations. Mill throughput exceeded nameplate capacity of 27 ktpd for 51% of days in Q1 2026 compared to 36% in Q4 2025.<\/li>\n<li>Valentine <i>(3% royalty)<\/i> \u2013 Equinox Gold reported that the ramp-up is progressing well, with the mine averaging 90% of nameplate capacity for Q1 2026. Once operating at design capacity, Valentine Gold is expected to produce between 175,000 and 200,000 ounces of gold annually. Equinox is also continuing to advance the Phase 2 expansion which would increase average annual production to approximately 223,000 ounces for ten years.<\/li>\n<li>Musselwhite <i>(5% NPI)<\/i> \u2013 In April 2026, Orla Mining continued to report exploration success at Musselwhite, with stacked extension zones expanding the mine trend by more than two kilometers and providing for significant mine life extension. Surface drilling within 10km of the mill identified multiple targets for potential open-pit satellite deposits, including at Camp Bay which is covered by our NPI.<\/li>\n<li>Sudbury (gold and PGM stream) \u2013 GEOs sold from our Sudbury stream were higher in Q1 2026 than in Q1 2025. Production relates to the McCreedy West Mine operated by Magna Mining. Since acquiring the assets in January 2025, Magna continues to evaluate production opportunities at McCreedy West as it continues to receive new diamond drilling information and optimizes its plan to increase production and profitability.<\/li>\n<li>Eskay Creek <i>(2.5% royalty)<\/i> \u2013 Skeena Resources reported that construction was 49% complete as of February 28, 2026 and that the project remains on schedule, with initial production targeted for Q2 2027 and commercial production for Q3 2027. In April 2026, Skeena raised $750 million through the issuance of senior secured notes.<\/li>\n<li>Canadian Malartic <i>(1.5% royalty)<\/i> \u2013 At Odyssey, production from the East Gouldie ramp commenced in March 2026, three months ahead of schedule. Gold production was in line with plan at approximately 27,400 ounces, with Odyssey expected to contribute approximately 120,000 ounces of gold in 2026. It is estimated that Franco-Nevada&#8217;s East Gouldie claims cover approximately 28% of the East Gouldie reserve, with drilling continuing to extend East Gouldie to the east in both the upper and lower portions of the deposit. For 2026, Franco-Nevada estimates 600-700 GEOs will be received from our royalty interest at Canadian Malartic.<\/li>\n<\/ul>\n<p>\n        <i>U.S.:<\/i>\n      <\/p>\n<ul type=\"disc\">\n<li>Stillwater <i>(5% royalty)<\/i> \u2013 Sibanye-Stillwater reported that its US PGM Operations were converting its stoping technique to allow increased volumes mined. The phased implementation is expected to be completed by H2 2028. Sibanye-Stillwater expects steady-state production of approximately 410,000 ounces by 2029, with Stillwater West providing future optionality and upside.<\/li>\n<li>South Arturo <i>(4-9% royalties) <\/i>\u2013 GEOs sold in Q1 2026 were higher than in Q1 2025, as Nevada Gold Mines continues to mine the South Arturo pit in 2026, in line with the Carlin mine plan.<\/li>\n<li>Bald Mountain <i>(1-5% royalties)<\/i> \u2013 Kinross reported that the Redbird project advanced across several key areas during the quarter, including mining, construction of processing infrastructure, and earthworks for the heap leach pad extension. The Redbird project, along with five additional satellite pits, is expected to incrementally produce a total of 640,000 gold ounces and extends the mine life to 2032.<\/li>\n<li>i-80 <i>(1.5% royalty)<\/i> \u2013 In March 2026, i-80 completed a recapitalization plan which is expected to fully fund its development plan through Phase 1 and Phase 2, with a path to funding Phase 3. In April, i-80 announced positive assay results from its drilling campaign at the Archimedes project. i-80 commenced construction of Archimedes in Q3 2025.<\/li>\n<\/ul>\n<p>\n        <i>Rest of World:<\/i>\n      <\/p>\n<ul type=\"disc\">\n<li>Western Limb <i>(gold and platinum stream) <\/i>\u2013 GEOs sold in Q1 2026 were lower than in the prior year quarter. Deliveries received in Q1 2025 related to four months of production, commencing from the effective date of the agreement (September 1, 2024) through December 31, 2024.<\/li>\n<li>Tasiast <i>(2% royalty)<\/i> \u2013 GEOs from our Tasiast royalty were higher than in Q1 2025, due to higher production supported by higher grades.<\/li>\n<li>Subika (Ahafo) <i>(2% royalty) <\/i>\u2013 GEOs from our Subika (Ahafo) royalty were lower in Q1 2026 than in Q1 2025 as mining activities in the Subika open pit were completed as planned in Q3 2025. Production on royalty ground continues at the Subika Underground, where Newmont plans to increase its investment in exploration and advanced projects.<\/li>\n<\/ul>\n<p>\n        <b>Diversified assets: <\/b>Our Diversified assets, primarily comprising our Iron Ore and Energy interests, generated $82.6 million in revenue, compared to $74.8 million in Q1 2025. When converted to GEOs, our Diversified assets contributed 18,373 GEOs, compared to 25,962 GEOs in Q1 2025. The lower GEOs are due to using a higher gold price for conversion ($4,500 per ounce for the current period).<\/p>\n<p>\n        <i>Other Mining:<\/i>\u00a0<\/p>\n<ul type=\"disc\">\n<li>Vale <i>(iron ore royalty)<\/i>\u00a0\u2013 Revenue from the Vale royalty increased when compared to Q1 2025, largely driven by the inclusion of sales from the Southeastern System following the achievement of the cumulative sales threshold of 1.7 billion tonnes of iron ore in April 2025.<\/li>\n<li>LIORC \u2013 Revenue from our attributable interest on the Carol Lake mine in Q1 2026 was lower than in Q1 2025. LIORC declared a cash dividend of C$0.30 per common share in the current period, compared to C$0.50 in Q1 2025. Production at IOC in Q1 2026 was lower due to adverse weather and ongoing challenges including mine equipment reliability.<\/li>\n<li>Ring of Fire \u2013 In March 2026, the government of Ontario released an accelerated plan for all\u2011season road construction into the Ring of Fire, with construction scheduled to commence in mid-2026. The Ontario government has also signed new economic partnerships with Marten Falls First Nation and Webequie First Nation. In December 2025, the Ontario and Canadian federal governments signed a cooperation agreement aimed at eliminating duplicative environmental and impact assessment processes through the &#8220;One Project, One Process&#8221; framework.<\/li>\n<\/ul>\n<p>\n        <i>Energy: <\/i>\n      <\/p>\n<ul type=\"disc\">\n<li>U.S. <i>(various royalty rates)<\/i> \u2013 Revenue from our U.S. Energy interests increased to $43.0 million in Q1 2026, compared to $41.8 million in Q1 2025. The increase was driven by higher production at our Haynesville interests, and higher realized gas prices at Marcellus due to weather-related seasonality.<\/li>\n<li>Canada <i>(various royalty rates)<\/i> \u2013 Revenue from our Canadian Energy interests was $16.4 million in Q1 2026, compared to $16.2 million in Q1 2025 due to higher realized oil prices. Our Weyburn NRI benefited from stronger pricing and lower expenses compared to Q1 2025.<\/li>\n<\/ul>\n<p>\n        <b>Dividend Declaration<\/b>\n      <\/p>\n<p>Franco-Nevada is pleased to announce that its Board of Directors has declared a quarterly dividend of US$0.44 per share. The dividend will be paid on June 25, 2026, to shareholders of record on June 11, 2026 (the &#8220;Record Date&#8221;). The dividend has been declared in U.S. dollars and the Canadian dollar equivalent will be determined based on the daily average rate posted by the Bank of Canada on the Record Date. Under Canadian tax legislation, Canadian resident individuals who receive &#8220;eligible dividends&#8221; are entitled to an enhanced gross-up and dividend tax credit on such dividends.<\/p>\n<p>The Company has a Dividend Reinvestment Plan (the &#8220;DRIP&#8221;) which allows shareholders of Franco-Nevada to reinvest dividends to purchase additional common shares at the Average Market Price, as defined in the DRIP, subject to a discount from the Average Market Price in the case of treasury acquisitions. The Company will issue additional common shares through treasury at a 1% discount to the Average Market Price. The Company may, from time to time, in its discretion, change or eliminate the discount applicable to treasury acquisitions or direct that such common shares be purchased in market acquisitions at the prevailing market price, any of which would be publicly announced. Participation in the DRIP is optional. The DRIP and enrollment forms are available on the Company&#8217;s website at <a href=\"http:\/\/www.franco-nevada.com\" rel=\"nofollow\">www.franco-nevada.com<\/a>. Canadian and U.S. registered shareholders may also enroll in the DRIP online through the plan agent&#8217;s self-service web portal at <a href=\"http:\/\/www.investorcentre.com\/franco-nevada\" rel=\"nofollow\">www.investorcentre.com\/franco-nevada<\/a>. Canadian and U.S. beneficial shareholders should contact their financial intermediary to arrange enrollment. Non-Canadian and non-U.S. shareholders may potentially participate in the DRIP, subject to the satisfaction of certain conditions. Non-Canadian and non-U.S. shareholders should contact the Company to determine whether they satisfy the necessary conditions to participate in the DRIP.<\/p>\n<p>This news release is not an offer to sell or a solicitation of an offer for securities. A registration statement relating to the DRIP has been filed with the U.S. Securities and Exchange Commission and may be obtained under the Company&#8217;s profile on the U.S. Securities and Exchange Commission&#8217;s website at\u00a0<a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=en&amp;o=4686157-1&amp;h=3399005485&amp;u=http%3A%2F%2Fwww.sec.gov%2F&amp;a=www.sec.gov\" target=\"_blank\" rel=\"nofollow\">www.sec.gov<\/a>.<\/p>\n<p>\n        <b>Shareholder Information and Details for Q1 2026 Conference Call<\/b>\n      <\/p>\n<p>The complete Consolidated Financial Statements and Management&#8217;s Discussion and Analysis can be found on our website at <a href=\"http:\/\/www.franco-nevada.com\" rel=\"nofollow\">www.franco-nevada.com<\/a>, on SEDAR+ at <a href=\"http:\/\/www.sedarplus.com\" rel=\"nofollow\">www.sedarplus.com<\/a> and on EDGAR at <a href=\"http:\/\/www.sec.gov\" rel=\"nofollow\">www.sec.gov<\/a>.<\/p>\n<p>We will host a conference call to review our Q1 2026 quarterly results. Interested investors are invited to participate as follows:<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Conference\u00a0Call\u00a0and\u00a0Webcast:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">May 13<sup>th<\/sup> 8:00\u00a0am\u00a0ET<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Dial\u2011in\u00a0Numbers:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Toll\u2011Free:\u00a01-888-510-2154<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">International:\u00a0437-900-0527<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Conference Call URL (This allows participants to join the conference call by <br \/>phone without operator assistance. Participants will receive an automated <br \/>call back after entering their name and phone number):<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">emportal.ink\/4eu8kF3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Webcast:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=en&amp;o=4686157-1&amp;h=3784281295&amp;u=http%3A%2F%2Fwww.franco-nevada.com%2F&amp;a=www.franco-nevada.com\" target=\"_blank\" class=\"prnews_a\" rel=\"nofollow\"><br \/>\n                    <span>www.franco-nevada.com<\/span><br \/>\n                  <\/a><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Replay\u00a0(available\u00a0until May 20<sup>th<\/sup>):<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Toll\u2011Free:\u00a01-888-660-6345<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">International:\u00a0289-819-1450<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Pass\u00a0code: 31601#<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Corporate Summary<\/b>\n      <\/p>\n<p>Franco-Nevada Corporation is the leading gold-focused royalty and streaming company with the largest and most diversified portfolio of cash-flow producing assets. Its business model provides investors with gold price and exploration optionality while limiting exposure to cost inflation. Franco-Nevada is debt-free and uses its free cash flow to expand its portfolio and pay dividends. It trades under the symbol FNV on both the Toronto and New York stock exchanges. Franco-Nevada is the gold investment that works.<\/p>\n<p>\n        <b>Forward-Looking Statements <\/b>\n      <\/p>\n<p>\n        <i>This news release contains &#8220;forward-looking information&#8221; and &#8220;forward-looking statements&#8221; within the meaning of applicable Canadian securities laws and the United States Private Securities Litigation Reform Act of 1995, respectively, which may include, but are not limited to, statements with respect to future events or future performance, management&#8217;s expectations regarding Franco-Nevada&#8217;s growth, results of operations, estimated future revenues, performance guidance, carrying value of assets, future dividends and requirements for additional capital, mineral resources and mineral reserves estimates, production estimates, production costs and revenue, future demand for and prices of commodities, expected mining sequences, business prospects and opportunities, the performance and plans of third party operators, any ongoing or future audits being conducted by the Canada Revenue Agency (&#8220;CRA&#8221;), the expected exposure for current and future tax assessments and available remedies, and statements with respect to the future status and any potential restart of the Cobre Panam\u00e1 mine. In addition, statements relating to mineral resources and mineral reserves, GEOs or mine lives are forward-looking statements, as they involve implied assessment, based on certain estimates and assumptions, and no assurance can be given that the estimates and assumptions are accurate and that such mineral resources and mineral reserves, GEOs or mine lives will be realized. Such forward-looking statements reflect management&#8217;s current beliefs and are based on information currently available to management. Often, but not always, forward-looking statements can be identified by the use of words such as &#8220;plans&#8221;, &#8220;expects&#8221;, &#8220;is expected&#8221;, &#8220;budgets&#8221;, &#8220;potential for&#8221;, &#8220;scheduled&#8221;, &#8220;estimates&#8221;, &#8220;forecasts&#8221;, &#8220;predicts&#8221;, &#8220;projects&#8221;, &#8220;intends&#8221;, &#8220;targets&#8221;, &#8220;aims&#8221;, &#8220;anticipates&#8221; or &#8220;believes&#8221; or variations (including negative variations) of such words and phrases or may be identified by statements to the effect that certain actions &#8220;may&#8221;, &#8220;could&#8221;, &#8220;should&#8221;, &#8220;would&#8221;, &#8220;might&#8221; or &#8220;will&#8221; be taken, occur or be achieved. Forward-looking statements involve known and unknown risks, uncertainties and other factors, which may cause the actual results, performance or achievements of Franco-Nevada to be materially different from any future results, performance or achievements expressed or implied by the forward-looking statements. A number of factors could cause actual events or results to differ materially from any forward-looking statement, including, without limitation: fluctuations in the prices of the primary commodities that drive royalty and stream revenue (gold, platinum group metals, copper, nickel, silver, iron-ore and oil and gas); fluctuations in the value of the Canadian and Australian dollar, Brazilian real, Mexican peso and any other currency in which revenue is generated, relative to the U.S. dollar; changes in national and local government legislation, including permitting and licensing regimes and taxation policies and the enforcement thereof; tariff and other trade measures that may be imposed by the United States and proposed retaliatory measures that may be adopted by its trading partners; the adoption and implementation of a global minimum tax on corporations; regulatory, political or economic developments in any of the countries where properties in which Franco-Nevada holds a royalty, stream or other interest are located or through which they are held; risks related to the operators of the properties in which Franco-Nevada holds a royalty, stream or other interest, including changes in the ownership and control of such operators; relinquishment or sale of mineral properties; influence of macroeconomic developments; business opportunities that become available to, or are pursued by Franco-Nevada; reduced access to debt and equity capital; litigation; title, permit or license disputes related to interests on any of the properties in which Franco-Nevada holds a royalty, stream or other interest; whether or not the Company is determined to have &#8220;passive foreign investment company&#8221; (&#8220;PFIC&#8221;) status as defined in Section 1297 of the United States Internal Revenue Code of 1986, as amended; potential changes in Canadian tax treatment of offshore streams; excessive cost escalation as well as development, permitting, infrastructure, operating or technical difficulties on any of the properties in which Franco-Nevada holds a royalty, stream or other interest; access to sufficient pipeline capacity; actual mineral content may differ from the mineral resources and mineral reserves contained in technical reports; rate and timing of production differences from mineral resource estimates, other technical reports and mine plans; risks and hazards associated with the business of development and mining on any of the properties in which Franco-Nevada holds a royalty, stream or other interest, including, but not limited to unusual or unexpected geological and metallurgical conditions, slope failures or cave-ins, sinkholes, flooding and other natural disasters, terrorism, civil unrest or an outbreak of contagious disease; the impact of future pandemics; and the integration of acquired assets. The forward-looking statements contained herein are based upon assumptions management believes to be reasonable, including, without limitation: the ongoing operation of the properties in which Franco-Nevada holds a royalty, stream or other interest by the owners or operators of such properties in a manner consistent with past practice; the accuracy of public statements and disclosures made by the owners or operators of such underlying properties; no material adverse change in the market price of the commodities that underlie the asset portfolio; the Company&#8217;s ongoing income and assets relating to determination of its PFIC status; no material changes to existing tax treatment; the expected application of tax laws and regulations by taxation authorities; the expected assessment and outcome of any audit by any taxation authority; no adverse development in respect of any significant property in which Franco-Nevada holds a royalty, stream or other interest; the accuracy of publicly disclosed expectations for the development of underlying properties that are not yet in production; integration of acquired assets; and the absence of any other factors that could cause actions, events or results to differ from those anticipated, estimated or intended. However, there can be no assurance that forward-looking statements will prove to be accurate, as actual results and future events could differ materially from those anticipated in such statements. Investors are cautioned that forward-looking statements are not guarantees of future performance. In addition, there can be no assurance as to (i) the outcome of any ongoing or future audits by the CRA or the Company&#8217;s exposure as a result thereof, or (ii) the future status and any potential restart of the Cobre Panam\u00e1 mine. Franco-Nevada cannot assure investors that actual results will be consistent with these forward-looking statements. Accordingly, investors should not place undue reliance on forward-looking statements due to the inherent uncertainty therein.\u00a0<\/i>\n      <\/p>\n<p>\n        <i>For additional information with respect to risks, uncertainties and assumptions, please refer to Franco-Nevada&#8217;s most recent Annual Information Form as well as Franco-Nevada&#8217;s most recent Management&#8217;s Discussion and Analysis filed with the Canadian securities regulatory authorities on <a href=\"http:\/\/www.sedarplus.com\" rel=\"nofollow\">www.sedarplus.com<\/a> and Franco-Nevada&#8217;s most recent Annual Report filed on Form 40-F filed with the SEC on <a href=\"http:\/\/www.sec.gov\" rel=\"nofollow\">www.sec.gov<\/a>. The forward-looking statements herein are made as of the date hereof only and Franco-Nevada does not assume any obligation to update or revise them to reflect new information, estimates or opinions, future events or results or otherwise, except as required by applicable law.<\/i>\n      <\/p>\n<p>\n        <b><br \/>\n          <u>ENDNOTES:<\/u><br \/>\n        <\/b>\n      <\/p>\n<p>\n        <b>1. Gold Equivalent Ounces (&#8220;GEOs&#8221;) and Net Gold Equivalent Ounces (&#8220;Net GEOs&#8221;):<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>\n          <b>GEOs<\/b> include Franco-Nevada&#8217;s attributable share of production from our Mining and Energy assets after applicable recovery and payability factors. GEOs are estimated on a gross basis for NSRs and, in the case of stream ounces, before the payment of the per ounce contractual price paid by the Company. For NPI royalties, GEOs are calculated taking into account the NPI economics. Where the Company receives gold and silver bullion in-kind as payment for its royalties, GEOs are recognized at the time of receipt of such bullion. Silver, platinum, palladium, iron ore, oil, gas and other commodities are converted to GEOs by dividing associated revenue, which includes settlement adjustments, by the relevant gold price. Beginning in 2026, the Company adopted fixed GEO conversion ratios based on the pricing assumptions outlined in our guidance. This methodology replaces our previous methodology which was based on variable GEO conversion ratios using prevailing market prices. Our 2026 guidance, as disclosed in our 2025 MD&amp;A filed on March 10, 2026, assumed the following commodity prices: $4,500\/oz Au, $75.00\/oz Ag, $2,000\/oz Pt, $1,650\/oz Pd, $100\/tonne Fe 62% CFR China, $70\/bbl WTI oil and $3.00\/mcf Henry Hub natural gas. GEOs for the 2026 period are calculated based on fixed conversion ratios based on the prices assumed in this 2026 guidance.<\/li>\n<li>\n          <b>Net GEOs<\/b> are GEOs sold, net of direct operating costs, including for our stream GEOs, the associated ongoing cost per ounce.<\/li>\n<\/ul>\n<p>\n        <b>Calculation of Net Gold Equivalent Ounces: <\/b>\n      <\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"7\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>For the three months ended<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March<\/b>\u00a0<b>31,<\/b>\u00a0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>(expressed in millions, excepts GEOs and Gold<\/i>\u00a0<i>Price)<\/i><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GEOs<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>136,353<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">126,585<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Less:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Cash Costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>46.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">38.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Divided by: Gold price per ounce<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,500<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,863<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>10,333<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,447<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net GEOs<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>126,020<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">113,138<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>2. NON-GAAP FINANCIAL MEASURES:\u00a0 <\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>\n          <b>Adjusted Net Income, Adjusted Net Income per share, Adjusted Net Income Margin, Adjusted EBITDA, Adjusted EBITDA per share, and Adjusted EBITDA Margin<\/b> are non-GAAP financial measures with no standardized meaning under International Financial Reporting Standards (&#8220;IFRS Accounting Standards&#8221;) and might not be comparable to similar financial measures disclosed by other issuers. For a quantitative reconciliation of each non-GAAP financial measure to the most directly comparable financial measure under IFRS Accounting Standards, refer to the below tables. Further information relating to these non-GAAP financial measures is incorporated by reference from the &#8220;Non-GAAP Financial Measures&#8221; section of Franco-Nevada&#8217;s MD&amp;A for the three months ended March\u00a031,\u00a02026 dated May 12, 2026 filed with the Canadian securities regulatory authorities on SEDAR+ available at <a href=\"http:\/\/www.sedarplus.com\" rel=\"nofollow\">www.sedarplus.com<\/a> and with the U.S. Securities and Exchange Commission available on EDGAR at <a href=\"http:\/\/www.sec.gov\" rel=\"nofollow\">www.sec.gov<\/a>.<\/li>\n<li>\n          <b>Change in Composition of Adjusted Net Income \u2013 Gains on buy-backs of royalty and stream interests: <\/b>Effective Q1 2026, the Company updated the composition of its Adjusted Net Income (and related per share and margin amounts) to no longer adjust for gains on contractual buy-backs of royalty and stream interests. Previously, gains on buy-backs were an adjusting item when calculating Adjusted Net Income (and related per share and margin amounts). Management continues to adjust for gains or losses on sales on discretionary sales of mineral interests when calculating these non-GAAP measures. Management believes that this change more appropriately reflects the Company&#8217;s operating performance as contractual buy-backs are embedded in the terms of many of the Company&#8217;s royalty and stream interest agreements, such that they occur in the ordinary course and are an integral part of Franco Nevada&#8217;s royalty and stream business. Unlike less common discretionary sales of mineral interests, these transactions are evaluated by management when assessing overall returns from our royalty and stream interests, and accordingly, we believe such gains should not be eliminated for purposes of calculating Adjusted Net Income and related per share amounts, when evaluating performance for investors. This change is reflected on a full retrospective basis.<\/li>\n<li>\n          <b>Adjusted Net Income and Adjusted Net Income per share<\/b> are non-GAAP financial measures, which exclude the following from net income and earnings per share (&#8220;EPS&#8221;): impairment losses and reversal related to royalty, stream and working interests and investments; gains\/losses on disposals of royalty, stream and working interests (excluding gains on buy-backs of royalty and stream interests) and investments; impairment losses and expected credit losses related to equity investments, loans receivable and other financial instruments, changes in fair value of investments, loans receivable and other financial instruments, foreign exchange gains\/losses and other income\/expenses; the impact of income taxes on these items; income taxes related to the reassessment of the probability of realization of previously recognized or de-recognized deferred income tax assets; and income taxes relating to the revaluation of deferred income tax assets and liabilities as a result of statutory income tax rate changes in the countries in which the Company operates.<\/li>\n<li>\n          <b>Adjusted Net Income Margin<\/b> is a non-GAAP financial measure which is defined by the Company as Adjusted Net Income divided by revenue.<\/li>\n<li>\n          <b>Adjusted EBITDA and Adjusted EBITDA per share<\/b> are non-GAAP financial measures, which exclude the following from net income and EPS: income tax expense\/recovery; finance expenses and finance income; depletion and depreciation; impairment losses and reversals related to royalty, stream and working interests and investments; gains\/losses on disposals of royalty, stream and working interests and investments; gains on buy-backs of royalty and stream interests, impairment losses and expected credit losses related to equity investments, loans receivable and other financial instruments, changes in fair value of investment, loans receivable and other financial instruments, and foreign exchange gains\/losses and other income\/expenses.<\/li>\n<li>\n          <b>Adjusted EBITDA Margin<\/b> is a non-GAAP financial measure which is defined by the Company as Adjusted EBITDA divided by revenue.<\/li>\n<\/ul>\n<p>\n        <b>Reconciliation of Non-GAAP Financial Measures: <\/b>\n      <\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>For the three months ended <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March<\/b>\u00a0<b>31,<\/b>\u00a0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>(expressed in millions, except per share amounts)<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>468.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">209.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Foreign exchange gain and other income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(12.4)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5.7)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Tax effect of adjustments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Net Income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>458.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">205.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Basic weighted average shares outstanding<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>192.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">192.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Net Income per share<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2.38<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.07<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>For the three months ended <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March<\/b>\u00a0<b>31,<\/b>\u00a0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>(expressed in millions, except Adjusted Net Income Margin)<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Net Income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>458.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">205.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Divided by: Revenue<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>650.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">368.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Net Income Margin<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>70.4<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>%<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">55.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">%<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>For the three months ended <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March<\/b>\u00a0<b>31,<\/b>\u00a0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>(expressed in millions, except per share amounts)<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>468.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">209.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Income tax expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>126.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">59.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Finance income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(5.5)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11.1)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Finance expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>0.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Depletion and depreciation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>77.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">68.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Gain on buy-back of royalty and stream interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(63.8)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Foreign exchange gain and other income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(12.4)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5.7)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted EBITDA<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>591.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">321.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Basic weighted average shares outstanding<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>192.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">192.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted EBITDA per share<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3.07<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.67<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>For the three months ended <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March<\/b>\u00a0<b>31,<\/b>\u00a0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <i>(expressed in millions, except Adjusted EBITDA Margin)<\/i><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted EBITDA<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>591.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">321.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Divided by: Revenue<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>650.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">368.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted EBITDA Margin<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>91.0<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>%<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">87.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">%<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>3. AVAILABLE CAPITAL: <\/b>Available Capital comprises our cash and cash equivalents of $714.7 million as at March 31, 2026, our equity investments (excluding our long-term investment in Labrador Iron Ore Company of Canada) of $1,142.4 million and the amount available to borrow under our $1.0 billion corporate revolving credit facility and its accordion of $500.0 million as at March 31, 2026. Subsequent to quarter-end, on May 8, 2026, FNIC entered into a revolving credit facility of $500.0 million with a $250.0 million accordion.<\/p>\n<p>\n        <b>FRANCO-NEVADA CORPORATION<br \/><\/b><br \/>\n        <b>CONDENSED CONSOLIDATED INTERIM STATEMENTS OF FINANCIAL POSITION<br \/><\/b><br \/>\n        <i>(in millions of U.S. dollars)<\/i>\n      <\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>At March<\/b>\u00a0<b>31,<\/b>\u00a0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">At December\u00a031,\u00a0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>ASSETS<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>714.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">670.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Receivables <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>267.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">241.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Gold and silver bullion and stream inventory<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>123.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">40.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>22.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">68.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,127.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,021.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Royalty, stream and working interests, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>6,307.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,043.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,322.0<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,141.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Deferred income tax assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>19.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">23.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>21.0<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>8,797.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,241.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>LIABILITIES<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accounts payable and accrued liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>49.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">44.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax liabilities <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>133.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">78.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Current liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>183.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">123.0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Deferred income tax liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>487.0<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">440.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>12.4<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">33.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>8.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>690.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">606.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>SHAREHOLDERS&#8217; EQUITY<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Share capital<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5,813.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,803.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Contributed surplus<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>16.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">21.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Retained earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,771.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,379.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accumulated other comprehensive income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>504.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">430.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total shareholders&#8217; equity<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>8,106.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,635.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total liabilities and shareholders&#8217; equity<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>8,797.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,241.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\n        <i>The condensed consolidated interim financial statements and accompanying notes can be found in our Q1 2026 Quarterly Report available on our website<\/i>\n      <\/p>\n<p>\n        <b>FRANCO-NEVADA CORPORATION<br \/><\/b><br \/>\n        <b>CONDENSED CONSOLIDATED INTERIM STATEMENTS OF INCOME AND COMPREHENSIVE INCOME\u00a0<br \/><\/b><br \/>\n        <i>(in millions of U.S. dollars and shares, except per share amounts)<\/i>\n      <\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">For\u00a0the\u00a0three months ended <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">March\u00a031,\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Revenue<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Revenue from royalty, streams and working interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>650.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">365.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Interest revenue<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Total revenue<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>650.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">368.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Costs of sales<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Costs of sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>46.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">38.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Depletion and depreciation <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>77.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">68.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total costs of sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>124.4<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">106.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Gross profit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>526.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">261.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Other operating (income) expenses<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">General and administrative expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>9.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Share-based compensation expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>6.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.7<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Gain on buy-back of royalty and stream interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(63.8)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Gain on sale of gold and silver bullion<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(3.1)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(7.1)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total other operating (income) expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(51.5)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8.0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Operating income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>577.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">253.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Foreign exchange gain and other income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>12.4<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.7<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income before finance items and income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>590.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">259.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Finance items<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Finance income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Finance expenses <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(0.8)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.7)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net income before income taxes<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>594.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">269.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>126.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">59.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>468.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">209.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Other comprehensive income, net of taxes<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Items that may be reclassified subsequently to profit and loss:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Currency translation adjustment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(51.9)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.7<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Items that will not be reclassified subsequently to profit and loss:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Gain on changes in the fair value of equity investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">at fair value through other comprehensive income (&#8220;FVTOCI&#8221;), <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">net of income tax<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>133.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">148.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other comprehensive income, net of taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>81.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">151.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Comprehensive income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>550.4<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">361.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Earnings per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Basic <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2.43<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.09<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Diluted <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2.43<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.09<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Weighted average number of shares outstanding<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Basic <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>192.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">192.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Diluted <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>193.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">192.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\n        <i>The condensed consolidated interim financial statements and accompanying notes can be found in our Q1 2026 Quarterly Report available on our website<\/i>\n      <\/p>\n<p>\n        <b>FRANCO-NEVADA CORPORATION<br \/><\/b><br \/>\n        <b>CONDENSED CONSOLIDATED INTERIM STATEMENTS OF CASH FLOWS<br \/><\/b><br \/>\n        <i>(in millions of U.S. dollars)<\/i>\n      <\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"7\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">For\u00a0the\u00a0three months ended <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"7\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">March\u00a031,\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2026<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash flows from operating activities<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>468.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">209.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjustments to reconcile net income to net cash provided by operating activities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Depletion and depreciation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>77.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">68.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Share-based compensation expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Gain on buy-back of royalty and stream interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(63.8)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Unrealized foreign exchange gain<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(1.3)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6.0)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Deferred income tax expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>33.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Gain on sale of gold and silver bullion<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(3.1)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(7.1)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Gain on derivative financial instruments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(11.0)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.1)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Other non-cash items<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(0.2)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Gold and silver bullion from royalties received in-kind<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(47.4)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(19.2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Proceeds from sale of gold and silver bullion <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>15.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">30.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Receipt of deposits and interest from Canada Revenue Agency<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>49.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Increase in other assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(8.2)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Operating cash flows before changes in non-cash working capital<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>510.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">287.0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Changes in non-cash working capital:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Increase in receivables<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(25.6)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8.4)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">(Increase) decrease in other current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(3.2)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Increase in accounts payable and accrued liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>38.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash provided by operating activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>520.4<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">288.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash flows used in investing activities<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Acquisition of royalty, stream and working interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(449.4)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(505.2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Acquisition of investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(35.3)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(52.3)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Proceeds from buy-back of royalty interest<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>97.5<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Acquisition of gold bullion from buy-back of stream interest<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(10.2)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Acquisition of energy well equipment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(0.3)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1.2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Acquisition of property and equipment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(0.2)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2.0)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Proceeds from sale of investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash used in investing activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(397.9)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(551.0)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash flows used in financing activities<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Payment of dividends <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(80.5)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(70.2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Capitalized debt issue costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(0.7)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Proceeds from exercise of stock options <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>0.4<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash used in financing activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(80.8)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(66.8)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Effect of exchange rate changes on cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net change in cash and cash equivalents<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>43.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(323.2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash and cash equivalents at beginning of period<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>670.9<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,451.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash and cash equivalents at end of period<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>714.7<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,128.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Supplemental cash flow information:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income taxes paid<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>58.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">47.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Dividend income received<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Interest and standby fees paid <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>0.8<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\n        <i>The condensed consolidated interim financial statements and accompanying notes can be found in our Q1 2026 Quarterly Report available on our website<\/i>\n      <\/p>\n<p id=\"PURL\">\n        <img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=TO56955&amp;sd=2026-05-12\" \/> View original content:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/news-releases\/franco-nevada-reports-record-q1-2026-results-302770055.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/news-releases\/franco-nevada-reports-record-q1-2026-results-302770055.html<\/a><\/p>\n<p>SOURCE Franco-Nevada Corporation<\/p>\n<\/p><\/div>\n<p>    <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=TO56955&amp;Transmission_Id=202605121715PR_NEWS_USPR_____TO56955&amp;DateId=20260512\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PR Newswire Tom\u00a0Albanese appointed Chair (in U.S. dollars unless otherwise noted) TORONTO, May 12, 2026 \/PRNewswire\/ &#8211;\u00a0Franco-Nevada realized record financial results in the first quarter of 2026, driven by higher commodity prices, contributions from newly acquired assets, a partial buy-back and a refund from the Canada Revenue Agency. &#8220;The sharp rise in oil prices is expected to positively impact our Q2 revenues, while our royalty and streaming model is largely insulated from the impact of energy prices on cost inflation. Franco-Nevada is unique as a mining equity that benefits from rising oil prices. We look forward to further growth from new assets, additional contributions from\u00a0Cobre Panam\u00e1 and the potential for a full resumption of the mine&#8221;, stated Paul Brink, President &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Franco-Nevada Reports Record Q1 2026 Results&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-961862","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Franco-Nevada Reports Record Q1 2026 Results - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Franco-Nevada Reports Record Q1 2026 Results - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"PR Newswire Tom\u00a0Albanese appointed Chair (in U.S. dollars unless otherwise noted) TORONTO, May 12, 2026 \/PRNewswire\/ &#8211;\u00a0Franco-Nevada realized record financial results in the first quarter of 2026, driven by higher commodity prices, contributions from newly acquired assets, a partial buy-back and a refund from the Canada Revenue Agency. &#8220;The sharp rise in oil prices is expected to positively impact our Q2 revenues, while our royalty and streaming model is largely insulated from the impact of energy prices on cost inflation. Franco-Nevada is unique as a mining equity that benefits from rising oil prices. We look forward to further growth from new assets, additional contributions from\u00a0Cobre Panam\u00e1 and the potential for a full resumption of the mine&#8221;, stated Paul Brink, President &hellip; Continue reading &quot;Franco-Nevada Reports Record Q1 2026 Results&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T22:37:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=TO56955&amp;sd=2026-05-12\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"36 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"Franco-Nevada Reports Record Q1 2026 Results\",\"datePublished\":\"2026-05-12T22:37:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/\"},\"wordCount\":7275,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edge.prnewswire.com\\\/c\\\/img\\\/favicon.png?sn=TO56955&amp;sd=2026-05-12\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/\",\"name\":\"Franco-Nevada Reports Record Q1 2026 Results - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edge.prnewswire.com\\\/c\\\/img\\\/favicon.png?sn=TO56955&amp;sd=2026-05-12\",\"datePublished\":\"2026-05-12T22:37:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edge.prnewswire.com\\\/c\\\/img\\\/favicon.png?sn=TO56955&amp;sd=2026-05-12\",\"contentUrl\":\"https:\\\/\\\/edge.prnewswire.com\\\/c\\\/img\\\/favicon.png?sn=TO56955&amp;sd=2026-05-12\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/franco-nevada-reports-record-q1-2026-results\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Franco-Nevada Reports Record Q1 2026 Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Franco-Nevada Reports Record Q1 2026 Results - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/","og_locale":"en_US","og_type":"article","og_title":"Franco-Nevada Reports Record Q1 2026 Results - Market Newsdesk","og_description":"PR Newswire Tom\u00a0Albanese appointed Chair (in U.S. dollars unless otherwise noted) TORONTO, May 12, 2026 \/PRNewswire\/ &#8211;\u00a0Franco-Nevada realized record financial results in the first quarter of 2026, driven by higher commodity prices, contributions from newly acquired assets, a partial buy-back and a refund from the Canada Revenue Agency. &#8220;The sharp rise in oil prices is expected to positively impact our Q2 revenues, while our royalty and streaming model is largely insulated from the impact of energy prices on cost inflation. Franco-Nevada is unique as a mining equity that benefits from rising oil prices. We look forward to further growth from new assets, additional contributions from\u00a0Cobre Panam\u00e1 and the potential for a full resumption of the mine&#8221;, stated Paul Brink, President &hellip; Continue reading \"Franco-Nevada Reports Record Q1 2026 Results\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/","og_site_name":"Market Newsdesk","article_published_time":"2026-05-12T22:37:48+00:00","og_image":[{"url":"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=TO56955&amp;sd=2026-05-12","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"36 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"Franco-Nevada Reports Record Q1 2026 Results","datePublished":"2026-05-12T22:37:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/"},"wordCount":7275,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/#primaryimage"},"thumbnailUrl":"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=TO56955&amp;sd=2026-05-12","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/","name":"Franco-Nevada Reports Record Q1 2026 Results - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/#primaryimage"},"thumbnailUrl":"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=TO56955&amp;sd=2026-05-12","datePublished":"2026-05-12T22:37:48+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/#primaryimage","url":"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=TO56955&amp;sd=2026-05-12","contentUrl":"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=TO56955&amp;sd=2026-05-12"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/franco-nevada-reports-record-q1-2026-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"Franco-Nevada Reports Record Q1 2026 Results"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/961862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=961862"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/961862\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=961862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=961862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=961862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}