{"id":905538,"date":"2025-11-04T18:43:45","date_gmt":"2025-11-04T23:43:45","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/"},"modified":"2025-11-04T18:43:45","modified_gmt":"2025-11-04T23:43:45","slug":"purple-innovation-reports-third-quarter-2025-results","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/","title":{"rendered":"Purple Innovation Reports Third Quarter 2025 Results"},"content":{"rendered":"<div class=\"xn-newslines\">\n<p class=\"xn-distributor\">PR Newswire<\/p>\n<\/p><\/div>\n<div class=\"xn-content\">\n<p class=\"prntac\">\n        <i>Purple Achieves Improved Net Loss and Positive Adjusted EBITDA, Advancing Its Profitability Turnaround<\/i>\n      <\/p>\n<p class=\"prntac\">\n        <i>Rejuvenate 2.0 Drives Continued Product and Brand Momentum<\/i>\n      <\/p>\n<p class=\"prntac\">\n        <i>Mattress Firm Rollout Remains on Track, Supporting Growth in Premium Segment<\/i>\n      <\/p>\n<p>\n        <span class=\"legendSpanClass\"><br \/>\n          <span class=\"xn-location\">LEHI, Utah<\/span><br \/>\n        <\/span>, <span class=\"legendSpanClass\"><span class=\"xn-chron\">Nov. 4, 2025<\/span><\/span> \/PRNewswire\/ &#8212;\u00a0Purple Innovation, Inc. (NASDAQ: PRPL) (&#8220;Purple&#8221;), a comfort innovation company whose mattresses promise to give you &#8220;less pain, better sleep,&#8221; today announced results for the third quarter ended <span class=\"xn-chron\">September 30, 2025<\/span>.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder1\">\n<p>\n          <a href=\"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.html\" target=\"_blank\" rel=\"nofollow\"><br \/>\n            <img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.jpg\" title=\"Purple (PRNewsfoto\/Purple Innovation, Inc.)\" alt=\"Purple (PRNewsfoto\/Purple Innovation, Inc.)\" \/><br \/>\n          <\/a>\n        <\/p>\n<\/p><\/div>\n<p>&#8220;Our third quarter results reflect the continued progress we&#8217;re making in strengthening Purple&#8217;s foundation and positioning the company for sustainable, profitable growth,&#8221; said <span class=\"xn-person\">Rob DeMartini<\/span>, CEO of Purple Innovation. \u00a0&#8220;We delivered results in line with expectations, achieving an improved net loss and \u00a0positive adjusted EBITDA and a sequential improvement in gross margin despite tariff headwinds.\u00a0 These results highlight the discipline and focus that are driving improved performance across our business.&#8221;<\/p>\n<p>DeMartini continued, &#8220;One year after launching our restructuring program, Purple is a leaner, more agile company that is now firmly focused on scaling for growth. \u00a0The success of Rejuvenate 2.0, the ongoing expansion of our Mattress Firm partnership, and strong showroom performance all underscore the power of our innovation and our brand momentum, marking an important inflection point in sales trends after consecutive quarters of year-over-year declines. \u00a0We are entering the final months of the year with confidence, executing against our Path to Premium Sleep strategy and remaining on track to deliver positive adjusted EBITDA for the full year.&#8221;<\/p>\n<p>\n        <b>Third Quarter 2025 Financial Results<br \/><\/b>Third quarter 2025 net revenue was <span class=\"xn-money\">$118.8 million<\/span>, up slightly compared to <span class=\"xn-money\">$118.6 million<\/span> in the third quarter of 2024, fueled by the timing of Rejuvenate 2.0 shipments and the continued expansion of our Mattress Firm partnership. \u00a0Strength across showroom and wholesale channels was partially offset by softer performance in e-commerce.<\/p>\n<p>Gross profit for the third quarter increased to <span class=\"xn-money\">$50.9 million<\/span> or 42.8% of net revenue, compared to <span class=\"xn-money\">$35.2 million<\/span> or 29.7% in the prior year period. \u00a0Adjusted gross margin, which excludes restructuring and related charges, expanded by 230 basis points to 42.8% in the quarter, compared to 40.5% in the year-prior period. \u00a0With the restructuring now complete, we also benefited as product continues to scale at our <span class=\"xn-location\">Georgia<\/span> facility, and we delivered greater manufacturing efficiencies and direct material cost savings. \u00a0<\/p>\n<p>Third quarter operating expenses were <span class=\"xn-money\">$63.0 million<\/span>, down 23.2% from <span class=\"xn-money\">$82.0 million<\/span> in the prior year quarter. \u00a0The improvement was primarily driven by the comparison to significant restructuring, impairment, and related charges recorded last year, which declined by <span class=\"xn-money\">$13.6 million<\/span>. \u00a0Adjusted operating expenses, which excludes certain restructuring and impairment charges, were <span class=\"xn-money\">$57.7 million<\/span>, down <span class=\"xn-money\">$5.4 million<\/span> from the prior year period.<\/p>\n<p>Net loss attributable to Purple Innovation, Inc. for the third quarter was <span class=\"xn-money\">$11.7 million<\/span>,\u00a0a decline from <span class=\"xn-money\">$39.2 million<\/span> in the prior year.<\/p>\n<p>Adjusted EBITDA for the third quarter was <span class=\"xn-money\">$0.2 million<\/span>, an improvement from <span class=\"xn-money\">$(6.4) million<\/span> last year, driven primarily by our strong gross margin performance and disciplined cost management.<\/p>\n<p>\n        <b>Balance Sheet<br \/><\/b>As of <span class=\"xn-chron\">September 30, 2025<\/span>, the Company had cash and cash equivalents of <span class=\"xn-money\">$32.4 million<\/span> compared to <span class=\"xn-money\">$29.0 million<\/span> as of <span class=\"xn-chron\">December 31, 2024<\/span>.<\/p>\n<p>Net inventories as of <span class=\"xn-chron\">September 30, 2025<\/span>, totaled <span class=\"xn-money\">$65.8 million<\/span>, up 9.8% compared to <span class=\"xn-chron\">September 30, 2024<\/span>, and an increase of 15.7% compared to <span class=\"xn-chron\">December 31, 2024<\/span>.<\/p>\n<p>\n        <b>2025 Outlook<br \/><\/b>The Company is maintaining its 2025 guidance, projecting full-year revenue of <span class=\"xn-money\">$465<\/span> to <span class=\"xn-money\">$485 million<\/span> and adjusted EBITDA of breakeven to <span class=\"xn-money\">$10 million<\/span>, supported by the strong performance of the Rejuvenate 2.0 mattress launch and the successful rollout of the Mattress Firm partnership.<\/p>\n<p>\n        <b>Conference Call and Webcast Information<br \/><\/b>Purple Innovation, Inc. will host a live conference call to discuss financial results today, <span class=\"xn-chron\">November 4, 2025<\/span>, at <span class=\"xn-chron\">4:30 p.m. Eastern Time<\/span>.\u00a0 To access the call dial 800-715-9871 (domestic) or 646-307-1963 (international). The call is also being webcast and can be accessed on the investor relations section of the Company&#8217;s website, <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=en&amp;o=4549550-1&amp;h=3678616809&amp;u=http%3A%2F%2Finvestors.purple.com%2F&amp;a=investors.purple.com\" target=\"_blank\" rel=\"nofollow\">investors.purple.com<\/a>. After the conference call, a webcast replay will remain available on the investor relations section of the Company&#8217;s website for 30 days.<\/p>\n<p>\n        <b>About Purple<br \/><\/b><br \/>\n        <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=en&amp;o=4549550-1&amp;h=2937872772&amp;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D4059981-1%26h%3D2130151504%26u%3Dhttps%253A%252F%252Fc212.net%252Fc%252Flink%252F%253Ft%253D0%2526l%253Den%2526o%253D3894825-1%2526h%253D3832399845%2526u%253Dhttp%25253A%25252F%25252Fpurple.com%25252F%2526a%253DPurple%26a%3DPurple&amp;a=Purple\" target=\"_blank\" rel=\"nofollow\">Purple<\/a> is a premium mattress company and the leader in sleep technology. Their patented GelFlex Grid\u00ae is the only material that instantly relieves pressure for less pain and better sleep.<\/p>\n<p>With over 30 years of innovation, Purple&#8217;s product engineers are paving the way for everyone to experience a proven, deeper sleep by reducing their aches and pains. The GelFlex Grid\u00ae does it all\u2014it instantly adapts as you move, balances temperature, relieves pressure, and offers support in all the right places. Purple products, including mattresses, pillows, cushions, frames, sheets, and more, can be found online at <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=en&amp;o=4549550-1&amp;h=2945128752&amp;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D4059981-1%26h%3D2344742843%26u%3Dhttps%253A%252F%252Fc212.net%252Fc%252Flink%252F%253Ft%253D0%2526l%253Den%2526o%253D3981032-1%2526h%253D1545702092%2526u%253Dhttps%25253A%25252F%25252Fc212.net%25252Fc%25252Flink%25252F%25253Ft%25253D0%252526l%25253Den%252526o%25253D3940387-1%252526h%25253D3728614864%252526u%25253Dhttps%2525253A%2525252F%2525252Fc212.net%2525252Fc%2525252Flink%2525252F%2525253Ft%2525253D0%25252526l%2525253Den%25252526o%2525253D3894825-1%25252526h%2525253D2422361177%25252526u%2525253Dhttp%252525253A%252525252F%252525252Fpurple.com%252525252F%25252526a%2525253DPurple.com%252526a%25253DPurple.com%2526a%253DPurple.com%26a%3DPurple.com&amp;a=Purple.com\" target=\"_blank\" rel=\"nofollow\">Purple.com<\/a>, in 55 Purple stores, and over 3,800 retailers nationwide.<\/p>\n<p>Purple<br \/>Less pain. Better sleep.<\/p>\n<p>\n        <b>Forward Looking Statements<br \/><\/b>Certain statements made in this release that are not historical facts are &#8220;forward looking statements&#8221; within the meaning of the &#8220;safe harbor&#8221; provisions of the United States Private Securities Litigation Reform Act of 1995. Statements based on historical data are not intended and should not be understood to indicate the Company&#8217;s expectations regarding future events. Forward-looking statements provide current expectations or forecasts of future events or determinations. These statements include, but are not limited to, statements regarding our innovation pipeline, the timing of new product collection launches, our ability to improve profitability and optimize our business, the expansion of and benefits to us from our commercial relationship with Mattress Firm, the impact of other commercial relationships, including those with Walmart, Costco, and other traditional and non-traditional partners, revenue-to-date for the third quarter, our ability to drive profitable growth and create shareholder value, and our outlook for revenue and adjusted EBITDA for the full year 2025. \u00a0These forward-looking statements are not guarantees of future performance, conditions or results, and involve a number of known and unknown risks, uncertainties, assumptions and other important factors, many of which are outside the Company&#8217;s control, that could cause actual results or outcomes to differ materially from those discussed in the forward-looking statements. Factors that could influence the realization of forward-looking statements include, among others: changes in economic, financial and end-market conditions in the markets in which we operate; fluctuations in raw material prices and cost of labor; the financial condition of our customers and suppliers; competitive pressures, including the need for technology improvement, successful new product development and introduction; changes in consumer demand, including pullbacks in consumer spending; disruptions to our manufacturing processes; and the risk factors outlined in the &#8220;Risk Factors&#8221; section of our Annual Report on Form 10-K filed with the Securities and Exchange Commission on <span class=\"xn-chron\">March 14, 2025<\/span>, and in our other filings made with the SEC. The Company does not undertake any obligation to update or revise any forward-looking statements, whether as a result of new information, future events or otherwise, except as required by law.<\/p>\n<p>\n        <b>Non-GAAP Financial Measures<br \/><\/b>EBITDA, adjusted operating expenses, adjusted EBITDA, adjusted gross margin, adjusted net income, and adjusted net income per diluted share are non-GAAP financial measures that remove the impact of certain non-cash and non-recurring costs. Management believes that the use of such non-GAAP financial measures provides investors with additional useful information with respect to the impact of various adjustments, which we view as a better measure of our operating performance. Refer to the attached table for the reconciliation of such non-GAAP financial measures to the most comparable GAAP financial measure.<\/p>\n<p>With respect to the Company&#8217;s Adjusted EBITDA outlook for the full year 2025, a quantitative reconciliation to the corresponding GAAP information cannot be provided without unreasonable effort because of the inherent difficulty of accurately forecasting the occurrence and financial impact of the various adjusting items necessary for such reconciliation that have not yet occurred, are out of our control, or cannot be reasonably predicted, including but not limited to warrant liabilities and stock based compensation. For the same reasons, the Company is unable to assess the probable significance of the unavailable information, which could have a material impact on its future GAAP financial results.<\/p>\n<p>\n        <b>Investor Contact:<br \/><\/b><br \/>\n        <span class=\"xn-person\">Stacy Turnof<\/span>, <span class=\"xn-person\">Edelman Smithfield<\/span><br \/><a href=\"mailto:stacy.turnof@edelmansmithfield.com\" target=\"_blank\" rel=\"nofollow\">stacy.turnof@edelmansmithfield.com<\/a><br \/>917-362-2581<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"8\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>PURPLE INNOVATION, INC.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Balance Sheets<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(unaudited \u2013 in thousands, except for par value)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"8\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">September\u00a030,<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">December\u00a031,<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Assets<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Current assets:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">32,358<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">29,011<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Accounts receivable, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">25,210<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">33,057<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Inventories<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">65,770<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">56,863<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Prepaid expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,401<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,023<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Other current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,667<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,414<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">136,406<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">126,368<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Property and equipment, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">79,495<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">93,874<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Operating lease right-of-use assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">70,668<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">75,516<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Intangible assets, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,895<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,890<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other long-term assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,657<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,197<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">302,121<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">307,845<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Liabilities and Stockholders&#8217; Equity<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Current liabilities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Accounts payable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">35,661<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">40,639<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Accrued compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,765<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9,415<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Customer prepayments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,209<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,411<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Accrued rebates and allowances<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,820<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">10,013<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Accrued warranty liabilities \u2013 current portion<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,635<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,114<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Operating lease obligations \u2013 current portion<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16,379<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">15,661<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Other current liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">10,628<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12,750<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total current liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">97,097<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">101,003<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Related party debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">102,889<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">55,394<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Accrued warranty liabilities, net of current portion<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">24,163<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">26,091<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Operating lease obligations, net of current portion<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">80,837<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">87,072<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Warrant liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">22,032<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16,067<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other long-term liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,010<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,009<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">329,028<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">287,636<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Commitments and contingencies (Note 13)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Stockholders&#8217; equity (deficit):<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Class A common stock; $0.0001 par value, 210,000 shares authorized; 108,246 issued and outstanding at September 30, <br \/>2025, and 107,545 issued and outstanding at December 31, 2024<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Class B common stock; $0.0001 par value, 90,000 shares authorized; 163 issued and outstanding at September 30, 2025, <br \/>and at December 31, 2024<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Additional paid-in capital<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">595,118<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">594,053<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Accumulated deficit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(622,068)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(573,866<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total stockholders&#8217; equity (deficit) attributable to Purple Innovation, Inc.<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(26,939)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20,198<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml40\">\n                <span class=\"prnews_span\">Noncontrolling interest<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">32<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total stockholders&#8217; equity (deficit)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(26,907)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20,209<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total liabilities and stockholders&#8217; equity (deficit)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">302,121<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">307,845<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"16\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>PURPLE INNOVATION, INC.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Statements of Operations<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(unaudited \u2013 in thousands, except per share amounts)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"16\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Nine Months Ended<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">September\u00a030,<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen29\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">September\u00a030,<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Revenues, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">118,766<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">118,598<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">328,037<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">358,902<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cost of revenues:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Cost of revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">67,915<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">70,546<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">197,462<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">220,190<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Cost of revenues &#8211; restructuring related charges<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12,859<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">995<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12,859<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total cost of revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">67,915<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">83,405<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">198,457<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">233,049<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Gross profit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">50,851<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">35,193<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">129,580<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">125,853<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Operating expenses:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Marketing and sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">40,120<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">42,939<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,362<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">125,778<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">General and administrative<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">15,200<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">17,266<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">44,678<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">55,111<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Research and development<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,367<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,920<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,997<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">10,572<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Restructuring, impairment and other related charges<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,290<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">18,881<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,387<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">18,881<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total operating expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">62,977<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">82,006<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">170,424<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">210,342<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Operating loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12,126)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(46,813)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(40,844)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(84,489)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other income (expense):<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,203)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,394)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(20,424)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(13,029)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other income, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,742<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,165<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,812<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,612<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Loss on extinguishment of debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,394)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Change in fair value \u2013 warrant liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,892<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,795<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,319<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(111)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total other income (expense), net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">431<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,566<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(7,293)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,922)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss before income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,695)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(39,247)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,137)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,411)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Income tax expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(53)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(63)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(148)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(176)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,748)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(39,310)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,285)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,587)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Net loss attributable to noncontrolling interest<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(28)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(82)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(83)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(169)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss attributable to Purple Innovation, Inc.<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,720)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(39,228)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,202)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,418)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss per share:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Basic<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.11)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.36)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.45)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.84)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Diluted<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.11)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.36)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.45)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.84)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Weighted average common shares outstanding:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Basic<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,245<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,508<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,026<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,008<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Diluted<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,409<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,508<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,191<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,008<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"8\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>PURPLE INNOVATION, INC.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Statements of Cash Flows<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(unaudited \u2013 in thousands)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"8\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Nine Months Ended<br \/>September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash flows from operating activities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,285)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,587)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments to reconcile net loss\u00a0to net cash used in operating activities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">19,659<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">27,448<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Non-cash interest<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9,537<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,303<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Paid-in-kind interest<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,266<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,028<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Non-cash restructuring, impairment and other related charges<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,775<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20,115<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Loss on extinguishment of debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,394<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Loss on disposal of property and equipment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">318<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">770<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Change in fair value \u2013 warrant liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,319)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">111<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Stock-based compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,265<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,108<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Changes in operating assets and liabilities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accounts receivable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,847<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,140<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Inventories<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,907)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,971<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Prepaid expenses and other assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">755<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">378<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Operating leases, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2,080)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2,105)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accounts payable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,464)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(16,558)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accrued compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1,650)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">10,045<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Customer prepayments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1,202)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1,940)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accrued rebates and allowances<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">307<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,203)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accrued warranty liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(407)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(621)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other accrued liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,445)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,592<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash used in operating activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(28,030)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(24,611)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash flows from investing activities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Sale of property and equipment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">464<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Purchase of property and equipment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,076)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,160)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Investment in intangible assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(454)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(221)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash used in investing activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,066)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,381)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash flows from financing activities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Proceeds from related party loan<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">39,000<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">61,000<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Payments on term loan<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(25,000)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Payments on revolving line of credit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5,000)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Payments for debt issuance costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1,557)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,466)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash provided by financing activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">37,443<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">27,534<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net increase (decrease) in cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,347<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,458)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash and cash equivalents, beginning of the year<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">29,011<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">26,857<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash and cash equivalents, end of the period<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">32,358<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">23,399<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\n        <b>PURPLE INNOVATION, INC.<br \/><\/b><br \/>\n        <b>RECONCILIATION OF GAAP TO NON-GAAP MEASURES<br \/><\/b><br \/>\n        <b>(In thousands)<\/b>\n      <\/p>\n<p>Management believes that the use of the following non-GAAP financial measures provides investors with additional useful information with respect to the impact of various adjustments, which we view as a better measure of our operating performance. These non-GAAP financial measures are EBITDA, adjusted EBITDA, adjusted operating expenses, adjusted net loss and adjusted net loss per diluted share. Other companies may calculate these non-GAAP measures differently than we do. These non-GAAP measures have limitations as analytical tools, and you should not consider them in isolation or as a substitute for our financial results prepared in accordance with GAAP.<\/p>\n<p>\n        <b>Reconciliation of GAAP Net Income (Loss) to Non-GAAP EBITDA and Adjusted EBITDA<\/b>\n      <\/p>\n<p>A reconciliation of GAAP net income (loss) to the non-GAAP measures of EBITDA and adjusted EBITDA is provided below. EBITDA represents net income (loss) before interest expense, income tax expense, other income, net, and depreciation and amortization. Adjusted EBITDA represents EBITDA excluding costs incurred due to changes in the fair value of the warrant liability, debt extinguishment, stock-based compensation expense, restructuring related expenses, loss on project write-off, nonrecurring and debt issuance legal fees, Board special committee costs, executive interim and search costs, severance cost, showroom opening and closing costs and non-operating facility expense. We believe EBITDA and Adjusted EBITDA provide additional useful information with respect to the impact of various adjustments and provide meaningful measures of our operating performance.<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months Ended<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Nine Months Ended<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">GAAP net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,748)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(39,310)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,285)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,587)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,203<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,394<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20,424<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,029<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">53<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">63<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">148<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">176<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other income, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1,742)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(7,165)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1,812)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,612)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9,777<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">14,627<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">19,658<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">27,448<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,543<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(27,391)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(9,867)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(60,546)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Change in fair value &#8211; warrant liability<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,893)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,795)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,320)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">111<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Loss on extinguishment of debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">795<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,394<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Stock-based compensation expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">420<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">791<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,265<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,108<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Restructuring related charges<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">65<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">23,669<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,850<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">23,669<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Loss on project write-off<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,355<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Non-recurring and debt issuance legal fees<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">310<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">655<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">940<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Strategic alternative costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">698<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,958<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Executive interim and search costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">409<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,383<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Severance costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">82<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">202<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,652<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,086<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Showroom opening and closing costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">724<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">147<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">782<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Non-operating facility expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">964<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">964<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">189<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,375)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,901)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(23,718)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Reconciliation of GAAP Gross Profit to Adjusted Gross Profit <\/b>\n      <\/p>\n<p>A reconciliation of GAAP gross profit to the non-GAAP measures of adjusted gross profit is provided below. Adjusted gross profit represents net revenue less adjusted cost of revenues. Adjusted cost of revenues represents cost of revenues excluding restructuring charges recorded in cost of revenues.\u00a0We believe adjusted gross margin provides additional useful information with respect to the impact of the restructuring and provides meaningful measures of our operating performance.<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen16\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months Ended <br \/>September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0Nine Months Ended <br \/>September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Revenues, net <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">118,766<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">118,598<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">328,037<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">358,902<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen20\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total cost of revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">67,915<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">83,405<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">198,457<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">233,049<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Restructuring charges in cost of revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12,859)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(995)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12,859)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted cost of revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">67,915<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">70,546<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">197,462<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">220,190<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen20\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted gross profit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">50,851<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">48,052<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">130,575<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">138,712<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted gross profit %<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">42.8\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">40.5\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">39.8\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">38.6\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Reconciliation of GAAP Operating Expenses to non-GAAP Adjusted Operating Expenses <\/b>\n      <\/p>\n<p>Our presentation of adjusted operating expenses assumes adjustments for certain nonrecurring items that we do not believe directly reflects our current core operations. Adjusted operating expenses is a supplemental measure of operating performance that does not represent, and should not be considered, alternatives to net loss and earnings per share, as calculated in accordance with GAAP. We believe adjusted operating expenses supplements GAAP measures and enables us to more effectively evaluate our performance period-over-period. A reconciliation of operating expenses, the most directly comparable GAAP measure, to adjusted operating expenses is set forth below:<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen16\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands, except per share amounts)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months Ended <br \/>September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0Nine Months Ended <br \/>September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total operating expenses <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">62,977<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">82,006<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">170,424<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">210,342<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Restructuring, impairment and other related charges<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5,290)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(18,881)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,387)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(18,881)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted operating expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">57,687<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">63,125<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">159,037<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">191,461<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Reconciliation of GAAP Net Loss to non-GAAP Adjusted Net Loss and Adjusted Net Loss per Diluted Share <\/b>\n      <\/p>\n<p>Our presentation of adjusted net loss assumes that all net loss is attributable to Purple Innovation, Inc. (i.e. there is no allocation of net loss to noncontrolling interests), which assumes the full exchange at the beginning of the period of all outstanding Paired Securities for shares of Class A common stock of Purple Innovation, Inc., adjusted for certain nonrecurring items that we do not believe directly reflect our core operations. Adjusted net loss per share, diluted, is calculated by dividing adjusted net loss by the total shares of Class A common stock outstanding plus any dilutive warrants, options and restricted stock as calculated in accordance with GAAP and assuming the full exchange of all outstanding Paired Securities as of the beginning of each period presented. Adjusted net loss and adjusted net loss per diluted share, are supplemental measures of operating performance that do not represent, and should not be considered, alternatives to net loss and earnings per share, as calculated in accordance with GAAP. We believe adjusted net loss and adjusted net loss per diluted share, supplement GAAP measures and enable us to more effectively evaluate our performance period-over-period. A reconciliation of net loss, the most directly comparable GAAP measure, to adjusted net loss and the computation of adjusted net loss per diluted share, are set forth below:<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen16\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands, except per share amounts)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months<br \/>Ended September<br \/>30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0Nine Months<br \/>Ended September 30,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,748)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(39,310)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,285)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,587)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax (benefit) expense, as reported<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">53<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">63<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">148<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">176<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Revenue reduction due to SGI Contract<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">941<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,568<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Change in fair value \u2013 warrant liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,892)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,795)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,319)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">111<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Loss on extinguishment of debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,394<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Restructuring related charges<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,290<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">32,682<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12,382<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">32,682<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Gain on insurance proceeds<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(7,301)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,601)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Board special committee fees<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">698<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,958<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net loss before income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,658)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(18,661)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(43,548)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(64,825)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted income tax benefit<sup>(1)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,026<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,833<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,279<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16,790<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,632)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(13,828)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(32,269)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,035)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net loss per share, diluted<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.08)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.13)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.30)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.45)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted weighted-average shares outstanding, diluted<sup>(2)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,409<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,703<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,191<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,203<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1) Represents the estimated effective tax rate of 25.9% for the three and nine months ended September 30, 2025 and 2024, applied to adjusted net income before income taxes. The estimated effective tax rates are what the Company would be subject to and consist of the combined federal statutory tax rate and the Company&#8217;s blended state tax rates.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2) Assumes options and restricted stock units calculated in accordance with GAAP and the full exchange of all outstanding Paired Securities for shares of Class A common stock as of the beginning of the period.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>A reconciliation of net income (loss) per share, diluted, to adjusted net loss per diluted share is set forth below for the three and nine months ended <span class=\"xn-chron\">September 30, 2025<\/span> and 2024:<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"22\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>For the Three Months Ended<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"10\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>September 30, 2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"10\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>September 30, 2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Loss<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Weighted <br \/>Average<br \/>\u00a0Shares,<br \/>\u00a0Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Income<br \/>per Share, <br \/>Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Loss<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Weighted <br \/>Average <br \/>Shares,<br \/>Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Income<br \/>per Share,<br \/>Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss attributable to Purple Innovation Inc.<sup>(1)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,720)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,409<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.11)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(39,228)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,508<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.36)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0Assumed exchange of shares<sup>(2)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(28)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(82)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">195<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0Net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,748)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(39,310)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments to arrive at adjusted loss before taxes<sup>(3)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen25\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">90<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen25\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20,649<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted loss before taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,658)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(18,661)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted income tax benefit<sup>(4)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,026<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,833<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,632)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,409<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.08)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(13,828)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,703<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.13)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1) Represents net loss attributable to Purple Innovation, Inc. and the associated weighted average diluted shares, of Class A common stock outstanding. For the three months ended September 30, 2025, the Paired Securities are included in the beginning weighted average shares, diluted.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2) Assumes the full exchange of all outstanding Paired Securities for shares of Class A common stock as of the beginning of the period if not already included in weighted average diluted shares in footnote (1) above. Also assumes the addition of net income attributable to noncontrolling interests corresponding with the assumed exchange of the Paired Securities for shares of Class A common stock.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3) Represents the total impact of all adjustments identified in the adjusted net income table above to arrive at adjusted income before income taxes. Also assumes the dilutive warrants, options and restricted stock as calculated in accordance with GAAP.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4) Represents the estimated effective tax rate of 25.9% for the three months ended September 30, 2025 and 2024, applied to adjusted net income before income taxes. The estimated effective tax rates are what the Company would be subject to and consist of the combined federal statutory tax rate and the Company&#8217;s blended state tax rates assuming no valuation allowance.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"22\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>For the Nine Months Ended<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"10\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>September 30, 2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"10\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>September 30, 2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Weighted <br \/>Average<br \/>\u00a0Shares,<br \/>\u00a0Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Income <br \/>per Share,<br \/>Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Weighted <br \/>Average <br \/>Shares,<br \/>Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Income <br \/>per Share,<br \/>Diluted<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net loss attributable to Purple Innovation Inc.<sup>(1)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,202)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,191<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.45)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,418)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,008<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.84)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0Assumed exchange of shares<sup>(2)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(83)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(169)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">195<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0Net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,285)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(89,587)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments to arrive at adjusted loss before taxes<sup>(3)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen25\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,737<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen25\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">24,762<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted loss before taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(43,548)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(64,825)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted income tax benefit<sup>(4)<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,279<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16,790<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(32,269)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">108,191<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.30)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(48,035)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">107,203<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.45)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1) Represents net loss attributable to Purple Innovation, Inc. and the associated weighted average diluted shares, of Class A common stock outstanding. For the nine months ended September 30, 2025, the Paired Securities are included in the beginning weighted average shares, diluted.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2) Assumes the full exchange of all outstanding Paired Securities for shares of Class A common stock as of the beginning of the period if not already included in weighted average diluted shares in footnote (1) above. Also assumes the addition of net income attributable to noncontrolling interests corresponding with the assumed exchange of the Paired Securities for shares of Class A common stock.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3) Represents the total impact of all adjustments identified in the adjusted net income table above to arrive at adjusted income before income taxes. Also assumes the dilutive warrants, options and restricted stock as calculated in accordance with GAAP.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4) Represents the estimated effective tax rate of 25.9% for the nine months ended September 30, 2025 and 2024, applied to adjusted net income before income taxes. The estimated effective tax rates are what the Company would be subject to and consist of the combined federal statutory tax rate and the Company&#8217;s blended state tax rates assuming no valuation allowance.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<p id=\"PURL\">\n        <img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=LA15423&amp;sd=2025-11-04\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/news-releases\/purple-innovation-reports-third-quarter-2025-results-302604624.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/news-releases\/purple-innovation-reports-third-quarter-2025-results-302604624.html<\/a><\/p>\n<p>SOURCE  Purple Innovation, LLC<\/p>\n<\/p><\/div>\n<p>    <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=LA15423&amp;Transmission_Id=202511041605PR_NEWS_USPR_____LA15423&amp;DateId=20251104\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PR Newswire Purple Achieves Improved Net Loss and Positive Adjusted EBITDA, Advancing Its Profitability Turnaround Rejuvenate 2.0 Drives Continued Product and Brand Momentum Mattress Firm Rollout Remains on Track, Supporting Growth in Premium Segment LEHI, Utah , Nov. 4, 2025 \/PRNewswire\/ &#8212;\u00a0Purple Innovation, Inc. (NASDAQ: PRPL) (&#8220;Purple&#8221;), a comfort innovation company whose mattresses promise to give you &#8220;less pain, better sleep,&#8221; today announced results for the third quarter ended September 30, 2025. &#8220;Our third quarter results reflect the continued progress we&#8217;re making in strengthening Purple&#8217;s foundation and positioning the company for sustainable, profitable growth,&#8221; said Rob DeMartini, CEO of Purple Innovation. \u00a0&#8220;We delivered results in line with expectations, achieving an improved net loss and \u00a0positive adjusted EBITDA and a sequential &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Purple Innovation Reports Third Quarter 2025 Results&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-905538","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Purple Innovation Reports Third Quarter 2025 Results - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Purple Innovation Reports Third Quarter 2025 Results - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"PR Newswire Purple Achieves Improved Net Loss and Positive Adjusted EBITDA, Advancing Its Profitability Turnaround Rejuvenate 2.0 Drives Continued Product and Brand Momentum Mattress Firm Rollout Remains on Track, Supporting Growth in Premium Segment LEHI, Utah , Nov. 4, 2025 \/PRNewswire\/ &#8212;\u00a0Purple Innovation, Inc. (NASDAQ: PRPL) (&#8220;Purple&#8221;), a comfort innovation company whose mattresses promise to give you &#8220;less pain, better sleep,&#8221; today announced results for the third quarter ended September 30, 2025. &#8220;Our third quarter results reflect the continued progress we&#8217;re making in strengthening Purple&#8217;s foundation and positioning the company for sustainable, profitable growth,&#8221; said Rob DeMartini, CEO of Purple Innovation. \u00a0&#8220;We delivered results in line with expectations, achieving an improved net loss and \u00a0positive adjusted EBITDA and a sequential &hellip; Continue reading &quot;Purple Innovation Reports Third Quarter 2025 Results&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-04T23:43:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.jpg\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"Purple Innovation Reports Third Quarter 2025 Results\",\"datePublished\":\"2025-11-04T23:43:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/\"},\"wordCount\":3271,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/639182\\\/Purple_mattress_logo.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/\",\"name\":\"Purple Innovation Reports Third Quarter 2025 Results - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/639182\\\/Purple_mattress_logo.jpg\",\"datePublished\":\"2025-11-04T23:43:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/639182\\\/Purple_mattress_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/639182\\\/Purple_mattress_logo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/purple-innovation-reports-third-quarter-2025-results\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Purple Innovation Reports Third Quarter 2025 Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Purple Innovation Reports Third Quarter 2025 Results - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/","og_locale":"en_US","og_type":"article","og_title":"Purple Innovation Reports Third Quarter 2025 Results - Market Newsdesk","og_description":"PR Newswire Purple Achieves Improved Net Loss and Positive Adjusted EBITDA, Advancing Its Profitability Turnaround Rejuvenate 2.0 Drives Continued Product and Brand Momentum Mattress Firm Rollout Remains on Track, Supporting Growth in Premium Segment LEHI, Utah , Nov. 4, 2025 \/PRNewswire\/ &#8212;\u00a0Purple Innovation, Inc. (NASDAQ: PRPL) (&#8220;Purple&#8221;), a comfort innovation company whose mattresses promise to give you &#8220;less pain, better sleep,&#8221; today announced results for the third quarter ended September 30, 2025. &#8220;Our third quarter results reflect the continued progress we&#8217;re making in strengthening Purple&#8217;s foundation and positioning the company for sustainable, profitable growth,&#8221; said Rob DeMartini, CEO of Purple Innovation. \u00a0&#8220;We delivered results in line with expectations, achieving an improved net loss and \u00a0positive adjusted EBITDA and a sequential &hellip; Continue reading \"Purple Innovation Reports Third Quarter 2025 Results\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/","og_site_name":"Market Newsdesk","article_published_time":"2025-11-04T23:43:45+00:00","og_image":[{"url":"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.jpg","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"Purple Innovation Reports Third Quarter 2025 Results","datePublished":"2025-11-04T23:43:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/"},"wordCount":3271,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/","name":"Purple Innovation Reports Third Quarter 2025 Results - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.jpg","datePublished":"2025-11-04T23:43:45+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/#primaryimage","url":"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.jpg","contentUrl":"https:\/\/mma.prnewswire.com\/media\/639182\/Purple_mattress_logo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/purple-innovation-reports-third-quarter-2025-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"Purple Innovation Reports Third Quarter 2025 Results"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/905538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=905538"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/905538\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=905538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=905538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=905538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}