{"id":847592,"date":"2025-05-06T16:23:41","date_gmt":"2025-05-06T20:23:41","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/"},"modified":"2025-05-06T16:23:41","modified_gmt":"2025-05-06T20:23:41","slug":"the-andersons-inc-reports-first-quarter-results-2","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/","title":{"rendered":"The Andersons, Inc. Reports First Quarter Results"},"content":{"rendered":"<div class=\"xn-newslines\">\n<p class=\"xn-distributor\">PR Newswire<\/p>\n<\/p><\/div>\n<div class=\"xn-content\">\n<p>\n        <span class=\"legendSpanClass\"><br \/>\n          <span class=\"xn-location\">MAUMEE, Ohio<\/span><br \/>\n        <\/span>, <span class=\"legendSpanClass\"><span class=\"xn-chron\">May 6, 2025<\/span><\/span> \/PRNewswire\/ &#8212; The Andersons, Inc. (Nasdaq: ANDE) announces financial results for the first quarter ended March\u00a031, 2025.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder1\">\n<p>\n          <a href=\"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.html\" target=\"_blank\" rel=\"nofollow\"><br \/>\n            <img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.jpg\" title=\"The Andersons, Inc. logo. (PRNewsFoto\/The Andersons, Inc.)\" alt=\"The Andersons, Inc. logo. (PRNewsFoto\/The Andersons, Inc.)\" \/><br \/>\n          <\/a>\n        <\/p>\n<\/p><\/div>\n<p>\n        <b>First Quarter Highlights:<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>\n          <b>Company reported net income attributable to The Andersons of <span class=\"xn-money\">$0.3 million<\/span>, or <span class=\"xn-money\">$0.01<\/span> per diluted share and adjusted net income of <span class=\"xn-money\">$4 million<\/span>, or <span class=\"xn-money\">$0.12<\/span> per diluted share<\/b>\n        <\/li>\n<li>\n          <b>Adjusted EBITDA was <span class=\"xn-money\">$57 million<\/span><\/b>\n        <\/li>\n<li>\n          <b>Renewables reported pretax income of <span class=\"xn-money\">$25 million<\/span> and pretax income attributable to The Andersons of <span class=\"xn-money\">$15 million<\/span> on strong operating performance and solid merchandising<\/b>\n        <\/li>\n<li>\n          <b>Agribusiness recorded a pretax loss of <span class=\"xn-money\">$10 million<\/span> and breakeven adjusted pretax income attributable to The Andersons on stagnant market conditions<\/b>\n        <\/li>\n<\/ul>\n<p>&#8220;We had mixed results in a turbulent first quarter. The Renewables segment performed well and our ethanol plants had strong operating efficiency and financial results. Coupled with the performance of our ethanol and renewable diesel feedstock merchandising, the segment produced one of its best first quarters. In Agribusiness, we faced challenging markets as global trade uncertainties disrupted typical grain flows and caused many of our commercial customers to focus on just-in-time purchasing. Our agronomy team is off to a good start with product well-positioned for the upcoming planting season,&#8221; said President and CEO <span class=\"xn-person\">Bill Krueger<\/span>. &#8220;As planting progresses, we see ample second quarter opportunities for our agronomy teams with the expected increase in corn acres this year. Strong system-wide corn and wheat production should provide a good environment for storage and handling in our assets later in the year. We also expect continued demand for our ethanol products, both domestic and export, as we enter the spring maintenance and driving season. We remain pleased with our overall asset and merchandising footprint. With the combination of the former Trade and Nutrient businesses, we are reviewing the portfolio to find synergies and process improvements.&#8221;<\/p>\n<p>&#8220;We continue to pursue growth opportunities. Our longer lead time capital projects in Agribusiness are progressing well and are expected to be completed by mid-2026,&#8221; continued Krueger. &#8220;Our Renewables projects are focused on improving efficiency, co-product yields and lowering the carbon intensity of our high-performing ethanol plants.&#8221;<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$ in millions, except per share amounts\u00a0\u00a0\u00a0\u00a0\u00a0 <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prnpr4 prnpl2 prnvab prntar prncbts prnrbrb1 prnbbbs prnbsbls\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Q1 2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Q1 2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prnpr2 prnpl2 prnvab prnsbtb1 prnbrbrs prnbbbs prnbsbls\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Variance<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Pretax Income<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 14.0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (10.8)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Pretax Income (Loss) Attributable to the Company<span class=\"prnews_span\"><sup>1<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(1.8)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8.7)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Pretax Income (Loss) Attributable to the Company<span class=\"prnews_span\"><sup>1<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3.2<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3.4)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0\u00a0\u00a0\u00a0 Agribusiness<span class=\"prnews_span\"><sup>1<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(0.1)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5.5)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0\u00a0\u00a0\u00a0 Renewables<span class=\"prnews_span\"><sup>1<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>15.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">14.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0\u00a0\u00a0\u00a0 Other<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(12.0)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12.9)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net Income Attributable to the Company<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>0.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5.3)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Net Income Attributable to the Company<span class=\"prnews_span\"><sup>1<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4.1<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1.5)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Diluted Earnings Per Share (&#8220;EPS&#8221;)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>0.01<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.16<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.15)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted EPS<span class=\"prnews_span\"><sup>1<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>0.12<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.16<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.04)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>EBITDA<span class=\"prnews_span\"><sup>1<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>50.6<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">51.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.8)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted EBITDA<span class=\"prnews_span\"><sup>1 <\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 57.3<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 51.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 6.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"4\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>1<\/sup> Non-GAAP financial measures; see appendix for explanations and reconciliations.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Cash, Liquidity, and Long-Term Debt Management<\/b>\n      <\/p>\n<p>&#8220;Our businesses continue to generate strong cash flows, although working capital needs in the first quarter typically require significant funding leading to a use of cash from operations. However, our debt remains at a modest level,&#8221; said Executive Vice President and CFO <span class=\"xn-person\">Brian Valentine<\/span>. &#8220;We remain well below our long-term debt to EBITDA target of less than 2.5 times and are pleased with the strength of our balance sheet. For 2025, we anticipate increased spending on growth projects for previously announced long-term opportunities.&#8221;<\/p>\n<p>The company used cash from operating activities of <span class=\"xn-money\">$350 million<\/span> and <span class=\"xn-money\">$240 million<\/span> in the first quarter of 2025 and 2024, respectively. Cash from operations before working capital changes in the same periods was <span class=\"xn-money\">$57 million<\/span> and <span class=\"xn-money\">$48 million<\/span>, respectively. Cash spent on capital projects in the quarter totaled <span class=\"xn-money\">$47 million<\/span>, a <span class=\"xn-money\">$20<\/span> million\u00a0increase from 2024.\u00a0<\/p>\n<p>\n        <b><br \/>\n          <u>First Quarter Segment Overview<\/u><br \/>\n        <\/b>\n      <\/p>\n<p>\n        <b>Agribusiness Challenged in Changing Markets<\/b>\n      <\/p>\n<p>Agribusiness recorded a pretax loss of <span class=\"xn-money\">$10 million<\/span> and breakeven adjusted pretax income attributable to the company for the quarter compared to pretax income of <span class=\"xn-money\">$3<\/span> million\u00a0and adjusted pretax income of <span class=\"xn-money\">$5 million<\/span> in the first quarter of 2024.<\/p>\n<p>Results from our ag supply chain businesses were lower with limited trade flows due to market uncertainty. Assets were significantly impacted as basis levels were challenged in our western locations, including those recently acquired as part of the Skyland Grain, LLC investment. The nutrient business showed year-over-year improvement with good fertilizer volume and positioning in advance of an expected increase in corn acres.<\/p>\n<p>The portfolio mix of assets, ingredients, and merchandising businesses provides a solid foundation to navigate challenging market conditions. Sizeable corn planting intentions are favorable, allowing for higher nutrient volumes as well as providing opportunities for storage and handling at harvest. In addition, lower corn stocks entering the year should allow for merchandising opportunities and good early harvest margins in the last half of 2025.\u00a0<\/p>\n<p>Agribusiness&#8217;s first\u00a0quarter adjusted EBITDA was <span class=\"xn-money\">$31 million<\/span>, compared to <span class=\"xn-money\">$29 million<\/span> in 2024.<\/p>\n<p>\n        <b>Renewables has Strong Quarter on Efficient Operations and Favorable Ethanol Margins<\/b>\n      <\/p>\n<p>The Renewables segment reported pretax income of <span class=\"xn-money\">$25 million<\/span> and pretax income attributable to the company of <span class=\"xn-money\">$15 million<\/span> in the first quarter. For the same period in 2024, the segment reported pretax income of <span class=\"xn-money\">$24 million<\/span> and adjusted pretax income attributable to the company of <span class=\"xn-money\">$14 million<\/span>.<\/p>\n<p>Results from the ethanol production facilities improved year-over-year on efficient operations and higher yields, also benefiting from better year-over-year board crush margins. Plant co-product values were lower, with corn-based feed ingredients competing against an oversupply of alternative protein sources. Ethanol demand is expected to strengthen into the summer with some concerns about cost of inputs. Values of feed ingredient co-products are expected to remain challenged.<\/p>\n<p>Renewables had first quarter EBITDA of <span class=\"xn-money\">$37 million<\/span> in 2025, compared to adjusted EBITDA of <span class=\"xn-money\">$34 million<\/span> in 2024.<\/p>\n<p>\n        <b>Income Taxes<\/b>\n      <\/p>\n<p>The company recorded an income tax benefit for the quarter of <span class=\"xn-money\">$2.1 million<\/span>, resulting in an effective rate of (66)% for the period. This rate was impacted by a discrete adjustment for a decrease in unrecognized tax benefits related to prior period tax positions. We anticipate a full-year adjusted effective rate of approximately 18% &#8211; 22%.<\/p>\n<p>\n        <b>Conference Call<\/b>\n      <\/p>\n<p>The company will host a webcast on <span class=\"xn-chron\">Wednesday, May 7, 2025<\/span>, at <span class=\"xn-chron\">8:30 a.m. ET<\/span>, to discuss its performance and provide its outlook for the remainder of 2025. To access the call, please dial 888-317-6003 or 412-317-6061 (elite entry number is 2480571). It is recommended that you call 10 minutes before the conference call begins.<\/p>\n<p>To access the webcast, click on the link: <u><a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=4421119-1&amp;h=606621145&amp;u=https%3A%2F%2Fapp.webinar.net%2FXQ59rnDKz3D&amp;a=https%3A%2F%2Fapp.webinar.net%2FXQ59rnDKz3D\" target=\"_blank\" rel=\"nofollow\">https:\/\/app.webinar.net\/XQ59rnDKz3D<\/a><\/u>\u00a0and submit the requested information as directed. A replay of the call can also be accessed under the heading &#8220;Investors&#8221; on the company&#8217;s website at <u><a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=4421119-1&amp;h=3703798933&amp;u=https%3A%2F%2Fwww.andersonsinc.com%2F&amp;a=www.andersonsinc.com\" target=\"_blank\" rel=\"nofollow\">www.andersonsinc.com<\/a><\/u>.\u00a0<\/p>\n<p>\n        <b>Forward-Looking Statements <\/b>\n      <\/p>\n<p>This release contains forward-looking statements. These statements involve risks and uncertainties that could cause actual results to differ materially. Without limitation, these risks include economic, weather and regulatory conditions, competition, geopolitical risk, and the risk factors set forth from time to time in the company&#8217;s filings with the Securities and Exchange Commission. Although the company believes that the assumptions upon which the financial information and its forward-looking statements are based are reasonable, it can give no assurance that these assumptions will prove to be correct.<\/p>\n<p>\n        <b>Non-GAAP Measures<\/b>\n      <\/p>\n<p>This release contains non-GAAP financial measures. The company believes that pretax income (loss) attributable to the company; adjusted pretax income (loss) attributable to the company; adjusted pretax income (loss); adjusted net income attributable to the company; adjusted diluted earnings per share; earnings before interest, taxes, depreciation, and amortization (or EBITDA); adjusted EBITDA; and cash from operations before working capital changes provide additional information to investors and others about its operations, allowing an evaluation of underlying operating performance and liquidity and better period-to-period comparability. The above measures are not and should not be considered as alternatives to pretax income (loss) or income (loss) before income taxes, net income (loss), diluted earnings (loss) per share attributable to The Andersons, Inc. common shareholders and cash provided by (used in) operating activities as determined by generally accepted accounting principles. Reconciliations of the GAAP to non-GAAP measures may be found within this press release and the financial tables provided herein.<\/p>\n<p>\n        <b>Company Description<\/b>\n      <\/p>\n<p>The Andersons, Inc., is a diversified company rooted in agriculture that conducts business in the agribusiness and renewables sectors. Guided by its Statement of Principles, The Andersons is committed to providing extraordinary service to its customers, helping its employees improve, supporting its communities, and increasing the value of the company. For more information, please visit <u><a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=4421119-1&amp;h=3703798933&amp;u=https%3A%2F%2Fwww.andersonsinc.com%2F&amp;a=www.andersonsinc.com\" target=\"_blank\" rel=\"nofollow\">www.andersonsinc.com<\/a><\/u>.<\/p>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen11\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Statements of Operations<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended <br \/>March 31,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands, except per share data)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen16\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Sales and merchandising revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0 2,659,098<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0 2,718,217<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cost of sales and merchandising revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,506,226<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,589,897<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Gross profit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>152,872<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">128,320<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Operating, administrative and general expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>145,754<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">119,358<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Interest expense, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>13,096<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,522<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other income, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>9,191<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,528<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income before income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3,213<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,968<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax (benefit) provision<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(2,118)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,303<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5,331<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12,665<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Net income attributable to noncontrolling interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5,047<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,084<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income attributable to The Andersons, Inc.<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 284<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,581<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Earnings per share attributable to The Andersons, Inc. common shareholders:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Basic earnings:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.01<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.16<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Diluted earnings:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.01<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.16<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen11\" colspan=\"6\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Balance Sheets<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<p class=\"prnml4\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March 31, 2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>December 31, 2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March 31, 2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Assets<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Current assets:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 219,219<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 561,771<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 283,902<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Accounts receivable, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>812,482<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">764,550<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">701,706<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Inventories<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,249,047<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,286,811<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">994,543<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Commodity derivative assets \u2013 current<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>155,028<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">148,801<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">178,623<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Other current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>92,968<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">88,344<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">55,134<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,528,744<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,850,277<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,213,908<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Property, plant and equipment, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>860,246<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">868,151<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">689,113<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other assets, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>408,692<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">402,886<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">358,052<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen20\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3,797,682<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen20\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4,121,314<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen20\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3,261,073<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Liabilities and equity<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Current liabilities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Short-term debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 222,691<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 166,614<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 10,148<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Trade and other payables<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>661,202<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,047,436<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">625,836<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Customer prepayments and deferred revenue<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>223,702<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">194,025<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">174,651<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Commodity derivative liabilities \u2013 current<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>69,648<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">59,766<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">67,079<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Current maturities of long-term debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>62,675<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">36,139<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">27,617<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0 Accrued expenses and other current liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>194,390<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">227,192<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">177,953<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total current liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,434,308<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,731,172<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,083,284<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Long-term debt, less current maturities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>588,087<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">608,151<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">556,174<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other long-term liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>180,853<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">182,155<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">145,965<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,203,248<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,521,478<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,785,423<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total equity <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,594,434<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,599,836<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,475,650<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total liabilities and equity<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3,797,682<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4,121,314<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3,261,073<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen11\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Statements of Cash Flows<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended March 31,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0(in thousands)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen16\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Operating Activities<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,331<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 12,665<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments to reconcile net income to cash used in operating activities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>34,340<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">30,949<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>17,303<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,795<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Changes in operating assets and liabilities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Accounts receivable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(53,268)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">57,725<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Inventories<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>38,531<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">169,083<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Commodity derivatives<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,076<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(28,498)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Other current and non-current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(8,558)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,923<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Payables and other current and non-current liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(384,775)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(488,269)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash used in operating activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(350,020)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(239,627)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Investing Activities<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Purchases of property, plant and equipment and capitalized software<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(46,548)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(26,775)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,717<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,723<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash used in investing activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(43,831)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(22,052)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Financing Activities<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net proceeds (payments) under short-term lines of credit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>56,044<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(31,913)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Proceeds from issuance of long-term debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>14,700<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Payments of long-term debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(8,416)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,870)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Dividends paid<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(6,693)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,516)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Value of shares withheld for taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(3,837)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,071)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Distributions to noncontrolling interest owner<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(44,910)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(1,353)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash provided by (used in) financing activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>50,445<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(98,280)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Effect of exchange rates on cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>854<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Decrease in cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(342,552)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(359,952)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash and cash equivalents at beginning of period<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>561,771<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">643,854<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash and cash equivalents at end of period<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 219,219<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 283,902<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen11\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The\u00a0Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Net Income Attributable to The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>A non-GAAP financial measure<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended <br \/>March 31,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands, except per share data)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen16\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,331<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 12,665<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Net income attributable to noncontrolling interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5,047<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,084<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income attributable to The Andersons, Inc.<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>284<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,581<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjustments:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Transaction related compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,103<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,852<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Insured inventory and property damage<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,926<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Gain on deconsolidation of joint venture<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,117)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Income tax impact of adjustments<sup>1<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(1,257)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">279<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total adjusting items, net of tax<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3,772<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">14<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net income attributable to The Andersons, Inc. <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4,056<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,595<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Diluted earnings per share attributable to <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">The Andersons, Inc. common shareholders<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.01<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.16<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Impact on diluted earnings per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.11<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted diluted earnings per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.12<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0.16<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>1<\/sup> The income tax impact of adjustments is taken at the blended federal, state, and local tax rate of 25% with the exception of certain transaction related compensation in 2024.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net income (loss) attributable to The Andersons, Inc. reflects reported net income (loss) available to The Andersons, Inc. common shareholders after the removal of specified items described above. Adjusted diluted earnings (loss) per share reflects the fully diluted EPS of The Andersons, Inc. after removal of the effect on EPS as reported of specified items described above. Management believes that Adjusted net income (loss) attributable to The Andersons, Inc. and Adjusted diluted earnings (loss) per share are useful measures of The Andersons, Inc. performance as they provide investors additional information about the operations of the company allowing better evaluation of underlying business performance and better comparability to previous periods. These non-GAAP financial measures are not intended to replace or be alternatives to Net income attributable to The Andersons, Inc. and Diluted earnings per share attributable to The Andersons, Inc. common shareholders as reported, the most directly comparable GAAP financial measures, or any other measures of operating results under GAAP. Earnings amounts described above have been divided by the company&#8217;s average number of diluted shares outstanding for each respective period in order to arrive at an adjusted diluted earnings (loss) per share amount for each specified item.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"8\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Segment Data<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Agribusiness<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Renewables<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Other<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Total<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended March 31, 2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Sales and merchandising revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1,993,287<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0 665,811<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0 2,659,098<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Gross profit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>118,598<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>34,274<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>152,872<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Operating, administrative and general expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>124,489<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>9,783<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>11,482<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>145,754<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other income (loss), net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>9,041<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,088<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(938)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>9,191<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income (loss) before income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(9,676)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>24,881<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(11,992)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3,213<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income (loss) attributable to noncontrolling interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(4,522)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>9,569<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5,047<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income (loss) before income taxes attributable to The Andersons, Inc.<sup>1<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (5,154)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 15,312<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0 (11,992)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (1,834)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments to income (loss) before income taxes<sup>2<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5,029<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>5,029<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted income (loss) before income taxes attributable to The Andersons, Inc.<sup>1<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (125)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 15,312<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0 (11,992)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3,195<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended March 31, 2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Sales and merchandising revenues<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2,061,439<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0 656,778<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0 2,718,217<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Gross profit<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">99,519<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">28,801<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">128,320<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Operating, administrative and general expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">96,921<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,777<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,660<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">119,358<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other income, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,571<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,760<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">197<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,528<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income (loss) before income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,538<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">24,327<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12,897)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,968<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income attributable to noncontrolling interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,084<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,084<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income (loss) before income taxes attributable to The Andersons, Inc.<sup>1<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2,538<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 17,243<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0 (12,897)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 6,884<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments to income (loss) before income taxes<sup>2<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,852<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,117)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(265)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted income (loss) before income taxes attributable to The Andersons, Inc.<sup>1<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,390<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 14,126<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0 (12,897)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 6,619<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table id=\"splitTable\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen23\" colspan=\"8\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen23\" colspan=\"8\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>1<\/sup> Income (loss) before income taxes attributable to The Andersons, Inc. for each operating segment is defined as net sales and merchandising revenues plus identifiable other income less all identifiable operating expenses, including interest expense for carrying working capital and long-term assets and is reported net of the noncontrolling interest share of income.<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>2<\/sup> Additional information on the individual adjustments that are included in the adjustments to income (loss) before income taxes can be found in the Reconciliation to EBITDA and Adjusted EBITDA table. All adjustments are consistent with the EBITDA reconciliation with the exception of items where a portion of the expense is attributable to the noncontrolling interest and is represented in Income attributable to the noncontrolling interest within the reconciliation above. These adjustments include a $1.6 million difference in insured inventory and property damages in the Agribusiness segment for the three months ended March 31, 2025. <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"8\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted Earnings Before Interest, Taxes, Depreciation, and Amortization (EBITDA)<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>A non-GAAP financial measure<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<p class=\"prnml4\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Agribusiness<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Renewables<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Other<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Total<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended March 31, 2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income (loss)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (9,676)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 24,881<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (9,874)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,331<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Interest expense (income)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>12,826<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>698<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(428)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>13,096<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Tax provision (benefit)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(2,118)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(2,118)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>21,685<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>11,891<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>764<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>34,340<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>24,835<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>37,470<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(11,656)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>50,649<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusting items impacting EBITDA:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Transaction related compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,103<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,103<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Insured inventory and property damage<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,502<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,502<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total adjusting items<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>6,605<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>6,605<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 31,440<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 37,470<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0 (11,656)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 57,254<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended March 31, 2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income (loss)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2,538<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 24,327<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0 (14,200)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 12,665<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Interest expense (income)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,631<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">457<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(566)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,522<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Tax provision<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,303<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,303<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">17,048<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,965<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,936<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">30,949<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">26,217<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">36,749<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(11,527)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">51,439<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusting items impacting EBITDA:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Transaction related compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,852<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,852<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Gain on deconsolidation of joint venture<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,117)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,117)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total adjusting items<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,852<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen25\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,117)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen24\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen25\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(265)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 29,069<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 33,632<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen21\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0 (11,527)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 51,174<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted EBITDA is defined as earnings before interest, taxes and depreciation and amortization, adjusted for specified items. The company calculates adjusted EBITDA by removing the impact of specified items and adding back the amounts of interest expense, tax expense and depreciation and amortization to net income (loss). Management believes that adjusted EBITDA is a useful measure of the company&#8217;s performance as it provides investors additional information about the company&#8217;s operations allowing better evaluation of underlying business performance and improved comparability to prior periods. Adjusted EBITDA is a non-GAAP financial measure and is not intended to replace or be an alternative to net income (loss), the most directly comparable GAAP financial measure.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"10\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Trailing Twelve Months of EBITDA and Adjusted EBITDA<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>A non-GAAP financial measure<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen27\" colspan=\"7\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months Ended,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a0Twelve months <br \/>ended <\/b><br \/>\n                  <b>March 31, <br \/>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>June 30, <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen29\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>September 30, <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen29\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>December 31, <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen29\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March 31, <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 52,470<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 51,461<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 54,104<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,331<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 163,366<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>6,611<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>8,361<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>10,266<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>13,096<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>38,334<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Tax provision (benefit)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,876<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>10,731<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>13,146<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(2,118)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>26,635<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>30,269<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>30,408<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>36,178<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>34,340<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>131,195<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>94,226<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>100,961<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>113,694<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>50,649<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>359,530<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusting items impacting EBITDA:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Transaction related compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,049<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,668<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,536<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,103<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>10,356<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Insured inventory and property damage (recoveries)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(5,204)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(4,446)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,502<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(5,148)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Acquisition costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3,193<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>3,193<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Loss on cost method investment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,535<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u2014<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,535<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total adjusting items<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>4,049<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(3,536)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2,818<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>6,605<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>9,936<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 98,275<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 97,425<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0 116,512<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 57,254<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 369,466<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen27\" colspan=\"7\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months Ended,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"2\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Twelve months <br \/>ended <\/b><br \/>\n                  <b>March 31, <br \/>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>June 30, <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2023<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen29\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>September 30, <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2023<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen29\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>December 31, <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2023<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen29\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen28\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>March 31,<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>\u00a02024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen26\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 82,686<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 30,523<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 78,437<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 12,665<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 204,311<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,953<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,188<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,101<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,522<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">36,764<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Tax provision<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">21,732<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,862<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,324<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,303<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">44,221<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">30,365<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">31,215<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">31,306<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">30,949<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">123,835<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">148,736<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">77,788<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">131,168<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">51,439<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">409,131<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusting items impacting EBITDA:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Transaction related compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">939<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,999<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,212<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,852<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9,002<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Gain on deconsolidation of joint venture<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(6,544)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,117)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(9,661)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Goodwill impairment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">686<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">686<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Gain on sale of assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5,643)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5,643)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Gain on cost method investment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,798)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,798)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Impairment on equity method investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">963<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">963<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Insured inventory expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,310<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,310<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total adjusting items<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,295)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(7,479)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,898<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(265)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,141)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0 144,441<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 70,309<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0 135,066<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 51,174<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 400,990<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>The Andersons, Inc.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash from Operations Before Working Capital Changes<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>A non-GAAP financial measure<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(unaudited)<\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three months ended <br \/>March 31,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(in thousands)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen16\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash used in operating activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0 (350,020)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 (239,627)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Changes in operating assets and liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Accounts receivable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(53,268)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">57,725<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Inventories<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>38,531<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">169,083<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Commodity derivatives<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>1,076<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(28,498)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Other current and non-current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(8,558)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,923<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Payables and other current and non-current liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(384,775)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(488,269)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Total changes in operating assets and liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(406,994)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(288,036)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash from operations before working capital changes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen30\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>$\u00a0\u00a0\u00a0\u00a0\u00a0 56,974<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen30\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0 48,409<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen22\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cash from operations before working capital changes is defined as cash provided by (used in) operating activities before the impact of changes in working capital within the statement of cash flows. The Company calculates cash from operations by eliminating the effect of changes in accounts receivable, inventories, commodity derivatives, other assets, and payables and accrued expenses from the cash provided by (used in) operating activities. Management believes that cash from operations before working capital changes is a useful measure of the company&#8217;s performance as it provides investors additional information about the company&#8217;s operations allowing better evaluation of underlying business performance and improved comparability to prior periods. Cash from operations before working capital changes is a non-GAAP financial measure and is not intended to replace or be an alternative to cash provided by (used in) operating activities, the most directly comparable GAAP financial measure.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p id=\"PURL\">\n        <img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/c212.net\/c\/img\/favicon.png?sn=CL81065&amp;sd=2025-05-06\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/news-releases\/the-andersons-inc-reports-first-quarter-results-302447693.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/news-releases\/the-andersons-inc-reports-first-quarter-results-302447693.html<\/a><\/p>\n<p>SOURCE  The Andersons, Inc.<\/p>\n<\/p><\/div>\n<p>    <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=CL81065&amp;Transmission_Id=202505061605PR_NEWS_USPR_____CL81065&amp;DateId=20250506\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PR Newswire MAUMEE, Ohio , May 6, 2025 \/PRNewswire\/ &#8212; The Andersons, Inc. (Nasdaq: ANDE) announces financial results for the first quarter ended March\u00a031, 2025. First Quarter Highlights: Company reported net income attributable to The Andersons of $0.3 million, or $0.01 per diluted share and adjusted net income of $4 million, or $0.12 per diluted share Adjusted EBITDA was $57 million Renewables reported pretax income of $25 million and pretax income attributable to The Andersons of $15 million on strong operating performance and solid merchandising Agribusiness recorded a pretax loss of $10 million and breakeven adjusted pretax income attributable to The Andersons on stagnant market conditions &#8220;We had mixed results in a turbulent first quarter. The Renewables segment performed well &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;The Andersons, Inc. Reports First Quarter Results&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-847592","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Andersons, Inc. Reports First Quarter Results - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Andersons, Inc. Reports First Quarter Results - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"PR Newswire MAUMEE, Ohio , May 6, 2025 \/PRNewswire\/ &#8212; The Andersons, Inc. (Nasdaq: ANDE) announces financial results for the first quarter ended March\u00a031, 2025. First Quarter Highlights: Company reported net income attributable to The Andersons of $0.3 million, or $0.01 per diluted share and adjusted net income of $4 million, or $0.12 per diluted share Adjusted EBITDA was $57 million Renewables reported pretax income of $25 million and pretax income attributable to The Andersons of $15 million on strong operating performance and solid merchandising Agribusiness recorded a pretax loss of $10 million and breakeven adjusted pretax income attributable to The Andersons on stagnant market conditions &#8220;We had mixed results in a turbulent first quarter. The Renewables segment performed well &hellip; Continue reading &quot;The Andersons, Inc. Reports First Quarter Results&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T20:23:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.jpg\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"The Andersons, Inc. Reports First Quarter Results\",\"datePublished\":\"2025-05-06T20:23:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/\"},\"wordCount\":2774,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/74436\\\/THE_ANDERSONS_LOGO.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/\",\"name\":\"The Andersons, Inc. Reports First Quarter Results - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/74436\\\/THE_ANDERSONS_LOGO.jpg\",\"datePublished\":\"2025-05-06T20:23:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/74436\\\/THE_ANDERSONS_LOGO.jpg\",\"contentUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/74436\\\/THE_ANDERSONS_LOGO.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/the-andersons-inc-reports-first-quarter-results-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Andersons, Inc. Reports First Quarter Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Andersons, Inc. Reports First Quarter Results - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/","og_locale":"en_US","og_type":"article","og_title":"The Andersons, Inc. Reports First Quarter Results - Market Newsdesk","og_description":"PR Newswire MAUMEE, Ohio , May 6, 2025 \/PRNewswire\/ &#8212; The Andersons, Inc. (Nasdaq: ANDE) announces financial results for the first quarter ended March\u00a031, 2025. First Quarter Highlights: Company reported net income attributable to The Andersons of $0.3 million, or $0.01 per diluted share and adjusted net income of $4 million, or $0.12 per diluted share Adjusted EBITDA was $57 million Renewables reported pretax income of $25 million and pretax income attributable to The Andersons of $15 million on strong operating performance and solid merchandising Agribusiness recorded a pretax loss of $10 million and breakeven adjusted pretax income attributable to The Andersons on stagnant market conditions &#8220;We had mixed results in a turbulent first quarter. The Renewables segment performed well &hellip; Continue reading \"The Andersons, Inc. Reports First Quarter Results\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/","og_site_name":"Market Newsdesk","article_published_time":"2025-05-06T20:23:41+00:00","og_image":[{"url":"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.jpg","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"The Andersons, Inc. Reports First Quarter Results","datePublished":"2025-05-06T20:23:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/"},"wordCount":2774,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/","name":"The Andersons, Inc. Reports First Quarter Results - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.jpg","datePublished":"2025-05-06T20:23:41+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/#primaryimage","url":"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.jpg","contentUrl":"https:\/\/mma.prnewswire.com\/media\/74436\/THE_ANDERSONS_LOGO.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/the-andersons-inc-reports-first-quarter-results-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"The Andersons, Inc. Reports First Quarter Results"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/847592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=847592"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/847592\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=847592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=847592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=847592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}