{"id":847583,"date":"2025-05-06T16:22:37","date_gmt":"2025-05-06T20:22:37","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/"},"modified":"2025-05-06T16:22:37","modified_gmt":"2025-05-06T20:22:37","slug":"grand-canyon-education-inc-reports-first-quarter-2025-results","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/","title":{"rendered":"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS"},"content":{"rendered":"<div class=\"xn-newslines\">\n<p class=\"xn-distributor\">PR Newswire<\/p>\n<\/p><\/div>\n<div class=\"xn-content\">\n<p>\n        <span class=\"legendSpanClass\"><br \/>\n          <span class=\"xn-location\">PHOENIX<\/span><br \/>\n        <\/span>, <span class=\"legendSpanClass\"><span class=\"xn-chron\">May 6, 2025<\/span><\/span> \/PRNewswire\/ &#8212; <b><u>Grand Canyon Education, Inc.<\/u><\/b> (NASDAQ: LOPE), (&#8220;GCE&#8221; or the &#8220;Company&#8221;), is a publicly traded education services company that currently provides services to 22 university partners. \u00a0GCE provides a full array of support services in the post-secondary education sector and has developed significant technological solutions, infrastructure and operational processes to provide superior services in these areas on a large scale. \u00a0GCE today announced financial results for the quarter ended <span class=\"xn-chron\">March 31<\/span>, 2025.\u00a0<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder1\">\n<p>\n          <a href=\"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.html\" target=\"_blank\" rel=\"nofollow\"><br \/>\n            <img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.jpg\" title=\"www.gce.com (PRNewsfoto\/Grand Canyon Education, Inc.)\" alt=\"www.gce.com (PRNewsfoto\/Grand Canyon Education, Inc.)\" \/><br \/>\n          <\/a>\n        <\/p>\n<\/p><\/div>\n<p>\n        <b>Grand Canyon Education, Inc. Reports First Quarter 2025 Results<\/b>\n      <\/p>\n<p>For the three months ended <span class=\"xn-chron\">March 31, 2025<\/span>:<\/p>\n<ul type=\"disc\">\n<li>Service revenue for the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> was <span class=\"xn-money\">$289.3 million<\/span>, an increase of <span class=\"xn-money\">$14.6 million<\/span>, or 5.3%, as compared to service revenue of <span class=\"xn-money\">$274.7 million<\/span> for the three months ended <span class=\"xn-chron\">March 31, 2024<\/span>. The increase year over year in service revenue was primarily due to an increase in partner enrollments of 5.8% to 127,779 at <span class=\"xn-chron\">March 31, 2025<\/span> as compared to 120,788 at <span class=\"xn-chron\">March 31, 2024<\/span>. Revenue per student decreased slightly between years primarily due to the additional day for leap year in 2024 which added additional service revenue of <span class=\"xn-money\">$1.5 million<\/span> as compared to the current year and contract modifications for some of our university partners in which the revenue share percentage was reduced in exchange for us no longer reimbursing the partner for certain faculty costs both of which had the effect of reducing revenue per student partially offset by the service revenue per student for accelerated Bachelor of Science in Nursing (&#8220;ABSN&#8221;) students at off-campus classroom and laboratory sites generating a significantly higher revenue per student than we earn under our agreement with GCU, as these agreements generally provide us with a higher revenue share percentage, the partners have higher tuition rates than GCU and the majority of our partners&#8217; students take more credits on average per semester.\n<\/li>\n<li>GCU enrollments increased to 123,773 at <span class=\"xn-chron\">March 31, 2025<\/span>, an increase of 5.8% over enrollments at <span class=\"xn-chron\">March 31, 2024<\/span>. University partner enrollments at our off-campus classroom and laboratory sites were 5,027, an increase of 12.1% over enrollments at <span class=\"xn-chron\">March 31, 2024<\/span>, which includes 1,021 and 650 GCU students at <span class=\"xn-chron\">March 31, 2025<\/span> and 2024, respectively. Excluding sites closing in 2024 to new enrollments, total enrollments at our off-campus classroom and laboratory sites increased 16.5% between years. We opened six sites in the year ended <span class=\"xn-chron\">December 31, 2024<\/span> and opened one site in the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> increasing the total number of these sites to 46 at <span class=\"xn-chron\">March 31, 2025<\/span>, which has also positively impacted the enrollment growth. Enrollments for GCU ground students were 22,330 at <span class=\"xn-chron\">March 31, 2025<\/span> down from 22,965 at <span class=\"xn-chron\">March 31, 2024<\/span> due to a small decline in traditional ground students year over year and the continued decline in professional studies students (working adults attending the university&#8217;s traditional campus at night), partially offset by an increase in ABSN students between years. GCU online enrollments were 101,443 at <span class=\"xn-chron\">March 31, 2025<\/span>, up from 93,987 at <span class=\"xn-chron\">December 31, 2024<\/span>, an increase of 7.9% between years.\n<\/li>\n<li>Operating income for the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> was <span class=\"xn-money\">$88.0 million<\/span>, an increase of <span class=\"xn-money\">$3.5 million<\/span>, or 4.2%, as compared to <span class=\"xn-money\">$84.5 million<\/span> for the same period in 2024. The operating margin for the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> and 2024 was 30.4% and 30.8%, respectively. The first quarter operating income and operating margin were negatively impacted on a year over year basis by the additional day for leap year in 2024 which added additional service revenue of <span class=\"xn-money\">$1.5 million<\/span> as compared to the current year partially offset by contract modifications for some of our university partners in which the revenue share percentage was reduced in exchange for us no longer reimbursing the partner for certain faculty costs both of which had the effect of reducing revenue per student.\n<\/li>\n<li>Income tax expense for the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> was <span class=\"xn-money\">$19.8 million<\/span>, a decrease of <span class=\"xn-money\">$0.4 million<\/span>, or 2.0%, as compared to income tax expense of <span class=\"xn-money\">$20.2 million<\/span> for the three months ended <span class=\"xn-chron\">March 31, 2024<\/span>. Our effective tax rate was 21.6% during the first quarter of 2025 compared to 22.9% during the first quarter of 2024. The effective tax rate decreased year over year primarily due to an increase in excess tax benefits to <span class=\"xn-money\">$2.7 million<\/span> as compared to <span class=\"xn-money\">$1.5 million<\/span> in the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> and 2024, respectively, partially offset by higher state income taxes.\n<\/li>\n<li>Net income for the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> was <span class=\"xn-money\">$71.6 million<\/span>, an increase of <span class=\"xn-money\">$3.6 million<\/span>, or 5.3% as compared to <span class=\"xn-money\">$68.0 million<\/span> for the same period in 2024. As adjusted net income was <span class=\"xn-money\">$73.3 million<\/span> and <span class=\"xn-money\">$69.6 million<\/span> for the first quarters of 2025 and 2024, respectively.\n<\/li>\n<li>Diluted net income per share was <span class=\"xn-money\">$2.52<\/span> and <span class=\"xn-money\">$2.29<\/span> for the first quarters of 2025 and 2024, respectively. As adjusted diluted net income per share was <span class=\"xn-money\">$2.57<\/span> and <span class=\"xn-money\">$2.35<\/span> for the first quarters of 2025 and 2024, respectively.\n<\/li>\n<li>Adjusted EBITDA increased 3.4% to <span class=\"xn-money\">$102.0 million<\/span> for the first quarter of 2025, compared to <span class=\"xn-money\">$98.6 million<\/span> for the same period in 2024.<\/li>\n<\/ul>\n<p>\n        <b>Liquidity and Capital Resources <\/b>\n      <\/p>\n<p>Our liquidity position, as measured by cash and cash equivalents and investments decreased by <span class=\"xn-money\">$20.0 million<\/span> between <span class=\"xn-chron\">December 31, 2024<\/span> and <span class=\"xn-chron\">March 31, 2025<\/span>, which was largely attributable to share repurchases, changes in our investment balance and capital expenditures exceeding our cash provided by operations during the three months ended <span class=\"xn-chron\">March 31<\/span>, 2025.\u00a0 Our unrestricted cash and cash equivalents and investments were <span class=\"xn-money\">$304.7 million<\/span> and <span class=\"xn-money\">$324.6 million<\/span> at <span class=\"xn-chron\">March 31, 2025<\/span> and <span class=\"xn-chron\">December 31, 2024<\/span>, respectively.<\/p>\n<p>\n        <b>Grand Canyon Education, Inc. Reports First Quarter 2025 Results and Full Year Outlook 2025<\/b>\n      <\/p>\n<p>\n        <b>2025 Outlook<\/b>\n      <\/p>\n<p class=\"prntaj\">\n        <b>Q2 2025:<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>Service revenue of between <span class=\"xn-money\">$239.0 million<\/span> and <span class=\"xn-money\">$241.5 million<\/span>;<\/li>\n<li>Operating margin of between 18.8% and 19.4%;<\/li>\n<li>Effective tax rate of 24.9%;<\/li>\n<li>Diluted EPS of between <span class=\"xn-money\">$1.28<\/span> and <span class=\"xn-money\">$1.33<\/span>; and<\/li>\n<li>28.2 million diluted shares.<\/li>\n<\/ul>\n<p>The diluted EPS guidance includes non-cash amortization of intangible assets net of taxes of <span class=\"xn-money\">$1.6 million<\/span>, which equates to a <span class=\"xn-money\">$0.06<\/span> impact on diluted EPS. Thus, as adjusted, non-GAAP diluted income per share of between <span class=\"xn-money\">$1<\/span>.34and <span class=\"xn-money\">$1.39<\/span>.<\/p>\n<p class=\"prntaj\">\n        <b>Q3 2025:<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>Service revenue of between <span class=\"xn-money\">$250.5 million<\/span> and <span class=\"xn-money\">$257.5 million<\/span>;<\/li>\n<li>Operating margin of between 22.0% and 23.2%;<\/li>\n<li>Effective tax rate of 24.9%;<\/li>\n<li>Diluted EPS of between <span class=\"xn-money\">$1.56<\/span> and <span class=\"xn-money\">$1.68<\/span>; and<\/li>\n<li>28.0 million diluted shares.<\/li>\n<\/ul>\n<p>The diluted EPS guidance includes non-cash amortization of intangible assets net of taxes of <span class=\"xn-money\">$1.6 million<\/span>, which equates to a <span class=\"xn-money\">$0.06<\/span> impact on diluted EPS. Thus, as adjusted, non-GAAP diluted income per share of between <span class=\"xn-money\">$1.62<\/span> and <span class=\"xn-money\">$1.74<\/span>.<\/p>\n<p class=\"prntaj\">\n        <b>Q4 2025:<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>Service revenue of between <span class=\"xn-money\">$301.0 million<\/span> and <span class=\"xn-money\">$311.5 million<\/span>;<\/li>\n<li>Operating margin of between 35.5% and 36.3%;<\/li>\n<li>Effective tax rate of 24.1%;<\/li>\n<li>Diluted EPS of between <span class=\"xn-money\">$3.00<\/span> and <span class=\"xn-money\">$3.17<\/span>; and<\/li>\n<li>27.8 million diluted shares.<\/li>\n<\/ul>\n<p>The diluted EPS guidance includes non-cash amortization of intangible assets net of taxes of <span class=\"xn-money\">$1.6 million<\/span>, which equates to a <span class=\"xn-money\">$0.06<\/span> impact on diluted EPS. Thus, as adjusted, non-GAAP diluted income per share of between <span class=\"xn-money\">$3.06<\/span> and <span class=\"xn-money\">$3.23<\/span>.<\/p>\n<p>\n        <b>Full Year 2025:<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>Service revenue of between <span class=\"xn-money\">$1,079.8 million<\/span> and <span class=\"xn-money\">$1,099.8 million<\/span>;<\/li>\n<li>Operating margin of between 27.3% and 28.0%;<\/li>\n<li>Effective tax rate of 23.7%;<\/li>\n<li>Diluted EPS between <span class=\"xn-money\">$8.36<\/span> and <span class=\"xn-money\">$8.70<\/span>; and<\/li>\n<li>28.1 million diluted shares.<\/li>\n<\/ul>\n<p>The diluted EPS guidance includes non-cash amortization of intangible assets net of taxes of <span class=\"xn-money\">$6.5 million<\/span>, which equates to a <span class=\"xn-money\">$0.23<\/span> impact on diluted EPS. Thus, as adjusted, non-GAAP diluted income per share of between <span class=\"xn-money\">$8.59<\/span> and <span class=\"xn-money\">$8.93<\/span>.<\/p>\n<p>\n        <b>Forward-Looking Statements<\/b>\n      <\/p>\n<p>This news release contains &#8220;forward-looking statements&#8221; within the meaning of Federal securities laws which include information relating to future events, future financial performance, strategies expectations, competitive environment, regulation, and availability of resources. \u00a0These forward-looking statements include, without limitation, statements regarding: proposed new programs; whether regulatory, economic, or business developments or other matters may or may not have a material adverse effect on our financial position, results of operations, or liquidity; projections, predictions, expectations, estimates, and forecasts as to our business, financial and operating results, and future economic performance; and management&#8217;s goals and objectives and other similar expressions concerning matters that are not historical facts. \u00a0Words such as &#8220;may,&#8221; &#8220;should,&#8221; &#8220;could,&#8221; &#8220;would,&#8221; &#8220;predicts,&#8221; &#8220;potential,&#8221; &#8220;continue,&#8221; &#8220;expects,&#8221; &#8220;anticipates,&#8221; &#8220;future,&#8221; &#8220;intends,&#8221; &#8220;plans,&#8221; &#8220;believes,&#8221; &#8220;estimates&#8221; and similar expressions, the negative of these expressions, as well as statements in future tense, identify forward-looking statements.<\/p>\n<p>Forward-looking statements should not be read as a guarantee of future performance or results and will not necessarily be accurate indications of the times at, or by, which such performance or results will be achieved. \u00a0Forward-looking statements are based on information available at the time those statements are made or management&#8217;s good faith belief as of that time with respect to future events and are subject to risks and uncertainties that could cause actual performance or results to differ materially from those expressed in or suggested by the forward-looking statements. \u00a0Important factors that could cause our actual performance or results to differ materially from those expressed in or suggested by the forward-looking statements include, but are not limited to: (i) legal and regulatory actions taken against us related to our services business, or against our university partners that impact their businesses and that directly or indirectly reduce the service revenue we can earn under our master services agreements; (ii) the occurrence of any event, change or other circumstance that could give rise to the termination of any of the key university partner agreements; (iii) our ability to properly manage risks and challenges associated with strategic initiatives, including potential acquisitions or divestitures of, or investments in, new businesses, acquisitions of new properties and new university partners, and expansion of services provided to our existing university partners; (iv) our ability to comply with the extensive regulatory framework applicable to us either directly as a third-party service provider or indirectly through our university partners; (v) our ability to manage risks associated with epidemics, pandemics, or public health crises; (vi) our ability to manage risks resulting from system disruptions, interruptions, or outages associated with our technology platforms or those of third-party service providers; (vii) the ability of our university partners&#8217; students to obtain federal Title IV funds, state financial aid, and private financing; (viii) potential damage to our reputation or other adverse effects as a result of negative publicity in the media, in the industry or in connection with governmental reports or investigations or otherwise; (ix) risks associated with changes in applicable federal and state laws and regulations and accrediting commission standards; (x) competition from other education service companies in our geographic region and market sector; (xi) our ability to hire and train new, and develop and train existing employees; (xii) the pace of growth of our university partners&#8217; enrollment and its effect on the pace of our own growth; (xiii) fluctuations in our revenues due to seasonality; (xiv) our ability to, on behalf of our university partners, convert prospective students to enrolled students and to retain active students to graduation; and (xv) other risks and uncertainties identified from time to time in documents filed with the Securities and Exchange Commission (the &#8220;SEC&#8221;) by us.<\/p>\n<p>Forward-looking statements speak only as of the date the statements are made. \u00a0You should not put undue reliance on any forward-looking statements. \u00a0We assume no obligation to update forward-looking statements to reflect actual results, changes in assumptions, or changes in other factors affecting forward-looking information, except to the extent required by applicable securities laws. \u00a0If we do update one or more forward-looking statements, no inference should be drawn that we will make additional updates with respect to those or other forward-looking statements.\u00a0 This press release should be read in conjunction with the information included in our other press releases, reports and other filings with the SEC.\u00a0 Understanding the information contained in these filings is important in order to fully understand GCE&#8217;s reported financial results and our business outlook for future periods.<\/p>\n<p>\n        <b>Grand Canyon Education, Inc. Reports First Quarter 2025 Results<\/b>\n      <\/p>\n<p>\n        <b>Conference Call<\/b>\n      <\/p>\n<p>Grand Canyon Education, Inc. will discuss its first quarter 2025 results and full year 2025 outlook during a conference call scheduled for today, <span class=\"xn-chron\">May 6, 2025<\/span> at <span class=\"xn-chron\">4:30 p.m. Eastern time<\/span> (ET). \u00a0<\/p>\n<p>\n        <b><br \/>\n          <u>Live Conference Dial-In:<\/u><br \/>\n        <\/b>\n      <\/p>\n<p>Those interested in participating in the question-and-answer session should follow the conference dial-in instructions below.\u00a0 Participants may register for the call <a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=4420515-1&amp;h=789675212&amp;u=https%3A%2F%2Fregister-conf.media-server.com%2Fregister%2FBI852127cabb2042f6894b597dfdcae00a&amp;a=here\" target=\"_blank\" rel=\"nofollow\">here<\/a>\u00a0to receive the dial-in numbers and unique PIN to access the call seamlessly. Please dial in at least ten minutes prior to the start of the call.\u00a0 Journalists are invited to listen only.\u00a0<\/p>\n<p>\n        <b><br \/>\n          <u>Webcast and Replay:<\/u><br \/>\n        <\/b>\n      <\/p>\n<p>Investors, journalists and the general public may access a live webcast of this event at:\u00a0<i><a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=4420515-1&amp;h=3646604385&amp;u=https%3A%2F%2Fedge.media-server.com%2Fmmc%2Fp%2F6drpzent&amp;a=Q1+2025%C2%A0Grand+Canyon+Education+Inc.%C2%A0Earnings+Conference+Call\" target=\"_blank\" rel=\"nofollow\">Q1 2025\u00a0Grand Canyon Education Inc.\u00a0Earnings Conference Call<\/a><\/i><i>.\u00a0<\/i>A webcast replay will be available approximately two hours following the conclusion of the call at the same link.<\/p>\n<p>\n        <b>About Grand Canyon Education, Inc.<\/b>\n      <\/p>\n<p>Grand Canyon Education, Inc. (&#8220;GCE&#8221;), incorporated in 2008, is a publicly traded education services company that currently provides services to 22 university partners. \u00a0GCE is uniquely positioned in the education services industry in that its leadership has over 30 years of proven expertise in providing a full array of support services in the post-secondary education sector and has developed significant technological solutions, infrastructure and operational processes to provide superior services in these areas on a large scale. \u00a0GCE provides services that support students, faculty and staff of partner institutions such as marketing, strategic enrollment management, counseling services, financial services, technology, technical support, compliance, human resources, classroom operations, content development, faculty recruitment and training, among others. \u00a0For more information about GCE visit the Company&#8217;s website at <a href=\"http:\/\/www.gce.com\" rel=\"nofollow\">www.gce.com<\/a>.<\/p>\n<p>Grand Canyon Education, Inc., 2600 W. Camelback Road, <span class=\"xn-location\">Phoenix, AZ<\/span> 85017, <b><a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=4420515-1&amp;h=1806881457&amp;u=http%3A%2F%2Fwww.gce.com%2F&amp;a=www.gce.com\" target=\"_blank\" rel=\"nofollow\">www.gce.com<\/a><\/b>.\u00a0<\/p>\n<p>\n        <b>Grand Canyon Education, Inc. Reports First Quarter 2025 Results<\/b>\n      <\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"7\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GRAND CANYON EDUCATION, INC.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Consolidated Income Statements<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(Unaudited)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March\u00a031,\u00a0<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">(In thousands, except per share data)<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Service revenue<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">289,310<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">274,675<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Costs and expenses:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Technology and academic services<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">41,664<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">39,125<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Counseling services and support<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">86,822<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">82,884<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Marketing and communication<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">60,330<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">55,353<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">General and administrative<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">10,366<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">10,730<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Amortization of intangible assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total costs and expenses<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">201,287<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">190,197<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Operating income<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">88,023<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">84,478<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Investment interest and other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,381<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,729<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Income before income taxes<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">91,404<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">88,205<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">19,786<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20,195<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Net income <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">71,618<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">68,010<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Earnings per share:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Basic income per share<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.53<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.31<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Diluted income per share<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.52<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.29<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Basic weighted average shares outstanding<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">28,277<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">29,459<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Diluted weighted average shares outstanding<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">28,469<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">29,639<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"7\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GRAND CANYON EDUCATION, INC.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Consolidated Balance Sheets<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">As of March\u00a031,\u00a0<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">As of December 31,<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">(In thousands, except par value)<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">ASSETS:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">(Unaudited)<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Current assets<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">144,509<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">324,623<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">160,144<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Accounts receivable, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">115,696<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">82,948<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Income taxes receivable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">490<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Other current assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16,087<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,915<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total current assets<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">436,436<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">419,976<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Property and equipment, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">177,758<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">176,823<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Right-of-use assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">96,059<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">99,541<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Amortizable intangible assets, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">157,857<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">159,962<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Goodwill<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">160,766<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">160,766<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,572<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,357<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total assets<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,031,448<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,018,425<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen2\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">LIABILITIES AND STOCKHOLDERS&#8217; EQUITY:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Current liabilities<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Accounts payable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">24,077<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">26,721<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Accrued compensation and benefits<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">23,251<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">33,183<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Accrued liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">34,573<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">29,620<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Income taxes payable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">24,076<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8,559<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Deferred revenue<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9,081<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Current portion of lease liability<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13,146<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12,883<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total current liabilities<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">128,204<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">110,966<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Deferred income taxes, noncurrent<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">28,974<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">26,527<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other long-term liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,398<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,444<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Lease liability, less current portion<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">92,168<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">95,635<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total liabilities<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">250,744<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">234,572<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Commitments and contingencies<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Stockholders&#8217; equity<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Preferred stock, $0.01 par value, 10,000 shares authorized; 0 shares issued and outstanding <br \/>at March 31, 2025 and December 31, 2024<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Common stock, $0.01 par value, 100,000 shares authorized; 54,176 and 54,090 shares issued <br \/>and 28,496 and 28,858 shares outstanding at March 31, 2025 and December 31, 2024, respectively<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">542<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">541<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Treasury stock, at cost, 25,680 and 25,232 shares of common stock at March 31, 2025 and <br \/>December 31, 2024, respectively<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2,102,760)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2,024,370)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Additional paid-in capital<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">340,365<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">336,736<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Accumulated other comprehensive loss<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(7)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Retained earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,542,564<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,470,946<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total stockholders&#8217; equity<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">780,704<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">783,853<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total liabilities and stockholders&#8217; equity<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,031,448<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,018,425<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen2\" colspan=\"7\" rowspan=\"1\" nowrap=\"nowrap\" height=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>GRAND CANYON EDUCATION, INC.<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Consolidated Statements of Cash Flows<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(Unaudited)<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March\u00a031,\u00a0<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">(In thousands)<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Cash flows provided by operating activities:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">71,618<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">68,010<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjustments to reconcile net income to net cash provided by operating activities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Share-based compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,630<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,483<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,451<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,653<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Amortization of intangible assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Deferred income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,446<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,724<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Other, including fixed asset disposals<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(207)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(208)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Changes in assets and liabilities:<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Accounts receivable from university partners<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(32,748)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(32,899)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(4,449)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,757)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Right-of-use assets and lease liabilities <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">278<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">335<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Accounts payable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2,023)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">11,970<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Accrued liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5,558)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(51)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Income taxes receivable\/payable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16,007<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">17,328<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Deferred revenue<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">9,081<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">10,270<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Net cash provided by operating activities<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">67,631<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">84,963<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Cash flows used in investing activities:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Capital expenditures<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,948)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8,979)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Additions of amortizable content<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(20)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(72)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Purchase of equity investment<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1,000)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Purchases of investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(159,920)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(19,381)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Proceeds from sale or maturity of investments<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">23,172<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Net cash used in investing activities<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(169,888)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(5,260)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Cash flows used in financing activities:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Repurchase of common shares and shares withheld in lieu of income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(77,857)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(29,970)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Net cash used in financing activities<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(77,857)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(29,970)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Net (decrease) increase in cash and cash equivalents and restricted cash <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(180,114)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">49,733<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Cash and cash equivalents and restricted cash, beginning of period<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">324,623<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">146,475<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Cash and cash equivalents and restricted cash, end of period<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">144,509<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">196,208<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Supplemental disclosure of cash flow information<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Cash paid for interest<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Cash paid for income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">333<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">295<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Supplemental disclosure of non-cash investing and financing activities<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Purchases of property and equipment included in accounts payable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">444<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,091<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">ROU Asset and Liability recognition<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">25,500<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">Excise tax on treasury stock repurchases<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">533<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">34<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Grand Canyon Education, Inc. Reports First Quarter 2025 Results<\/b>\n      <\/p>\n<p class=\"prntac\">\n        <b><br \/>\n          <span class=\"xn-location\">GRAND CANYON<\/span> EDUCATION, INC.<\/b>\n      <\/p>\n<p>\n        <b>Adjusted EBITDA\u00a0 (Non-GAAP Financial Measure)<\/b>\n      <\/p>\n<p>Adjusted EBITDA is defined as net income plus interest expense, less interest income and other gain (loss) recognized on investments, plus income tax expense, and plus depreciation and amortization (EBITDA), as adjusted for (i)\u00a0 contributions to private <span class=\"xn-location\">Arizona<\/span> school tuition organizations in lieu of the payment of state income taxes; (ii) share-based compensation, and (iii) unusual charges or gains, such as litigation and regulatory reserves, impairment charges and asset write-offs, severance costs, and exit or lease termination costs.\u00a0 We present Adjusted EBITDA because we consider it to be an important supplemental measure of our operating performance.\u00a0 We also make certain compensation decisions based, in part, on our operating performance, as measured by Adjusted EBITDA.\u00a0 All of the adjustments made in our calculation of Adjusted EBITDA are adjustments to items that management does not consider to be reflective of our core operating performance.\u00a0 Management considers our core operating performance to be that which can be affected by our managers in any particular period through their management of the resources that affect our underlying revenue and profit generating operations during that period and does not consider the items for which we make adjustments (as listed above) to be reflective of our core performance.<\/p>\n<p>We believe Adjusted EBITDA allows us to compare our current operating results with corresponding historical periods and with the operational performance of other companies in our industry because it does not give effect to potential differences caused by variations in capital structures (affecting relative interest expense, including the impact of write-offs of deferred financing costs when companies refinance their indebtedness), tax positions (such as the impact on periods or companies of changes in effective tax rates or net operating losses), the book amortization of intangibles (affecting relative amortization expense), and other items that we do not consider reflective of underlying operating performance.\u00a0 We also present Adjusted EBITDA because we believe it is frequently used by securities analysts, investors, and other interested parties as a measure of performance.<\/p>\n<p>In evaluating Adjusted EBITDA, investors should be aware that in the future we may incur expenses similar to the adjustments described above.\u00a0 Our presentation of Adjusted EBITDA should not be construed as an inference that our future results will be unaffected by expenses that are unusual, non-routine, or non-recurring.\u00a0 Adjusted EBITDA has limitations as an analytical tool in that, among other things it does not reflect:<\/p>\n<ul type=\"disc\">\n<li>cash expenditures for capital expenditures or contractual commitments;<\/li>\n<li>changes in, or cash requirements for, our working capital requirements;<\/li>\n<li>interest expense, or the cash required to replace assets that are being depreciated or amortized; and<\/li>\n<li>the impact on our reported results of earnings or charges resulting from the items for which we make adjustments to our EBITDA, as described above and set forth in the table below.<\/li>\n<\/ul>\n<p>In addition, other companies, including other companies in our industry, may calculate these measures differently than we do, limiting the usefulness of Adjusted EBITDA as a comparative measure.\u00a0 Because of these limitations, Adjusted EBITDA should not be considered as a substitute for net income, operating income, or any other performance measure derived in accordance with and reported under GAAP, or as an alternative to cash flow from operating activities or as a measure of our liquidity.\u00a0 We compensate for these limitations by relying primarily on our GAAP results and only use Adjusted EBITDA as a supplemental performance measure.<\/p>\n<p>The following table provides a reconciliation of net income to Adjusted EBITDA, which is a non-GAAP measure for the periods indicated:<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March\u00a031,\u00a0<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"2\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">(Unaudited,\u00a0in\u00a0thousands)<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">71,618<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">68,010<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Plus: interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Less: investment interest and other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,381)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3,729)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Plus: income tax expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">19,786<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20,195<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Plus: amortization of intangible assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Plus: depreciation and amortization<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,451<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,653<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml8\">\n                <span class=\"prnews_span\">EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">97,579<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">93,236<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Plus: share-based compensation<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,630<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,483<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Plus: litigation and regulatory costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">743<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,870<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Plus: loss on fixed asset disposal<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted EBITDA<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">101,968<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">98,589<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Non-GAAP Net Income and Non-GAAP Diluted Income Per Share<\/b>\n      <\/p>\n<p>The Company believes the presentation of non-GAAP net income and non-GAAP diluted income per share information that excludes amortization of intangible assets and loss on disposal of fixed assets allows investors to develop a more meaningful understanding of the Company&#8217;s performance over time.\u00a0 Accordingly, for the three months ended <span class=\"xn-chron\">March 31, 2025<\/span> and 2024, the table below provides reconciliations of these non-GAAP items to GAAP net income and GAAP diluted income per share, respectively:<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"5\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"5\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March\u00a031,\u00a0<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"2\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen2\" colspan=\"7\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">(Unaudited, in thousands except per share data)<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">GAAP Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a071,618<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a068,010<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Amortization of intangible assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,105<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Loss on disposal of fixed assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income tax effects of adjustments (1)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(459)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(482)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">As Adjusted, Non-GAAP Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a073,280<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a069,633<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">GAAP Diluted income per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02.52<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02.29<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Amortization of intangible assets (2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.05<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.06<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Loss on disposal of fixed assets (3)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.00<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">As Adjusted, Non-GAAP Diluted income per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02.57<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02.35<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">The income tax effects of adjustments are based on the effective income tax rate applicable to adjusted (non-GAAP) results.\u00a0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(2)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">The amortization of acquired intangible assets per diluted share is net of an income tax benefit of $0.02 for both of the three months ended March 31, 2025 and 2024, respectively.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(3)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">The loss on disposal of fixed assets per diluted share is net of an income tax benefit of nil for the three months ended March 31, 2025.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\n        <b>Investor Relations Contact:<br \/><\/b><br \/>\n        <span class=\"xn-person\">Daniel E. Bachus<\/span><br \/>\n        <br \/>Chief Financial Officer<br \/>Grand Canyon Education, Inc.<br \/>602-639-6648<br \/><u><a href=\"mailto:Dan.bachus@gce.com\" target=\"_blank\" rel=\"nofollow\">Dan.bachus@gce.com<\/a><\/u><\/p>\n<p id=\"PURL\">\n        <img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/c212.net\/c\/img\/favicon.png?sn=LA80440&amp;sd=2025-05-06\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/news-releases\/grand-canyon-education-inc-reports-first-quarter-2025-results-302447657.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/news-releases\/grand-canyon-education-inc-reports-first-quarter-2025-results-302447657.html<\/a><\/p>\n<p>SOURCE  Grand Canyon Education<\/p>\n<\/p><\/div>\n<p>    <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=LA80440&amp;Transmission_Id=202505061605PR_NEWS_USPR_____LA80440&amp;DateId=20250506\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PR Newswire PHOENIX , May 6, 2025 \/PRNewswire\/ &#8212; Grand Canyon Education, Inc. (NASDAQ: LOPE), (&#8220;GCE&#8221; or the &#8220;Company&#8221;), is a publicly traded education services company that currently provides services to 22 university partners. \u00a0GCE provides a full array of support services in the post-secondary education sector and has developed significant technological solutions, infrastructure and operational processes to provide superior services in these areas on a large scale. \u00a0GCE today announced financial results for the quarter ended March 31, 2025.\u00a0 Grand Canyon Education, Inc. Reports First Quarter 2025 Results For the three months ended March 31, 2025: Service revenue for the three months ended March 31, 2025 was $289.3 million, an increase of $14.6 million, or 5.3%, as compared to &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-847583","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"PR Newswire PHOENIX , May 6, 2025 \/PRNewswire\/ &#8212; Grand Canyon Education, Inc. (NASDAQ: LOPE), (&#8220;GCE&#8221; or the &#8220;Company&#8221;), is a publicly traded education services company that currently provides services to 22 university partners. \u00a0GCE provides a full array of support services in the post-secondary education sector and has developed significant technological solutions, infrastructure and operational processes to provide superior services in these areas on a large scale. \u00a0GCE today announced financial results for the quarter ended March 31, 2025.\u00a0 Grand Canyon Education, Inc. Reports First Quarter 2025 Results For the three months ended March 31, 2025: Service revenue for the three months ended March 31, 2025 was $289.3 million, an increase of $14.6 million, or 5.3%, as compared to &hellip; Continue reading &quot;GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T20:22:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.jpg\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS\",\"datePublished\":\"2025-05-06T20:22:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/\"},\"wordCount\":3437,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/799628\\\/GCE_Logo.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/\",\"name\":\"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/799628\\\/GCE_Logo.jpg\",\"datePublished\":\"2025-05-06T20:22:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/799628\\\/GCE_Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/799628\\\/GCE_Logo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/grand-canyon-education-inc-reports-first-quarter-2025-results\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/","og_locale":"en_US","og_type":"article","og_title":"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS - Market Newsdesk","og_description":"PR Newswire PHOENIX , May 6, 2025 \/PRNewswire\/ &#8212; Grand Canyon Education, Inc. (NASDAQ: LOPE), (&#8220;GCE&#8221; or the &#8220;Company&#8221;), is a publicly traded education services company that currently provides services to 22 university partners. \u00a0GCE provides a full array of support services in the post-secondary education sector and has developed significant technological solutions, infrastructure and operational processes to provide superior services in these areas on a large scale. \u00a0GCE today announced financial results for the quarter ended March 31, 2025.\u00a0 Grand Canyon Education, Inc. Reports First Quarter 2025 Results For the three months ended March 31, 2025: Service revenue for the three months ended March 31, 2025 was $289.3 million, an increase of $14.6 million, or 5.3%, as compared to &hellip; Continue reading \"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/","og_site_name":"Market Newsdesk","article_published_time":"2025-05-06T20:22:37+00:00","og_image":[{"url":"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.jpg","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS","datePublished":"2025-05-06T20:22:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/"},"wordCount":3437,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/","name":"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.jpg","datePublished":"2025-05-06T20:22:37+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/#primaryimage","url":"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.jpg","contentUrl":"https:\/\/mma.prnewswire.com\/media\/799628\/GCE_Logo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/grand-canyon-education-inc-reports-first-quarter-2025-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"GRAND CANYON EDUCATION, INC. REPORTS FIRST QUARTER 2025 RESULTS"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/847583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=847583"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/847583\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=847583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=847583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=847583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}