{"id":846984,"date":"2025-05-06T06:34:43","date_gmt":"2025-05-06T10:34:43","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/"},"modified":"2025-05-06T06:34:43","modified_gmt":"2025-05-06T10:34:43","slug":"lear-reports-first-quarter-2025-results","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/","title":{"rendered":"Lear Reports First Quarter 2025 Results"},"content":{"rendered":"<div class=\"xn-newslines\">\n<p class=\"xn-distributor\">PR Newswire<\/p>\n<\/p><\/div>\n<div class=\"xn-content\">\n<p>\n        <span class=\"legendSpanClass\"><br \/>\n          <span class=\"xn-location\">SOUTHFIELD, Mich.<\/span><br \/>\n        <\/span>, <span class=\"legendSpanClass\"><span class=\"xn-chron\">May 6, 2025<\/span><\/span> \/PRNewswire\/ &#8212;\u00a0Lear Corporation (NYSE: LEA), a global automotive technology leader in Seating and E-Systems, today reported results for the first quarter 2025.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder1\">\n<p>\n          <a href=\"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.html\" target=\"_blank\" rel=\"nofollow\"><br \/>\n            <img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.jpg\" title=\"Lear Corporation Logo.\u00a0(PRNewsFoto\/Lear Corporation) (PRNewsfoto\/Lear Corporation)\" alt=\"Lear Corporation Logo.\u00a0(PRNewsFoto\/Lear Corporation) (PRNewsfoto\/Lear Corporation)\" \/><br \/>\n          <\/a>\n        <\/p>\n<\/p><\/div>\n<p>\n        <b><br \/>\n          <u>First Quarter 2025 Highlights<\/u><br \/>\n        <\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>Delivered revenue of <span class=\"xn-money\">$5.6 billion<\/span> in the first quarter, compared to <span class=\"xn-money\">$6.0 billion<\/span> in the first quarter of 2024<\/li>\n<li>Net income of <span class=\"xn-money\">$81 million<\/span> and adjusted net income of <span class=\"xn-money\">$169 million<\/span>, compared to <span class=\"xn-money\">$110 million<\/span> and <span class=\"xn-money\">$183 million<\/span>, respectively, in the first quarter of 2024<\/li>\n<li>Core operating earnings of <span class=\"xn-money\">$270 million<\/span>, compared to <span class=\"xn-money\">$280 million<\/span> in the first quarter of 2024<\/li>\n<li>Earnings per share of <span class=\"xn-money\">$1.49<\/span> and adjusted earnings per share of <span class=\"xn-money\">$3.12<\/span>, compared to <span class=\"xn-money\">$1.90<\/span> and <span class=\"xn-money\">$3.18<\/span>, respectively, in the first quarter of 2024<\/li>\n<li>Net cash used in operating activities of <span class=\"xn-money\">$(128) million<\/span> and free cash flow of <span class=\"xn-money\">$(232) million<\/span>, compared to <span class=\"xn-money\">$(35) million<\/span> and <span class=\"xn-money\">$(148) million<\/span>, respectively, in the first quarter of 2024<\/li>\n<li>Repurchased <span class=\"xn-money\">$25 million<\/span> of shares and paid <span class=\"xn-money\">$43 million<\/span> in dividends<\/li>\n<li>Cash and cash equivalents of <span class=\"xn-money\">$780 million<\/span> and total liquidity of <span class=\"xn-money\">$2.8 billion<\/span> at quarter end<\/li>\n<li>Increased operating margins year-over-year for Seating, E-Systems and the total company<\/li>\n<li>Delivered strong operating performance for both segments, generating \u2248125 basis points in Seating and \u2248155 basis points in E-Systems, driven by efficiency improvements and savings from our restructuring and automation investments<\/li>\n<li>Obtained operating control of a joint venture in <span class=\"xn-location\">China<\/span> in April, which supports BYD&#8217;s Han L and Tai 3 vehicles<\/li>\n<li>Awarded two ComfortFlex programs, one with Volvo, combining ventilation and pneumatic lumbar, and one with Hyundai, combining steering wheel heat with hands on detection<\/li>\n<li>Awarded complete seat programs for key Chinese domestic automakers: BYD, FAW and XPeng<\/li>\n<li>Awarded business in E-Systems totaling over \u2248$750 million in average annual sales<\/li>\n<li>Awarded key wire business with Ford in <span class=\"xn-location\">North America<\/span>, including new conquest volume, and the first wire award with BMW in <span class=\"xn-location\">China<\/span><\/li>\n<li>Awarded the second-generation battery disconnect unit (&#8220;BDU&#8221;) with a key global automaker<\/li>\n<li>Won a 2025 Automotive News PACE award for our innovative Zone Control Module featuring a highly configurable software solution<\/li>\n<\/ul>\n<p>&#8220;Lear delivered a solid start to 2025 by accelerating our operational improvement plans, leading to higher year-over-year margins in both segments, despite lower industry production in our largest markets,&#8221; said <span class=\"xn-person\">Ray Scott<\/span>, Lear&#8217;s President and CEO. &#8220;Changes to global tariffs have created uncertainty for the automotive industry, making it difficult to forecast global production and impacting the cost structure of the global supply chain. As the largest automotive supplier incorporated in <span class=\"xn-location\">the United States<\/span>, Lear is working closely with our customers, suppliers and the administration to ensure we maintain our long-term competitiveness and deliver strong financial returns. We continue to effectively manage the near-term challenges while winning new business and investing in automation and restructuring to further improve margins and extend our leadership position in operational excellence.&#8221;<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prnpr2 prnpl2 prnvab prntal prnsbtb1 prnrbrb1 prnsbbb1 prnsblb1\" colspan=\"4\" rowspan=\"1\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u>First Quarter Financial Results<br \/><\/u><br \/>\n                  <\/b>(in millions, except per share amounts)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"4\" rowspan=\"1\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2025<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen3\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen4\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2024<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Reported <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$5,560.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$5,994.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$80.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$109.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Earnings per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$1.49<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$1.90<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Adjusted<span class=\"prnews_span\"><sup>(1)<\/sup><\/span><\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Core operating earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$270.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$279.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Adjusted net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$169.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$183.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml30\">\n                <span class=\"prnews_span\">Adjusted earnings per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$3.12<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$3.18<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>In the first quarter, global vehicle production was up 1% compared to a year ago, with <span class=\"xn-location\">North America<\/span> down 5%, <span class=\"xn-location\">Europe<\/span> down 7% and <span class=\"xn-location\">China<\/span> up 12%. Global vehicle production was down 5% on a Lear sales-weighted basis<sup>(2)<\/sup>.<\/p>\n<p>Sales in the first quarter were\u00a0$5.6 billion, representing a year-over-year decrease of 7%. Excluding the impact of commodities, foreign exchange, acquisitions and divestitures, sales were down 5%, reflecting lower production on key Lear platforms, partially offset by the addition of new business in both of our business segments.<\/p>\n<p>Core operating earnings were\u00a0$270.4 million, or 4.9% of sales, as compared to <span class=\"xn-money\">$279.8 million<\/span>, or 4.7% of sales, in 2024.\u00a0Earnings were impacted by lower production on key Lear platforms, partially offset by positive operating performance and the addition of new business. Net income was <span class=\"xn-money\">$80.7 million<\/span>, as compared to <span class=\"xn-money\">$109.6 million<\/span> in 2024.<\/p>\n<p>In the Seating segment, margins and adjusted margins were 5.2% and 6.7% of sales, respectively.\u00a0In the E-Systems segment, margins and adjusted margins were 3.9% and 5.2% of sales, respectively.<\/p>\n<p>Earnings per share were\u00a0$1.49 and\u00a0adjusted earnings per share were\u00a0$3.12, as compared to <span class=\"xn-money\">$1.90<\/span> and <span class=\"xn-money\">$3.18<\/span>, respectively, a year ago.<\/p>\n<p>In the first quarter of 2025, net cash used in operating activities was <span class=\"xn-money\">$(128) million<\/span>,\u00a0and free cash flow<sup>(1)<\/sup> was\u00a0$(232) million. As expected, operating cash flow was negatively impacted by the timing of customer receipts and higher cash restructuring costs.<\/p>\n<p>\u00a0<sup>(1)<\/sup> For more information regarding our non-GAAP financial measures, see &#8220;Non-GAAP Financial Information&#8221; below.<\/p>\n<p>\n        <sup>(2)<\/sup>\u00a0The global and regional production changes are based on S&amp;P Global estimates. The production change on a Lear sales-weighted basis is calculated using Lear&#8217;s prior year regional sales mix and first quarter fiscal calendar.\u00a0Management believes this provides a more meaningful comparison of the Company&#8217;s global revenue growth relative to global vehicle production.<\/p>\n<p>\n        <b><br \/>\n          <u>Share Repurchase Program<br \/><\/u><br \/>\n        <\/b>During the first quarter of 2025, Lear repurchased 263,003 shares of our common stock for a total of <span class=\"xn-money\">$25 million<\/span>. At the end of the first quarter, we had a remaining share repurchase authorization of approximately <span class=\"xn-money\">$1<\/span>.1\u00a0billion, which reflects approximately 23% of our total market capitalization at current market prices.<\/p>\n<p>Since initiating the share repurchase program in 2011, we have repurchased 59.3 million shares of our common stock for a total of <span class=\"xn-money\">$5.6 billion<\/span> at an average price of <span class=\"xn-money\">$94.55<\/span> per share. This represents a reduction of approximately 56% of our shares outstanding since the time we began the program<b>.<\/b><\/p>\n<p>\n        <b><br \/>\n          <u>2025 Financial Outlook<br \/><\/u><br \/>\n        <\/b>Given the uncertainty in industry production caused by the evolving tariff environment, we are not reaffirming\u00a0our 2025 financial outlook at this time. We remain confident in delivering the operating performance commitments for 2025 that we highlighted in our <span class=\"xn-chron\">February 2025<\/span> earnings call. We intend to provide updates as visibility on industry production improves.<\/p>\n<p>\n        <b><br \/>\n          <u>First Quarter 2025 Conference Call and Webcast Information<br \/><\/u><br \/>\n        <\/b>A conference call and webcast will be held to discuss Lear&#8217;s first quarter 2025 financial results and related matters on <span class=\"xn-chron\">May 6, 2025<\/span>, at <span class=\"xn-chron\">9:00 a.m. EDT<\/span>. The webcast link for the conference call will be available through Lear&#8217;s investor relations webpage at <a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=4420204-1&amp;h=1041303638&amp;u=https%3A%2F%2Fir.lear.com%2Fevents-and-presentations&amp;a=ir.lear.com\" target=\"_blank\" rel=\"nofollow\">ir.lear.com<\/a>. In addition, the conference call can be accessed by dialing 1-877-883-0383 (domestic) or 1-412-902-6506 (international) with Conference I.D. 6699126. The webcast replay will be available two hours following the call.<\/p>\n<p>\n        <b><br \/>\n          <u>Non-GAAP Financial Information<br \/><\/u><br \/>\n        <\/b>In addition to the results reported in accordance with accounting principles generally accepted in <span class=\"xn-location\">the United States<\/span> (GAAP) included throughout this press release, the Company has provided information regarding &#8220;pretax income before equity income, interest, other expense, restructuring costs and other special items&#8221; (core operating earnings or adjusted segment earnings), &#8220;adjusted net income attributable to Lear&#8221; (adjusted net income), &#8220;adjusted diluted net income per share attributable to Lear&#8221; (adjusted earnings per share) and &#8220;free cash flow&#8221; (each, a non-GAAP financial measure). Other expense includes, among other things, non-income related taxes, foreign exchange gains and losses, gains and losses related to certain derivative instruments and hedging activities, gains and losses on certain disposals of fixed assets and the non-service cost components of net periodic benefit cost. Adjusted net income and adjusted earnings per share represent net income attributable to Lear and diluted net income per share attributable to Lear, respectively, adjusted for restructuring costs and other special items, including the tax effect thereon. Free cash flow represents net cash used in operating activities, less capital expenditures.<\/p>\n<p>Management believes the non-GAAP financial measures used in this press release are useful to both management and investors in their analysis of the Company&#8217;s financial position and results of operations. In particular, management believes that core operating earnings, adjusted net income and adjusted earnings per share are useful measures in assessing the Company&#8217;s financial performance by excluding certain items that are not indicative of the Company&#8217;s core operating performance or that may obscure trends useful in evaluating the Company&#8217;s continuing operating activities. Management also believes that these measures provide improved comparability between fiscal periods. Management believes that free cash flow is useful to both management and investors in their analysis of the Company&#8217;s ability to service and repay its debt. Further, management uses these non-GAAP financial measures for planning and forecasting future periods.<\/p>\n<p>Core operating earnings, adjusted net income, adjusted earnings per share and free cash flow should not be considered in isolation or as a substitute for net income attributable to Lear, diluted net income per share attributable to Lear, cash used in operating activities or other income statement or cash flow statement data prepared in accordance with GAAP or as a measure of profitability or liquidity. In addition, the calculation of free cash flow does not reflect cash used to service debt and, therefore, does not reflect funds available for investment or other discretionary uses. Also, these non-GAAP financial measures, as determined and presented by the Company, may not be comparable to related or similarly titled measures reported by other companies. Set forth below are reconciliations of these non-GAAP financial measures to the most directly comparable financial measures calculated and presented in accordance with GAAP.<\/p>\n<p>\n        <b><br \/>\n          <u>Forward-Looking Statements<\/u><br \/>\n        <\/b><br \/>\n        <br \/>This press release contains forward-looking statements within the meaning of the Private Securities Litigation Reform Act of 1995, including statements regarding anticipated financial results and liquidity. The words &#8220;will,&#8221; &#8220;may,&#8221; &#8220;designed to,&#8221; &#8220;outlook,&#8221; &#8220;believes,&#8221; &#8220;should,&#8221; &#8220;anticipates,&#8221; &#8220;plans,&#8221; &#8220;expects,&#8221; &#8220;intends,&#8221; &#8220;estimates,&#8221; &#8220;forecasts&#8221; and similar expressions identify certain of these forward-looking statements. The Company also may provide forward-looking statements in oral statements or other written materials released to the public. All statements contained or incorporated in this press release or in any other public statements that address operating performance, events or developments that the Company expects or anticipates may occur in the future are forward-looking statements. Factors that could cause actual results to differ materially from these forward-looking statements are discussed in the Company&#8217;s Annual Report on Form 10-K for the year ended <span class=\"xn-chron\">December 31, 2024<\/span>, and its other Securities and Exchange Commission filings. Future operating results will be based on various factors, including actual industry production volumes, the impact of, and our ability to mitigate the effects of, U.S. policy regarding trade, including tariffs and any changes to such tariffs, any response by foreign countries to such policies and tariffs, any resulting volume reductions or changes in vehicle production schedules by our customers, and any other industry disruptions, supply chain disruptions, labor disruptions, commodity prices, changes in foreign exchange rates, the impact of restructuring actions and the Company&#8217;s success in implementing its operating strategy.<\/p>\n<p>Information in this press release relies on assumptions in the Company&#8217;s core sales backlog. The Company&#8217;s core sales backlog reflects anticipated net sales from formally awarded new programs less lost and discontinued programs and excludes the impact of non-core products winding down in our E-Systems business. The Company enters into contracts with its customers to provide production parts generally at the beginning of a vehicle&#8217;s life cycle. Typically, these contracts do not provide for a specified quantity of production, and many of these contracts may be terminated by the Company&#8217;s customers at any time. Therefore, these contracts do not represent firm orders. Further, the calculation of the core sales backlog does not reflect customer price reductions on existing or newly awarded programs. The core sales backlog may be impacted by various assumptions embedded in the calculation, including vehicle production levels on new programs, foreign exchange rates and the timing of major program launches.<\/p>\n<p>The forward-looking statements in this press release are made as of the date hereof, and the Company does not assume any obligation to update, amend or clarify them to reflect events, new information or circumstances occurring after the date hereof.<\/p>\n<p>\n        <b><br \/>\n          <u>About Lear Corporation<br \/><\/u><br \/>\n        <\/b>Lear, a global automotive technology leader in Seating and E-Systems, enables superior in-vehicle experiences for consumers around the world. Lear&#8217;s diverse team of talented employees in 37 countries is driven by a commitment to innovation, operational excellence, and sustainability. Lear is Making every drive better\u2122 by providing the technology for safer, smarter, and more comfortable journeys. Lear, headquartered in <span class=\"xn-location\">Southfield, Michigan<\/span>, serves every major automaker in the world and ranks 174 on the Fortune 500. Further information about Lear is available at lear.com.<\/p>\n<p class=\"prntac\">\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen5\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Lear Corporation and Subsidiaries<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Statements of Income<br \/>\u00a0<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\">(Unaudited; in millions, except per share amounts)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 29,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2025<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 30,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2024<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,560.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,994.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Cost of sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,201.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,596.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Selling, general and administrative expenses<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">172.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">186.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Amortization of intangible assets<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">15.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">25.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">26.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Other expense, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Consolidated income before income taxes and equity in net income of <br \/>affiliates<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">135.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">156.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">45.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">40.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Equity in net income of affiliates<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12.3)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(10.5)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Consolidated net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">102.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">126.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income attributable to noncontrolling interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">21.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">17.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income attributable to Lear<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 80.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 109.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Diluted net income per share attributable to Lear<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1.49<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1.90<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Weighted average number of diluted shares outstanding<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">54.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">57.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\u00a0<\/p>\n<p class=\"prntac\">\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen5\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Lear Corporation and Subsidiaries<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Condensed Consolidated Balance Sheets<br \/>\u00a0<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen3\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(In millions)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 29,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2025<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">December 31,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2024<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\">(Unaudited)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\">(Audited)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">ASSETS<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Current:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 779.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1,052.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Accounts receivable<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,224.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,589.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Inventories<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,681.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,601.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,030.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">940.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,715.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7,184.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Long-Term:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">PP&amp;E, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,846.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,833.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Goodwill<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,723.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,699.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,337.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,310.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,907.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6,843.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total Assets<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 14,623.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 14,027.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">LIABILITIES AND EQUITY<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Current:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Short-term borrowings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 26.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 26.7<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Accounts payable and drafts<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,631.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,250.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Accrued liabilities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,186.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,167.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Current portion of long-term debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,847.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5,447.0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Long-Term:<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Long-term debt<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,733.0<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,733.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,218.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,246.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,951.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3,979.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Equity<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,824.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">4,601.0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Total Liabilities and Equity<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 14,623.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 14,027.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen5\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Lear Corporation and Subsidiaries<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Consolidated Supplemental Data<\/p>\n<p><\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\">(Unaudited; in millions, except content per vehicle and per share amounts)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 29,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2025<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 30,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2024<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">Net Sales<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">North America<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2,248.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2,475.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Europe and Africa<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,062.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2,253.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Asia<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,071.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1,059.7<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">South America<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">177.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">205.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Total<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,560.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5,994.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">Content per Vehicle<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\"><br \/>\n                      <sup>1<\/sup><br \/>\n                    <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">North America<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 609<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 624<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Europe and Africa<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 476<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 476<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">Free Cash Flow<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\"><br \/>\n                      <sup> 2<\/sup><br \/>\n                    <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net cash used in operating activities<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (127.7)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (34.6)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Capital expenditures<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(104.0)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(113.6)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Free cash flow<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (231.7)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (148.2)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">Core Operating Earnings<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\"><br \/>\n                      <sup> 2<\/sup><br \/>\n                    <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income attributable to Lear<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 80.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 109.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Interest expense<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">25.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">26.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other expense, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">20.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Income taxes<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">45.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">40.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Equity in net income of affiliates<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12.3)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(10.5)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Net income attributable to noncontrolling interests<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">21.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">17.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Restructuring costs and other special items &#8211;<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Costs related to restructuring actions<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">87.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">54.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Acquisition costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Disposal costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Impairments (recoveries) related to Fisker Inc., net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.4)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">14.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Impairments (recoveries) related to Russian operations, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1.4)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen11\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13.0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Core operating earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 270.4<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 279.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen5\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Lear Corporation and Subsidiaries<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Consolidated Supplemental Data<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(continued)<br \/>\u00a0<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\">(Unaudited; in millions, except content per vehicle and per share amounts)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 29,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2025<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen9\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 30,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2024<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">Adjusted Net Income and Adjusted Earnings Per Share<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\"><br \/>\n                      <sup> 2<\/sup><br \/>\n                    <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Net income attributable to Lear<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 80.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 109.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Restructuring costs and other special items &#8211;<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Costs related to restructuring actions<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">87.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">54.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Acquisition costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Loss on disposal of non-core business<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Disposal costs<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">0.6<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Impairments (recoveries) related to Fisker Inc., net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.4)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">14.5<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Impairments (recoveries) related to Russian operations, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen6\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1.4)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Loss related to affiliate<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">7.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">13.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Tax impact of special items and other net tax adjustments<sup> 3<\/sup><\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(8.6)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen12\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(12.7)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted net income<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 169.3<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 183.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Weighted average number of diluted shares outstanding<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">54.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">57.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Diluted net income per share available to Lear<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1.49<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1.90<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">Adjusted earnings per share<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3.12<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3.18<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">Diluted Shares Outstanding at the End of Period<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\"><br \/>\n                      <sup>4<\/sup><br \/>\n                    <\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">53,968,155<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen13\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">57,417,052<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>1 <\/sup>Content per Vehicle for 2024 has been updated to reflect actual production levels.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>2 <\/sup>See &#8220;Non-GAAP Financial Information&#8221; included in this press release.<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>3 <\/sup>Represents the tax effect of restructuring costs and other special items, as well as several discrete tax items. <br \/>The identification of these tax items is judgmental in nature, and their calculation is based on various <br \/>assumptions and estimates.<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <sup>4<\/sup> Calculated using stock price at end of quarter.<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen7\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p class=\"prntac\">\u00a0<\/p>\n<div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"1\" class=\"prnbcc\">\n<tr>\n<td class=\"prngen5\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Lear Corporation and Subsidiaries<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Segment Supplemental Data<br \/>\u00a0<\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prngen23\">\n                <span class=\"prnews_span\">(Unaudited; in millions, except margins)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"5\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"3\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Three Months Ended<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen8\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 29,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2025<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prnpr10 prnpl2 prnvab prntar prncbts prnrbrb1 prnsbbb1 prnsblb1\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen10\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prngen23\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">March 30,<\/span><br \/>\n                  <\/b><br \/>\n                  <br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">2024<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <u><br \/>\n                      <span class=\"prnews_span\">Adjusted Segment Earnings<\/span><br \/>\n                    <\/u><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">Seating<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Net sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4,151.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4,477.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Segment earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 215.7<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 241.6<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Restructuring costs and other special items &#8211;<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Costs related to restructuring actions<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">64.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">43.7<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Impairments related to Fisker Inc.<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.3<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Impairments (recoveries) related to Russian operations, net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(1.4)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.4<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.1<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusted segment earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 279.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 294.9<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Segment margins<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.2\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.4\u00a0%<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusted segment margins<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6.7\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">6.6\u00a0%<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\"><br \/>\n                  <b><br \/>\n                    <span class=\"prnews_span\">E-Systems<\/span><br \/>\n                  <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Net sales<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1,409.2<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1,517.0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Segment earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 55.5<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 54.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Restructuring and other special items &#8211;<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Costs related to restructuring actions<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">16.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">8.8<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Impairments (recoveries) related to Fisker Inc., net<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen18\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">(0.4)<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">12.2<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml20\">\n                <span class=\"prnews_span\">Other<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">1.9<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen19\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">2.0<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusted segment earnings<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 73.8<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen17\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">$\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 77.1<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Segment margins<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3.9\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">3.6\u00a0%<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td class=\"prngen5\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml10\">\n                <span class=\"prnews_span\">Adjusted segment margins<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.2\u00a0%<\/span>\n              <\/p>\n<\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen14\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n<p class=\"prnml4\">\n                <span class=\"prnews_span\">5.1\u00a0%<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<td class=\"prngen15\" colspan=\"1\" rowspan=\"1\" nowrap=\"nowrap\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<p id=\"PURL\">\n        <img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/c212.net\/c\/img\/favicon.png?sn=DE80090&amp;sd=2025-05-06\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/news-releases\/lear-reports-first-quarter-2025-results-302446426.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/news-releases\/lear-reports-first-quarter-2025-results-302446426.html<\/a><\/p>\n<p>SOURCE  Lear Corporation<\/p>\n<\/p><\/div>\n<p>    <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=DE80090&amp;Transmission_Id=202505060630PR_NEWS_USPR_____DE80090&amp;DateId=20250506\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PR Newswire SOUTHFIELD, Mich. , May 6, 2025 \/PRNewswire\/ &#8212;\u00a0Lear Corporation (NYSE: LEA), a global automotive technology leader in Seating and E-Systems, today reported results for the first quarter 2025. First Quarter 2025 Highlights Delivered revenue of $5.6 billion in the first quarter, compared to $6.0 billion in the first quarter of 2024 Net income of $81 million and adjusted net income of $169 million, compared to $110 million and $183 million, respectively, in the first quarter of 2024 Core operating earnings of $270 million, compared to $280 million in the first quarter of 2024 Earnings per share of $1.49 and adjusted earnings per share of $3.12, compared to $1.90 and $3.18, respectively, in the first quarter of 2024 Net &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Lear Reports First Quarter 2025 Results&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-846984","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lear Reports First Quarter 2025 Results - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lear Reports First Quarter 2025 Results - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"PR Newswire SOUTHFIELD, Mich. , May 6, 2025 \/PRNewswire\/ &#8212;\u00a0Lear Corporation (NYSE: LEA), a global automotive technology leader in Seating and E-Systems, today reported results for the first quarter 2025. First Quarter 2025 Highlights Delivered revenue of $5.6 billion in the first quarter, compared to $6.0 billion in the first quarter of 2024 Net income of $81 million and adjusted net income of $169 million, compared to $110 million and $183 million, respectively, in the first quarter of 2024 Core operating earnings of $270 million, compared to $280 million in the first quarter of 2024 Earnings per share of $1.49 and adjusted earnings per share of $3.12, compared to $1.90 and $3.18, respectively, in the first quarter of 2024 Net &hellip; Continue reading &quot;Lear Reports First Quarter 2025 Results&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T10:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.jpg\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"Lear Reports First Quarter 2025 Results\",\"datePublished\":\"2025-05-06T10:34:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/\"},\"wordCount\":2494,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/460765\\\/LEAR_LOGO.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/\",\"name\":\"Lear Reports First Quarter 2025 Results - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/460765\\\/LEAR_LOGO.jpg\",\"datePublished\":\"2025-05-06T10:34:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/460765\\\/LEAR_LOGO.jpg\",\"contentUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/460765\\\/LEAR_LOGO.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/lear-reports-first-quarter-2025-results\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lear Reports First Quarter 2025 Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lear Reports First Quarter 2025 Results - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/","og_locale":"en_US","og_type":"article","og_title":"Lear Reports First Quarter 2025 Results - Market Newsdesk","og_description":"PR Newswire SOUTHFIELD, Mich. , May 6, 2025 \/PRNewswire\/ &#8212;\u00a0Lear Corporation (NYSE: LEA), a global automotive technology leader in Seating and E-Systems, today reported results for the first quarter 2025. First Quarter 2025 Highlights Delivered revenue of $5.6 billion in the first quarter, compared to $6.0 billion in the first quarter of 2024 Net income of $81 million and adjusted net income of $169 million, compared to $110 million and $183 million, respectively, in the first quarter of 2024 Core operating earnings of $270 million, compared to $280 million in the first quarter of 2024 Earnings per share of $1.49 and adjusted earnings per share of $3.12, compared to $1.90 and $3.18, respectively, in the first quarter of 2024 Net &hellip; Continue reading \"Lear Reports First Quarter 2025 Results\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/","og_site_name":"Market Newsdesk","article_published_time":"2025-05-06T10:34:43+00:00","og_image":[{"url":"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.jpg","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"Lear Reports First Quarter 2025 Results","datePublished":"2025-05-06T10:34:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/"},"wordCount":2494,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/","name":"Lear Reports First Quarter 2025 Results - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.jpg","datePublished":"2025-05-06T10:34:43+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/#primaryimage","url":"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.jpg","contentUrl":"https:\/\/mma.prnewswire.com\/media\/460765\/LEAR_LOGO.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/lear-reports-first-quarter-2025-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"Lear Reports First Quarter 2025 Results"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/846984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=846984"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/846984\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=846984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=846984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=846984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}