{"id":525849,"date":"2021-08-10T07:33:27","date_gmt":"2021-08-10T11:33:27","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/"},"modified":"2021-08-10T07:33:27","modified_gmt":"2021-08-10T11:33:27","slug":"fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/","title":{"rendered":"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update"},"content":{"rendered":"<div class=\"xn-newslines\">\n<p class=\"xn-distributor\">PR Newswire<\/p>\n<\/p><\/div>\n<div class=\"xn-content\">\n<p>\n        <i>Phase 1 study of FPI-1434 progressing towards\u00a0multi-dose data and recommended Phase 2 dose in 1H2022<\/i>\n      <\/p>\n<p>\n        <i>FPI-1966 advancing to clinic<\/i>\n      <\/p>\n<p>\n        <span class=\"xn-location\">HAMILTON, ON<\/span> and <span class=\"xn-location\">BOSTON<\/span>, <span class=\"xn-chron\">Aug. 10, 2021<\/span> \/PRNewswire\/ &#8212;\u00a0Fusion Pharmaceuticals Inc. (Nasdaq: FUSN), a clinical-stage oncology company focused on developing next-generation radiopharmaceuticals as precision medicines, today announced financial results for the second quarter ended <span class=\"xn-chron\">June 30, 2021<\/span> and provided an update on clinical and corporate developments.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder1\">\n<p>\n          <a href=\"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.html\" target=\"_blank\" rel=\"nofollow noopener\"><br \/>\n            <img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.jpg\" title=\"(PRNewsfoto\/Fusion Pharmaceuticals Inc.)\" alt=\"(PRNewsfoto\/Fusion Pharmaceuticals Inc.)\" \/><br \/>\n          <\/a>\n        <\/p>\n<\/p><\/div>\n<p>&#8220;We are building a fully integrated radiopharmaceutical company based upon our platform, reflecting a diverse pipeline of targeted alpha therapies in development supported by manufacturing and supply chain expertise,&#8221; said Chief Executive Officer <span class=\"xn-person\">John Valliant<\/span>, Ph.D. &#8220;We expect to have three clinical programs employing differentiated radiopharmaceuticals underway by mid-next year. In addition to our ongoing Phase 1 study of FPI-1434, the investigational new drug application (IND) of FPI-1966 was recently cleared by the U.S. Food &amp; Drug Administration (FDA), and we intend to submit an IND application for FPI-2059 in the first half of 2022. In parallel, we are quickly advancing programs under our partnership agreement with AstraZeneca and are planning for a combination study of FPI-1434 with KEYTRUDA\u00ae (pembrolizumab).&#8221;<\/p>\n<p>Dr. Valliant continued, &#8220;These programs, along with our work to build Fusion&#8217;s radiopharmaceutical manufacturing capabilities with a new facility, demonstrate the depth and versatility of our pipeline and the potential to use our expertise to create innovative treatments for a broad array of solid tumors with high unmet medical need.&#8221;<\/p>\n<p>\n        <b>Recent Highlights and Future Milestones<\/b>\n      <\/p>\n<p>Corporate Updates<\/p>\n<ul type=\"disc\">\n<li>On <span class=\"xn-chron\">July 28<\/span>, <a target=\"_blank\" href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=3253950-1&amp;h=2544510345&amp;u=https%3A%2F%2Fir.fusionpharma.com%2F2021-07-28-Fusion-Pharmaceuticals-Announces-FDA-Clearance-of-IND-for-FPI-1966%2C-an-Investigational-Radiopharmaceutical-for-the-Treatment-of-Head-and-Neck-and-Bladder-Cancers-Expressing-FGFR3&amp;a=Fusion+announced+the+FDA+cleared+the+Company%27s+Investigational+New+Drug+(IND)+application+for+FPI-1966\" rel=\"nofollow noopener\">Fusion announced the FDA cleared the Company&#8217;s Investigational New Drug (IND) application for FPI-1966<\/a>. FPI-1966 is a targeted alpha therapy (TAT) designed to use vofatamab, a human monoclonal antibody, to target and deliver actinium-225 to tumor sites expressing fibroblast growth factor 3 (FGFR3), a protein that is overexpressed in multiple tumor types, particularly head and neck and bladder cancers. Fusion plans to initiate a Phase 1, non-randomized, open-label clinical trial in patients with solid tumors expressing FGFR3 intended to investigate safety, tolerability and pharmacokinetics and to establish the recommended Phase 2 dose. The Company anticipates initiating the Phase 1 study around the end of 2021 and reporting interim data from the first patient cohort around the end of 2022. <\/li>\n<li>On <span class=\"xn-chron\">June 14<\/span>, <a target=\"_blank\" href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=3253950-1&amp;h=3700316935&amp;u=https%3A%2F%2Fir.fusionpharma.com%2F2021-06-14-Fusion-Pharmaceuticals-Announces-Preliminary-Safety-and-Dosimetry-Results-from-its-Single-Dose-Portion-of-the-Phase-1-Study-of-FPI-1434&amp;a=Fusion+announced+the+presentation+of+preliminary+Phase+1+data\" rel=\"nofollow noopener\">Fusion announced the presentation of preliminary Phase 1 data<\/a> from the single-dose portion of the study at the Society of Nuclear Medicine and Molecular Imaging (SNMMI) Virtual Annual Meeting. Results from the first three patient cohorts (n=12) demonstrated a favorable safety profile for FPI-1434. No drug-related serious adverse events and\/or dose limiting toxicity were reported in administered activity up to 40kBq\/kg body weight and dosimetric results were within normal organ radiation tolerability limits. <\/li>\n<li>On <span class=\"xn-chron\">June 14<\/span>, <a target=\"_blank\" href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=3253950-1&amp;h=884308460&amp;u=https%3A%2F%2Fir.fusionpharma.com%2F2021-06-14-Fusion-Pharmaceuticals-Announces-Preliminary-Safety-and-Dosimetry-Results-from-its-Single-Dose-Portion-of-the-Phase-1-Study-of-FPI-1434&amp;a=Fusion+also+announced+preclinical+data\" rel=\"nofollow noopener\">Fusion also announced preclinical data<\/a> demonstrating synergistic efficacy against olaparib-resistant colorectal and radioresistant lung cancer xenografts when combining FPI-1434 with olaparib, and preclinical data showing that treatment with FPI-1434 in combination with immune checkpoint inhibitors resulted in complete tumor eradication. <\/li>\n<li>On <span class=\"xn-chron\">June 2<\/span>, <a target=\"_blank\" href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=3253950-1&amp;h=4127336729&amp;u=https%3A%2F%2Fir.fusionpharma.com%2F2021-06-02-Fusion-Pharmaceuticals-Enters-into-Agreement-to-Build-Radiopharmaceutical-Manufacturing-Facility&amp;a=Fusion+announced+that+the+Company+entered+a+15-year+lease+agreement\" rel=\"nofollow noopener\">Fusion announced that the Company entered a 15-year lease agreement<\/a> with <span class=\"xn-location\">Hamilton, Ontario<\/span>-based <span class=\"xn-org\">McMaster University<\/span> to build a 27,000 square foot current Good Manufacturing Practice (GMP) compliant radiopharmaceutical manufacturing facility. The facility, to be built by <span class=\"xn-org\">McMaster<\/span> and equipped and validated by Fusion, will be designed to support manufacturing of the Company&#8217;s growing pipeline of targeted alpha therapies (TATs).<\/li>\n<\/ul>\n<p>FPI-1434 Monotherapy<\/p>\n<ul type=\"disc\">\n<li>Fusion continues to advance the multi-dose portion of its Phase 1 study evaluating FPI-1434 in patients with advanced solid tumors. The dose-finding study is enrolling patients at sites in <span class=\"xn-location\">Canada<\/span>, <span class=\"xn-location\">the United States<\/span> and <span class=\"xn-location\">Australia<\/span>. <\/li>\n<li>Fusion anticipates reporting Phase 1 multi-dose safety and imaging data, and the recommended Phase 2 dose and schedule, in the first half of 2022.<\/li>\n<\/ul>\n<p>FPI-1434 Combination Therapy<\/p>\n<ul type=\"disc\">\n<li>Fusion has evaluated FPI-1434 in preclinical studies in combination with approved checkpoint and DNA damage response inhibitors, including PARP inhibitors, and believes the synergies observed could expand the addressable patient populations for FPI-1434 and allow for potential use in earlier lines of treatment. <\/li>\n<li>Fusion anticipates the initiation of a Phase 1 combination study with FPI-1434 and KEYTRUDA\u00ae (pembrolizumab) to occur six to nine months following determination of the recommended Phase 2 dose of FPI-1434 monotherapy. <\/li>\n<\/ul>\n<p>FPI-2059<\/p>\n<ul type=\"disc\">\n<li>FPI-2059 is a small molecule radioconjugate in development as a targeted alpha therapy for various solid tumors. The molecule targets neurotensin receptor 1 (NTSR1), a promising target for cancer treatment, that is overexpressed in multiple solid tumors. FPI-2059 combines Ipsen&#8217;s IPN-1087, which Fusion acquired in 2021, with actinium-225. Fusion anticipates submitting an IND application for FPI-2059 in the first half of 2022.<\/li>\n<\/ul>\n<p>\n        <b>Second Quarter 2021 Financial Results<\/b>\n      <\/p>\n<ul type=\"disc\">\n<li>\n          <b>Cash and Investments:<\/b> As of <span class=\"xn-chron\">June 30, 2021<\/span>, Fusion held cash, cash equivalents and investments of <span class=\"xn-money\">$260.5 million<\/span>, compared to cash, cash equivalents and investments of <span class=\"xn-money\">$299.5 million<\/span> as of <span class=\"xn-chron\">December 31, 2020<\/span>. Fusion expects its cash, cash equivalents and investments as of <span class=\"xn-chron\">June 30, 2021<\/span> will enable the Company to fund its operations through the end of 2023. <\/li>\n<li>\n          <b>Collaboration Revenue:<\/b> For the second quarter of 2021, Fusion recorded <span class=\"xn-money\">$0.5 million<\/span> of revenue under the AstraZeneca collaboration agreement. <\/li>\n<li>\n          <b>R&amp;D Expenses:<\/b> Research and development expenses for the second quarter of 2021 were <span class=\"xn-money\">$21.1 million<\/span>, compared to <span class=\"xn-money\">$3.3 million<\/span> for the same period in 2020. The increase was primarily related to increased platform development and research activities, clinical activities related to the ongoing Phase 1 clinical trial of FPI-1434, asset purchase agreements and preclinical research and manufacturing costs. <\/li>\n<li>\n          <b>G&amp;A Expenses:<\/b> General and administrative expenses for the second quarter of 2021 were <span class=\"xn-money\">$6.6 million<\/span>, compared to <span class=\"xn-money\">$4.0 million<\/span> for the same period in 2020. The increase was primarily related to personnel related costs, including salary, benefits and stock compensation due to hiring, as well as general corporate costs, including expenses for general corporate, director and officer insurance. <\/li>\n<li>\n          <b>Net Loss:<\/b> For the second quarter of 2021, Fusion reported a net loss of <span class=\"xn-money\">$26.9 million<\/span>, or <span class=\"xn-money\">$0.63<\/span> per share, compared with a net loss of <span class=\"xn-money\">$44.7 million<\/span>, or <span class=\"xn-money\">$18.91<\/span> per share, for the same period in 2020. On a non-GAAP basis, excluding a change in fair value of preferred share tranche right liability and warrant liability, net loss was <span class=\"xn-money\">$7.1 million<\/span> for the second quarter of 2020. <\/li>\n<\/ul>\n<p>\n        <b>Impact of COVID-19<\/b>\n      <\/p>\n<p>While Fusion is progressing the multi-dosing portion of the Phase 1 clinical trial of FPI-1434, the Company has experienced material delays in patient recruitment and enrollment as a result of continued resourcing issues related to COVID-19 at trial sites. <\/p>\n<p>Moreover, there remains uncertainty relating to the trajectory of the pandemic and whether it may cause further delays in patient study recruitment. The impact of related responses and disruptions caused by the COVID-19 pandemic may result in difficulties or delays in initiating, enrolling, conducting or completing the planned and ongoing trials and the incurrence of unforeseen costs as a result of disruptions in clinical supply or preclinical study or clinical trial delays. The continued impact of COVID-19 on results will largely depend on future developments, which are highly uncertain and cannot be predicted with confidence.<\/p>\n<p>\n        <b>About Fusion<br \/><\/b>Fusion Pharmaceuticals is a clinical-stage oncology company focused on developing next-generation radiopharmaceuticals as precision medicines. Employing a proprietary Fast-Clear\u2122 linker technology, Fusion connects alpha particle emitting isotopes to various targeting molecules in order to selectively deliver the alpha emitting payloads to tumors.<\/p>\n<p>Fusion&#8217;s lead program, FPI-1434 targeting insulin-like growth factor 1 receptor, is currently in a Phase 1 clinical trial. The pipeline includes FPI-1966 targeting the fibroblast growth factor receptor 3 (FGFR3) and FPI-2059, a small molecule recently acquired from Ipsen, targeting neurotensin receptor 1 (NTSR1). In addition to a robust proprietary pipeline, Fusion has a collaboration with AstraZeneca to jointly develop up to three novel targeted alpha therapies (TATs) and explore up to five combination programs between Fusion&#8217;s TATs and AstraZeneca&#8217;s DNA Damage Repair Inhibitors (DDRis) and immuno-oncology agents. Fusion also entered into a collaboration with Merck to evaluate FPI-1434 in combination with Merck&#8217;s KEYTRUDA\u00ae (pembrolizumab) in patients with solid tumors expressing IGF-1R.<\/p>\n<p>\n        <b>Forward-Looking Statements<br \/><\/b>Certain statements set forth in this press release constitute &#8220;forward-looking&#8221; statements within the meaning of the Private Securities Litigation Reform Act of 1995, as amended. Forward-looking statements can be identified by terms such as &#8220;believes,&#8221; &#8220;expects,&#8221; &#8220;plans,&#8221; &#8220;potential,&#8221; &#8220;would&#8221; or similar expressions and the negative of those terms. Such forward-looking statements involve substantial risks and uncertainties that could cause Fusion&#8217;s research and clinical development programs, future results, performance or achievements to differ significantly from those expressed or implied by the forward-looking statements. Such risks and uncertainties include, among others, the uncertainties inherent in the drug development process, including Fusions&#8217; programs&#8217; early stage of development, the ability to move in-licensed targets forward in the clinic, \u00a0the process of designing and conducting preclinical and clinical trials, the regulatory approval processes, the timing of regulatory filings, the challenges associated with manufacturing drug products generally and radiopharmaceuticals specifically, Fusion&#8217;s ability to successfully establish, protect and defend its intellectual property, risks relating to business interruptions resulting from the coronavirus (COVID-19) disease outbreak or similar public health crises and other matters that could affect the sufficiency of existing cash to fund operations. Fusion undertakes no obligation to update or revise any forward-looking statements. For a further description of the risks and uncertainties that could cause actual results to differ from those expressed in these forward-looking statements, as well as risks relating to the business of the company in general, see Fusion&#8217;s annual report on Form 10-Q for the quarter ended <span class=\"xn-chron\">March 31, 2021<\/span> which is available on the Securities and Exchange Commission&#8217;s website at <a href=\"http:\/\/www.sec.gov\" rel=\"nofollow\">www.sec.gov<\/a> and Fusion&#8217;s website at <a href=\"http:\/\/www.fusionpharma.com\" rel=\"nofollow\">www.fusionpharma.com<\/a>.\u00a0 <\/p>\n<p>Investors and others should note that Fusion communicates with its investors and the public using the Fusion website, <a href=\"http:\/\/www.fusionpharma.com\" rel=\"nofollow\">www.fusionpharma.com<\/a>, including, but not limited to, company disclosures, investor presentations, SEC filings, and press releases. The information that Fusion posts on this website could be deemed to be material information. As a result, Fusion encourages investors, media and others interested to review the information that Fusion posts there on a regular basis.<\/p>\n<p>\u00a0<\/p>\n<div>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" class=\"prntblns\">\n<tr>\n<td colspan=\"5\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>FUSION PHARMACEUTICALS INC. <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>CONDENSED CONSOLIDATED BALANCE SHEETS <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(In thousands, except share amounts) <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(Unaudited) <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"5\" nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen4\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>June\u00a030,<br \/>2021<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen4\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>December\u00a031,<br \/>2020<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Assets<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Current assets:<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Cash and cash equivalents<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 27,615<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 90,517<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accounts receivable<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">121<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Short-term investments<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">150,904<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">131,882<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Prepaid expenses and other current assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">5,847<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">5,340<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Restricted cash<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">669<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">425<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total current assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">185,156<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">228,164<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Property and equipment, net<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">2,659<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,967<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Deferred tax assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,067<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">653<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Restricted cash<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,222<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,466<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Long-term investments<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">81,974<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">77,082<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Operating lease right-of-use assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">7,224<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Other non-current assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">2,854<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,344<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen9\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 282,156<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen9\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 310,676<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Liabilities and Shareholders&#8217; Equity<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Current liabilities:<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accounts payable<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0685<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 3,399<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accrued expenses<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">5,682<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">4,659<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Income taxes payable<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">2,799<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Deferred revenue<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,733<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,000<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Operating lease liabilities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,265<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total current liabilities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">9,365<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">11,857<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Deferred rent, net of current portion<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">11<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Income taxes payable, net of current portion<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">295<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">295<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Deferred revenue, net of current portion<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">2,867<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">4,000<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Operating lease liabilities, net of current portion<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">6,078<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total liabilities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">18,605<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">16,163<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Commitments and contingencies<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Shareholders&#8217; equity:<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Common shares, no par value, unlimited shares authorized as of June\u00a030, 2021 <br \/>\u00a0\u00a0 and December\u00a031, 2020; 42,621,099 and 41,725,797 shares issued and outstanding as of<br \/>\u00a0\u00a0 June\u00a030, 2021 and December\u00a031, 2020, respectively<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Additional paid-in capital<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">420,799<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">407,672<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accumulated other comprehensive income<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">337<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">44<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accumulated deficit<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(157,585)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(113,203)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total shareholders&#8217; equity<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen12\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">263,551<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen12\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">294,513<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total liabilities and shareholders&#8217; equity<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen9\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 282,156<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen9\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 310,676<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<p \/>\n<p \/>\n<div>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" class=\"prntblns\">\n<tr>\n<td colspan=\"9\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>FUSION PHARMACEUTICALS INC. <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>CONDENSED CONSOLIDATED STATEMENTS OF OPERATIONS AND COMPREHENSIVE LOSS <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(In thousands, except share and per share amounts) <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(Unaudited) <\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"9\" nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td colspan=\"3\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months Ended<br \/>June\u00a030,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td colspan=\"3\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Six Months Ended<br \/>June\u00a030,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2021<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2020<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2021<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2020<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Collaboration revenue<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 521<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 521<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Operating expenses:<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Research and development<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">21,146<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">3,325<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">31,862<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">7,702<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">General and administrative<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">6,642<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">3,988<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">13,606<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">8,315<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total operating expenses<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">27,788<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">7,313<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">45,468<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">16,017<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Loss from operations<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen15\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(27,267)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen15\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(7,313)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen15\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,947)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen15\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(16,017)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Other income (expense):<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Change in fair value of preferred share tranche right liability<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(31,604)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(32,722)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Change in fair value of preferred share warrant liability<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(6,065)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(6,399)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Interest income (expense), net<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">97<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">22<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">193<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">169<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Refundable investment tax credits<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">52<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">98<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Other income (expense), net<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">331<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">325<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">379<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">128<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Total other income (expense), net<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">428<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen16\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(37,270)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen10\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">572<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen16\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(38,726)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Loss before provision for income taxes<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(26,839)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,583)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,375)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(54,743)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Income tax provision<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(14)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(150)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(7)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(212)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net loss<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(26,853)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,733)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,382)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(54,955)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Unrealized gain on investments<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">54<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">293<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Comprehensive loss<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(26,799)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,733)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,089)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(54,955)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Reconciliation of net loss to net loss attributable to common shareholders:<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net loss<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(26,853)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,733)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(44,382)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(54,955)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Dividends paid to preferred shareholders in the form of<br \/>\u00a0\u00a0 warrants issued<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(1,382)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net loss attributable to common shareholders<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0(26,853)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0(44,733)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0(44,382)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0(56,337)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net loss per share attributable to common shareholders\u2014basic and<br \/>\u00a0\u00a0 diluted<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(0.63)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(18.91)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(1.05)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen18\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(26.23)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Weighted-average common shares outstanding\u2014basic and diluted<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen19\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">42,501,321<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen19\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">2,366,198<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen19\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">42,145,435<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen19\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">2,147,876<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<div>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" class=\"prntblns\">\n<tr>\n<td colspan=\"5\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>FUSION PHARMACEUTICALS INC. <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>CONDENSED CONSOLIDATED STATEMENTS OF CASH FLOWS <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(In thousands) <\/b><br \/>\n                <\/span>\n              <\/p>\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(Unaudited)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"5\" nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td colspan=\"3\" nowrap=\"nowrap\" class=\"prngen4\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Six Months Ended June\u00a030,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen20\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2021<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen20\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2020<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash flows from operating activities:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net loss<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(44,382)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(54,955)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Adjustments to reconcile net loss to net cash used in operating activities:<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Share-based compensation expense<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">3,863<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">784<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Depreciation and amortization expense<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">265<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">270<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Non-cash lease expense<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">516<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">14<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Change in fair value of preferred share tranche right liability<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">32,722<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Change in fair value of preferred share warrant liability<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">6,399<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Amortization of premiums (accretion of discounts) on investments, net<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">924<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Deferred tax benefit<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(413)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Common shares issued to acquire in-process research &amp; development<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">8,924<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Foreign exchange loss<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">36<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Changes in operating assets and liabilities:<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accounts receivable<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(121)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Prepaid expenses and other current assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(374)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(103)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Other non-current assets<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(1,509)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accounts payable<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(2,687)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(319)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Accrued expenses<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">673<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">1,209<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Deferred revenue<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(400)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Income taxes payable<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(2,800)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">162<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Operating lease liabilities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(418)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net cash used in operating activities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen16\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(37,903)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen16\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(13,817)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash flows from investing activities:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Purchases of investments<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(132,137)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Maturities of investments<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">107,591<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Purchases of property and equipment<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(793)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(382)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net cash used in investing activities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(25,339)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen17\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(382)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Cash flows from financing activities:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Proceeds from issuance of Class B convertible preferred shares and Class B preferred<br \/>\u00a0\u00a0 share tranche right, net of issuance costs<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">65,676<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Proceeds from issuance of Class B preferred exchangeable shares of Fusion<br \/>\u00a0\u00a0 Pharmaceuticals (Ireland) Limited and Class B preferred share tranche right,<br \/>\u00a0\u00a0 net of issuance costs<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">6,722<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Proceeds from the issuance of common shares upon closing of initial public offering,<br \/>\u00a0\u00a0\u00a0\u00a0 net of underwriter fees<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">197,625<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Payment of offering costs<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(2,276)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Proceeds from issuance of common shares upon exercise of stock options<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">340<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Net cash provided by financing activities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">340<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen7\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">267,747<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Net (decrease) increase in cash, cash equivalents and restricted cash<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(62,902)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">253,548<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Cash, cash equivalents and restricted cash at beginning of period<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">92,408<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">67,121<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Cash, cash equivalents and restricted cash at end of period<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen9\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a029,506<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen9\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0320,669<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Supplemental disclosure of cash flow information:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Cash paid for income taxes<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a03,494<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 50<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Right-of-use assets obtained in exchange for new operating lease liabilities<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01,166<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Increase in right-of-use assets and operating lease liabilities from operating lease<br \/>\u00a0\u00a0 modifications<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 911<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Supplemental disclosure of non-cash investing and financing activities:<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Purchases of property and equipment included in accounts payable and accrued expenses<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 199<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Issuance of warrants to purchase Class B preferred shares and Class B preferred<br \/>\u00a0\u00a0 exchangeable shares as a non-cash dividend to preferred shareholders<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01,382<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Deferred offering costs included in accounts payable and accrued expenses<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 160<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02,296<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<p \/>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<div>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" class=\"prntblns\">\n<tr>\n<td colspan=\"9\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>FUSION PHARMACEUTICALS INC.<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"9\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>RECONCILIATION OF GAAP TO NON-GAAP FINANCIAL RESULTS<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"9\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(In thousands)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"9\" nowrap=\"nowrap\" class=\"prngen2\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>(Unaudited)<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td colspan=\"3\" nowrap=\"nowrap\" class=\"prngen4\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Three Months Ended<br \/>June\u00a030,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td colspan=\"3\" nowrap=\"nowrap\" class=\"prngen4\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>Six Months Ended<br \/>June\u00a030,<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2021<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2020<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2021<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen14\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen13\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\"><br \/>\n                  <b>2020<\/b><br \/>\n                <\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">GAAP Net loss<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(26,853)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (44,733)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (44,382)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (54,955)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen6\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Less: Adjustments<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Change in fair value of preferred share tranche right liability<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(31,604)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(32,722)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen8\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Change in fair value of preferred share warrant liability<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(6,065)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">\u2014<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen11\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">(6,399)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen5\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">Non-GAAP Net loss<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen21\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(26,853)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen21\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (7,064)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen21\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (44,382)<\/span>\n              <\/p>\n<\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen21\">\n<p class=\"prnews_p\">\n                <span class=\"prnews_span\">$ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (15,834)<\/span>\n              <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<td nowrap=\"nowrap\" class=\"prngen3\">\n              \n            <\/td>\n<\/tr>\n<\/table><\/div>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder2\"><\/div>\n<p id=\"PURL\">\n        <img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/c212.net\/c\/img\/favicon.png?sn=NE69488&amp;sd=2021-08-10\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/news-releases\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update-301351413.html\">https:\/\/www.prnewswire.com\/news-releases\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update-301351413.html<\/a><\/p>\n<p>SOURCE  Fusion Pharmaceuticals Inc.<\/p>\n<\/p><\/div>\n<p>    <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=NE69488&amp;Transmission_Id=202108100730PR_NEWS_USPR_____NE69488&amp;DateId=20210810\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PR Newswire Phase 1 study of FPI-1434 progressing towards\u00a0multi-dose data and recommended Phase 2 dose in 1H2022 FPI-1966 advancing to clinic HAMILTON, ON and BOSTON, Aug. 10, 2021 \/PRNewswire\/ &#8212;\u00a0Fusion Pharmaceuticals Inc. (Nasdaq: FUSN), a clinical-stage oncology company focused on developing next-generation radiopharmaceuticals as precision medicines, today announced financial results for the second quarter ended June 30, 2021 and provided an update on clinical and corporate developments. &#8220;We are building a fully integrated radiopharmaceutical company based upon our platform, reflecting a diverse pipeline of targeted alpha therapies in development supported by manufacturing and supply chain expertise,&#8221; said Chief Executive Officer John Valliant, Ph.D. &#8220;We expect to have three clinical programs employing differentiated radiopharmaceuticals underway by mid-next year. In addition to &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-525849","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"PR Newswire Phase 1 study of FPI-1434 progressing towards\u00a0multi-dose data and recommended Phase 2 dose in 1H2022 FPI-1966 advancing to clinic HAMILTON, ON and BOSTON, Aug. 10, 2021 \/PRNewswire\/ &#8212;\u00a0Fusion Pharmaceuticals Inc. (Nasdaq: FUSN), a clinical-stage oncology company focused on developing next-generation radiopharmaceuticals as precision medicines, today announced financial results for the second quarter ended June 30, 2021 and provided an update on clinical and corporate developments. &#8220;We are building a fully integrated radiopharmaceutical company based upon our platform, reflecting a diverse pipeline of targeted alpha therapies in development supported by manufacturing and supply chain expertise,&#8221; said Chief Executive Officer John Valliant, Ph.D. &#8220;We expect to have three clinical programs employing differentiated radiopharmaceuticals underway by mid-next year. In addition to &hellip; Continue reading &quot;Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-10T11:33:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.jpg\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update\",\"datePublished\":\"2021-08-10T11:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/\"},\"wordCount\":2316,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/1196797\\\/Fusion_Pharmaceuticals_Logo.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/\",\"name\":\"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/1196797\\\/Fusion_Pharmaceuticals_Logo.jpg\",\"datePublished\":\"2021-08-10T11:33:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/1196797\\\/Fusion_Pharmaceuticals_Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mma.prnewswire.com\\\/media\\\/1196797\\\/Fusion_Pharmaceuticals_Logo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/","og_locale":"en_US","og_type":"article","og_title":"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update - Market Newsdesk","og_description":"PR Newswire Phase 1 study of FPI-1434 progressing towards\u00a0multi-dose data and recommended Phase 2 dose in 1H2022 FPI-1966 advancing to clinic HAMILTON, ON and BOSTON, Aug. 10, 2021 \/PRNewswire\/ &#8212;\u00a0Fusion Pharmaceuticals Inc. (Nasdaq: FUSN), a clinical-stage oncology company focused on developing next-generation radiopharmaceuticals as precision medicines, today announced financial results for the second quarter ended June 30, 2021 and provided an update on clinical and corporate developments. &#8220;We are building a fully integrated radiopharmaceutical company based upon our platform, reflecting a diverse pipeline of targeted alpha therapies in development supported by manufacturing and supply chain expertise,&#8221; said Chief Executive Officer John Valliant, Ph.D. &#8220;We expect to have three clinical programs employing differentiated radiopharmaceuticals underway by mid-next year. In addition to &hellip; Continue reading \"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/","og_site_name":"Market Newsdesk","article_published_time":"2021-08-10T11:33:27+00:00","og_image":[{"url":"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.jpg","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update","datePublished":"2021-08-10T11:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/"},"wordCount":2316,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/","name":"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/#primaryimage"},"thumbnailUrl":"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.jpg","datePublished":"2021-08-10T11:33:27+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/#primaryimage","url":"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.jpg","contentUrl":"https:\/\/mma.prnewswire.com\/media\/1196797\/Fusion_Pharmaceuticals_Logo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/fusion-pharmaceuticals-announces-second-quarter-2021-financial-results-and-business-update\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"Fusion Pharmaceuticals Announces Second Quarter 2021 Financial Results and Business Update"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/525849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=525849"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/525849\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=525849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=525849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=525849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}