{"id":522407,"date":"2021-08-03T16:09:42","date_gmt":"2021-08-03T20:09:42","guid":{"rendered":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/"},"modified":"2021-08-03T16:09:42","modified_gmt":"2021-08-03T20:09:42","slug":"new-relic-announces-first-quarter-fiscal-year-2022-results","status":"publish","type":"post","link":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/","title":{"rendered":"New Relic Announces First Quarter Fiscal Year 2022 Results"},"content":{"rendered":"<p>        <!--.bwalignc { text-align: center; list-style-position: inside }\n.bwalignl { text-align: left }\n.bwalignr { text-align: right; list-style-position: inside }\n.bwblockalignl { margin-left: 0px; margin-right: auto }\n.bwcellpmargin { margin-bottom: 0px; margin-top: 0px }\n.bwdoublebottom { border-bottom: double black 2.25pt }\n.bwleftsingle { border-left: solid black 1pt }\n.bwlistcircle { list-style-type: circle }\n.bwlistdisc { list-style-type: disc }\n.bwnowrap { white-space: nowrap }\n.bwpadl0 { padding-left: 0px }\n.bwpadl3 { padding-left: 15px }\n.bwpadl6 { padding-left: 30px }\n.bwpadr0 { padding-right: 0px }\n.bwrightsingle { border-right: solid black 1pt }\n.bwrowaltcolor0 { background-color: #cceeff }\n.bwsinglebottom { border-bottom: solid black 1pt }\n.bwtablemarginb { margin-bottom: 10px }\n.bwtopsingle { border-top: solid black 1pt }\n.bwuline { text-decoration: underline }\n.bwvertalignb { vertical-align: bottom }\n.bwvertalignt { vertical-align: top }body {font:normal small Arial,Helvetica,sans-serif;color:#000;background-color:#fff;padding:24px;margin:0;} a img {border:0;} h3 {font-size:medium;color:#000;margin:0 0 1em 0; text-align:center;}-->  <\/p>\n<p class=\"bwalignc\">\n\u00a0<b>New Relic Announces First Quarter Fiscal Year 2022 Results<\/b><\/p>\n<p class=\"bwalignc\">\n\u00a0<i>First quarter revenue increased 11% year-over-year to $180 million<br \/>\n<br \/><\/i><i>Quarterly GAAP operating loss of $(73.9) million; Non-GAAP operating loss of $(16.2) million <\/i><\/p>\n<p>SAN FRANCISCO&#8211;(<a href=\"http:\/\/www.businesswire.com\">BUSINESS WIRE<\/a>)&#8211;<br \/>\nNew Relic, Inc. (NYSE: NEWR), the observability company, today announced financial results for the first quarter of fiscal year 2022.\n<\/p>\n<p>\n\u201cWe aspire to help millions of developers and engineers build better software, faster and with less toil, by making observability a daily part of a data-driven engineering approach across the entire software lifecycle,\u201d said Bill Staples, CEO, New Relic. \u201cMy top priority is to return our revenue to market growth rates by making this vision a reality for engineers, and delivering unique value to our customers to support their success.\u201d\n<\/p>\n<p><b>First Quarter Fiscal Year 2022 Financial Highlights:<\/b><\/p>\n<ul class=\"bwlistdisc\">\n<li>\nRevenue of $180 million, compared to $163 million for the first quarter of fiscal 2021.\n<\/li>\n<li>\nGAAP gross margin of 67% and non-GAAP gross margin of 69%.\n<\/li>\n<li>\nGAAP loss from operations was $(73.9) million, compared to $(26.1) million for the first quarter of fiscal 2021.\n<\/li>\n<li>\nNon-GAAP income (loss) from operations was $(16.2) million, compared to $7.6 million for the first quarter of fiscal 2021.\n<\/li>\n<li>\nGAAP net loss attributable to New Relic per basic share was $(1.24), compared to a loss of $(0.50) per basic share for the first quarter of fiscal 2021.\n<\/li>\n<li>\nNon-GAAP net income (loss) attributable to New Relic per diluted share was $(0.25), compared to $0.15 per diluted share for the first quarter of fiscal 2021.\n<\/li>\n<li>\nCash provided by operating activities was $9.9 million and free cash flow was $4.8 million for the first quarter of fiscal 2022.\n<\/li>\n<li>\nCash, cash equivalents and short-term investments were $817 million at the end of the first quarter of fiscal 2022, compared with $816 million at the end of the fourth quarter of fiscal 2021.\n<\/li>\n<li>\nRemaining performance obligations were $654 million at the end of the first quarter of fiscal 2022, compared with $727 million at the end of the fourth quarter of fiscal 2021. This represents the aggregate unrecognized transaction price of remaining performance obligations as of each of June 30, 2021 and March 31, 2021.\n<\/li>\n<\/ul>\n<p><b>Key Operating Metrics<sup>1<\/sup>:<\/b><\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td rowspan=\"2\" class=\"bwvertalignb bwleftsingle bwpadl0 bwsinglebottom bwtopsingle\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwtopsingle bwleftsingle bwpadl0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Jun-20<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwtopsingle bwleftsingle bwpadl0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Sep-20<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwtopsingle bwleftsingle bwpadl0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Dec-20<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwtopsingle bwleftsingle bwpadl0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Mar-21<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwtopsingle bwleftsingle bwrightsingle bwpadl0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Jun-21<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>1Q21<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2Q21<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>3Q21<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>4Q21<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwrightsingle bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>1Q22<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nActive Customer Accounts\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n15,400\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n14,500\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n13,900\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n14,100\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwrightsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n14,100\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nActive Customer Accounts &gt;$100,000\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n862\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n894\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n913\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n945\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwrightsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n964\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPercentage of Revenue from Active Customer Accounts &gt;$100,000\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n76%\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n77%\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n78%\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n79%\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwleftsingle bwrightsingle bwpadl0 bwpadr0 bwvertalignb bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n79%\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0 bwleftsingle bwsinglebottom bwvertalignt\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet Revenue Retention Rate (NRR)\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb bwsinglebottom bwalignc bwleftsingle\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n122%\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb bwsinglebottom bwalignc bwleftsingle\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n119%\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb bwsinglebottom bwalignc bwleftsingle\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n115%\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb bwsinglebottom bwalignc bwleftsingle\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n112%\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb bwrightsingle bwsinglebottom bwalignc bwleftsingle\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n111%\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<hr \/>\n<p><sup>1<\/sup> Beginning with fiscal 2022, we introduced new key operating metrics and changed the methodology we are using to count customer accounts. Total customer accounts are now aggregated at the parent hierarchy level and include any account for which we have recognized any revenue in the fiscal quarter. Please refer to the appendix for the definitions of these new key operating metrics.\n<\/p>\n<p><b>Recent Business Highlights:<\/b><\/p>\n<ul class=\"bwlistdisc\">\n<li>\nPromoted <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fir.newrelic.com%2Fpress-releases%2FPress-Release-Details%2F2021%2FNew-Relic-to-Promote-Cloud-Industry-Veteran-Bill-Staples-to-CEO%2Fdefault.aspx&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=Bill+Staples&amp;index=1&amp;md5=979c882f00cacd85cc00fbc6f32e3a5b\">Bill Staples<\/a> to CEO effective July 1, 2021.\n<\/li>\n<li>\nLaunched Industry\u2019s First <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fir.newrelic.com%2Fpress-releases%2FPress-Release-Details%2F2021%2FNew-Relic-Launches-Industrys-First-HIPAA-Compliant-Observability-Platform-to-Help-Healthcare-and-Life-Sciences-Organizations-Deliver-More-Perfect-Software%2Fdefault.aspx&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=HIPAA-Compliant+Observability+Platform&amp;index=2&amp;md5=8ba57f188ab4024ec2b289911f8924ca\">HIPAA-Compliant Observability Platform<\/a>.\n<\/li>\n<li>\nAppointed <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fir.newrelic.com%2Fpress-releases%2FPress-Release-Details%2F2021%2FNew-Relic-Announces-Appointment-of-Former-Disney-Executive-Anita-Lynch-as-Chief-Data-Officer-and-Promotions-to-C-Suite-Leadership%2Fdefault.aspx&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=Anita+Lynch&amp;index=3&amp;md5=2d7a6a870c8bf10bf002df5ebd225f3d\">Anita Lynch<\/a> as Chief Data Officer.\n<\/li>\n<li>\nAppointed <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fir.newrelic.com%2Fpress-releases%2FPress-Release-Details%2F2021%2FNew-Relic-Appoints-RK-Mahendran-Partner-at-HMI-Capital-as-Director%2Fdefault.aspx&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=RK+Mahendran&amp;index=4&amp;md5=ace177bd6273bd9141161b432257bf45\">RK Mahendran<\/a> as Director.\n<\/li>\n<li>\nNamed a leader in the 2021 <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fir.newrelic.com%2Fpress-releases%2FPress-Release-Details%2F2021%2FNew-Relic-Named-a-Leader-in-the-2021-Gartner-Magic-Quadrant-for-Application-Performance-Monitoring-for-the-Ninth-Time%2Fdefault.aspx&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=Gartner+Magic+Quadrant&amp;index=5&amp;md5=4f40b8df4659e7fa3e08325acc11c089\">Gartner Magic Quadrant<\/a> for Application Performance Monitoring for the Ninth Time.\n<\/li>\n<\/ul>\n<p><b>Outlook:<\/b><\/p>\n<ul class=\"bwlistdisc\">\n<li>\nSecond Quarter Fiscal 2022 Outlook:<\/p>\n<ul class=\"bwlistcircle\">\n<li>\nRevenue between $181 million and $183 million, representing year-over-year growth of approximately 9% and 10%.\n<\/li>\n<li>\nNon-GAAP loss from operations between $(13) million and $(15) million.\n<\/li>\n<li>\nNon-GAAP net loss attributable to New Relic per diluted share between $(0.11) and $(0.15).\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul class=\"bwlistdisc\">\n<li>\nFull Year Fiscal 2022 Outlook:<\/p>\n<ul class=\"bwlistcircle\">\n<li>\nRevenue between $730 million and $735 million, representing year-over-year growth of approximately 9% and 10%.\n<\/li>\n<li>\nNon-GAAP loss from operations between $(53) million and $(55) million.\n<\/li>\n<li>\nNon-GAAP net loss attributable to New Relic per diluted share between $(0.49) and $(0.52).\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>\nNew Relic has not reconciled its expectations as to non-GAAP income (loss) from operations or non-GAAP net income (loss) per diluted share to their most directly comparable GAAP measures as a result of uncertainty regarding, and the potential variability of, reconciling items such as stock-based compensation expense, lawsuit litigation cost and other expense, employer payroll taxes on equity incentive plans and gain or loss from lease modification. Accordingly, reconciliation is not available without unreasonable effort, although it is important to note that these factors could be material to New Relic\u2019s results computed in accordance with GAAP.\n<\/p>\n<p><b>Conference Call and Investor Letter Details:<\/b><\/p>\n<ul class=\"bwlistdisc\">\n<li><b>What:<\/b> New Relic financial results for the first quarter of fiscal year 2022 and outlook for the second quarter and the full year of fiscal 2022.\n<\/li>\n<li><b>When:<\/b> August 3, 2021 at 2:00 P.M. Pacific Time (5:00 P.M. Eastern Time)\n<\/li>\n<li><b>Dial in:<\/b> To access the call in the United States, please dial (844) 757-5730, and for international callers, please dial (412) 542-4120. Callers may provide confirmation number 10158237 to access the call more quickly, and are encouraged to dial into the call at least 15 minutes prior to the start to prevent any delay in joining.\n<\/li>\n<li><b>Webcast:<\/b><a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=http%3A%2F%2Fir.newrelic.com%2F&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=http%3A%2F%2Fir.newrelic.com&amp;index=6&amp;md5=6a9fe9fc3ef5752d61b6961348a3b310\">http:\/\/ir.newrelic.com<\/a> (live and replay)\n<\/li>\n<li><b>Investor Letter: <\/b>Available at <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=http%3A%2F%2Fir.newrelic.com%2F&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=http%3A%2F%2Fir.newrelic.com&amp;index=7&amp;md5=4eb8513736af0a8f53167072e7604882\">http:\/\/ir.newrelic.com<\/a><\/li>\n<li><b>Replay: <\/b>Following the completion of the call through 11:59 PM Eastern Time on August 10, 2021, a telephone replay will be available by dialing (877) 344-7529 from the United States or (412) 317-0088 internationally with conference ID 10158237.\n<\/li>\n<\/ul>\n<p><b>About New Relic<\/b><\/p>\n<p>\nThe world\u2019s best engineering teams rely on New Relic to visualize, analyze and troubleshoot their software. New Relic One is the most powerful cloud-based observability platform built to help companies create more perfect software. Learn why developers trust New Relic for improved uptime and performance, greater scale and efficiency, and accelerated time to market at <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=http%3A%2F%2Fnewrelic.com%2F&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=newrelic.com&amp;index=8&amp;md5=ee9e28a412d26f095d7fd70c4d82c6de\">newrelic.com<\/a>.\n<\/p>\n<p><b>Forward-Looking Statements<\/b><\/p>\n<p>\nThis press release and the earnings call referencing this press release contain \u201cforward-looking\u201d statements, as that term is defined under the federal securities laws, including but not limited to statements regarding: New Relic\u2019s future financial performance, including its outlook on financial results for the second quarter and the full year of fiscal 2022, such as revenue, non-GAAP loss from operations, non-GAAP net loss attributable to New Relic per diluted share, our ability to achieve our five strategic priorities, including statements regarding reacceleration of revenue growth and returning to market growth rates, ability to exceed our target revenue percentage on the new consumption model, growing the number of paying customers, delivering unique value and demonstrating our differentiated platform vision, and improving internal execution efficiency and costs, improvements in gross margins, churn, ability to complete our cloud migration, benefits and features of new products and partnerships, including Errors Inbox, Logs, Kubernetes and Network Monitoring, trends related to sales and marketing and research and development spend as a percentage of revenue, our revenue mix in the intermediate and longer-term, expectations of growth in awareness and increase adoption in the observability community, and related ability to continue to drive growth in our data, users and accounts. These forward-looking statements are based on New Relic\u2019s current assumptions, expectations and beliefs and are subject to substantial risks, uncertainties, assumptions and changes in circumstances that may cause New Relic\u2019s actual results, performance or achievements to differ materially from those expressed or implied in any forward-looking statement.\n<\/p>\n<p>\nThe risks and uncertainties referred to above include, but are not limited to, New Relic\u2019s ability to determine optimal prices for its products and the potential challenges presented by New Relic\u2019s evolving pricing models; the effect of the COVID-19 pandemic on New Relic\u2019s business and on global economies and financial markets generally; New Relic\u2019s ability to generate sufficient revenue to achieve and sustain profitability, particularly in light of its significant ongoing expenses; New Relic\u2019s short operating history in an evolving industry; New Relic\u2019s ability to manage its significant recent growth; the dependence of New Relic\u2019s business on its customers remaining on its platform and increasing their spend with New Relic; New Relic\u2019s ability to develop enhancements to its products, increase adoption and usage of its products and introduce new products that achieve market acceptance; the dependence on customers expanding their use of New Relic\u2019s products beyond the current predominant use cases; New Relic\u2019s ability to expand its marketing and sales capabilities and increase sales of its solutions; privacy concerns, including changes in privacy laws and regulations, which could result in additional cost and liability to New Relic or inhibit sales; New Relic\u2019s ability to effectively compete in intensely competitive markets and respond effectively to rapidly changing technology, evolving industry standards and changing customer needs, requirements or preferences; fluctuation of New Relic\u2019s quarterly results; New Relic\u2019s dependence on lead generation strategies to drive sales and revenue; interruptions or performance problems associated with New Relic\u2019s technology and infrastructure; New Relic\u2019s dependence on SaaS technologies and related services from third parties; defects or disruptions in New Relic\u2019s products; the expense and complexity of New Relic\u2019s ongoing and planned investments in data center hosting facilities and expenditures on cloud hosting providers; risks associated with international operations; New Relic\u2019s ability to protect its intellectual property rights; risks related to the acquisition and integration of businesses or technologies; risks related to sales to government entities and highly regulated organizations; certain risks associated with incurring indebtedness, including risks related to servicing New Relic\u2019s convertible senior notes and related capped call transactions; and other \u201cRisk Factors\u201d set forth in New Relic\u2019s most recent filings with the Securities and Exchange Commission (the \u201cSEC\u201d).\n<\/p>\n<p>\nFurther information on these and other factors that could affect New Relic\u2019s financial results and the forward-looking statements in this press release and in the earnings call referencing this press release is included in the filings New Relic makes with the SEC from time to time, particularly under the captions \u201cRisk Factors\u201d and \u201cManagement\u2019s Discussion and Analysis of Financial Condition and Results of Operations,\u201d including our Annual Report on Form 10-K and subsequent Quarterly Reports on Form 10-Q and subsequent filings. Copies of these documents may be obtained by visiting New Relic\u2019s Investor Relations website at <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=http%3A%2F%2Fir.newrelic.com%2F&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=http%3A%2F%2Fir.newrelic.com&amp;index=9&amp;md5=5d5cd605179b14e740806e14869db6bc\">http:\/\/ir.newrelic.com<\/a> or the SEC\u2019s website at <a rel=\"nofollow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=http%3A%2F%2Fwww.sec.gov%2F&amp;esheet=52470405&amp;newsitemid=20210803006058&amp;lan=en-US&amp;anchor=www.sec.gov&amp;index=10&amp;md5=b71ab8514ac4482551336f8bae019f15\">www.sec.gov<\/a>.\n<\/p>\n<p>\nAll information provided in this press release and in the earnings call is as of the date hereof and New Relic assumes no obligation and does not intend to update these forward-looking statements, except as required by law.\n<\/p>\n<p><b>Non-GAAP Financial Measures<\/b><\/p>\n<p>\nNew Relic discloses the following non-GAAP financial measures in this press release and the earnings call referencing this press release: non-GAAP income (loss) from operations, non-GAAP gross profit, non-GAAP gross margin, non-GAAP operating expenses (sales and marketing, research and development, general and administrative), non-GAAP operating margin, non-GAAP net income (loss) attributable to New Relic, non-GAAP net income (loss) attributable to New Relic per diluted share, non-GAAP net income (loss) attributable to New Relic per basic share and free cash flow. New Relic uses each of these non-GAAP financial measures internally to understand and compare operating results across accounting periods, for internal budgeting and forecasting purposes, for short- and long-term operating plans, and to evaluate New Relic\u2019s financial performance. In addition, New Relic\u2019s bonus plan for eligible employees and executives is based in part on non-GAAP income (loss) from operations. New Relic believes these non-GAAP financial measures are useful to investors, as a supplement to GAAP measures, in evaluating its operational performance, as further discussed below. New Relic\u2019s non-GAAP financial measures may not provide information that is directly comparable to that provided by other companies in its industry, as other companies in its industry may calculate non-GAAP financial results differently, particularly related to non-recurring and unusual items. In addition, there are limitations in using non-GAAP financial measures because the non-GAAP financial measures are not prepared in accordance with GAAP and may be different from non-GAAP financial measures used by other companies and exclude expenses that may have a material impact on New Relic\u2019s reported financial results.\n<\/p>\n<p>\nNon-GAAP financial measures should not be considered in isolation from, or as a substitute for, financial information prepared in accordance with GAAP. A reconciliation of the historical non-GAAP financial measures to their most directly comparable GAAP measures has been provided in the financial statement tables included below in this press release.\n<\/p>\n<p>\nNew Relic defines non-GAAP income (loss) from operations, non-GAAP gross profit, non-GAAP gross margin, non-GAAP operating expenses (sales and marketing, research and development, general and administrative), non-GAAP operating margin, non-GAAP net income (loss) attributable to New Relic, non-GAAP net income (loss) attributable to New Relic per diluted share and non-GAAP net income (loss) attributable to New Relic per basic share as the respective GAAP balances, adjusted for, as applicable: (1) stock-based compensation expense, (2) amortization of stock-based compensation capitalized in software development costs, (3) the amortization of purchased intangibles, (4) employer payroll tax expense on equity incentive plans, (5) amortization of debt discount and issuance costs, (6) the transaction costs related to acquisitions, (7) lawsuit litigation cost and other expense, (8) gain or loss from lease modification, (9) adjustment to redeemable non-controlling interest, and (10) restructuring charges. Non-GAAP net income (loss) per basic and diluted share is calculated as non-GAAP net income (loss) attributable to New Relic divided by weighted-average shares used to compute net income (loss) attributable to New Relic per share, basic and diluted, with the number of weighted-average shares decreased to reflect the anti-dilutive impact of the capped call transactions entered into in connection with the 0.50% Convertible Senior Notes due 2023 issued in May 2018. New Relic defines free cash flow as GAAP cash from operations, minus capital expenditures and minus capitalized software. Investors are encouraged to review the reconciliation of these historical non-GAAP financial measures to their most directly comparable GAAP financial measures.\n<\/p>\n<p>\nManagement believes these non-GAAP financial measures are useful to investors and others in assessing New Relic\u2019s operating performance due to the following factors:\n<\/p>\n<p><i>Stock-based compensation expense and amortization of stock-based compensation capitalized in software development costs.<\/i> New Relic utilizes share-based compensation to attract and retain employees. It is principally aimed at aligning their interests with those of its stockholders and at long-term retention, rather than to address operational performance for any particular period. As a result, share-based compensation expenses vary for reasons that are generally unrelated to financial and operational performance in any particular period.\n<\/p>\n<p><i>Amortization of purchased intangibles and transaction costs related to acquisitions. <\/i>New Relic views amortization of purchased intangible assets as items arising from pre-acquisition activities determined at the time of an acquisition. While these intangible assets are evaluated for impairment regularly, amortization of the cost of purchased intangibles is an expense that is not typically affected by operations during any particular period. Similarly, New Relic views acquisition-related expenses as events that are not necessarily reflective of operational performance during a period.\n<\/p>\n<p><i>Employer payroll tax expense on equity incentive plans. <\/i>New Relic excludes employer payroll tax expense on equity incentive plans as these expenses are tied to the exercise or vesting of underlying equity awards and the price of New Relic\u2019s common stock at the time of vesting or exercise. As a result, these taxes may vary in any particular period independent of the financial and operating performance of New Relic\u2019s business.\n<\/p>\n<p><i>Amortization of debt discount and issuance costs. <\/i>In May 2018, New Relic issued $500.25 million of convertible senior notes due in 2023, which bear interest at an annual fixed rate of 0.50%. The effective interest rate of the convertible senior notes was approximately 5.74%. Effective April 1, 2021 New Relic adopted ASU No. 2020-06, <i>Accounting for Convertible Instruments and Contract on an Entity\u2019s Own Equity<\/i>. As a result of the adoption, the debt conversion option and debt issuance costs previously attributable to the equity component will no longer be presented in equity. Similarly, the debt discount, which is equal to the carrying value of the embedded conversion feature upon issuance, will no longer be amortized into income as interest expense over the life of the instrument. The debt issuance costs are amortized as interest expense. The expense for the amortization of debt issuance costs is a non-cash item, and New Relic believes the exclusion of this interest expense will provide for a more useful comparison of our operational performance in different periods.\n<\/p>\n<p><i>Transaction costs related to acquisitions. <\/i>New Relic may from time to time incur direct transaction costs related to acquisitions. New Relic believes it is useful to exclude such charges because it does not consider such amounts to be part of the ongoing operation of New Relic\u2019s business.\n<\/p>\n<p><i>Lawsuit litigation cost and other expense. <\/i>New Relic may from time to time incur charges or benefits related to litigation that are outside of the ordinary course of New Relic\u2019s business. New Relic believes it is useful to exclude such charges or benefits because it does not consider such amounts to be part of the ongoing operation of New Relic\u2019s business and because of the singular nature of the claims underlying the matter.\n<\/p>\n<p><i>Gain or loss from lease modification. <\/i>New Relic may incur a gain or loss from modification related to lease agreements. New Relic believes it is useful to exclude such charges or benefits because it does not consider such amounts to be part of the ongoing operation of New Relic\u2019s business and because of the singular nature of benefit or charge from such events.\n<\/p>\n<p><i>Adjustment to redeemable non-controlling interest. <\/i>In second quarter fiscal year 2022, New Relic made an adjustment to the value of redeemable non-controlling interest in connection with its joint venture in New Relic K.K. New Relic believes it is useful to exclude the adjustment to redeemable non-controlling interest because it may not be indicative of future operating results and that investors benefit from an understanding of the company\u2019s operating results without giving effect to this adjustment.\n<\/p>\n<p><i>Restructuring charges.<\/i> In April 2021, New Relic commenced a restructuring plan to realign its cost structure to better reflect significant product and business model innovation over the past 12 months. As a result of the restructuring plan, New Relic incurred charges of approximately $13.0 million for employee terminations and other costs associated with the restructuring plan. Most of these charges consisted of cash expenditures and stock-based compensation expense and were recognized in the first quarter of fiscal 2022. New Relic believes it is appropriate to exclude the restructuring charges because it is not indicative of its future operating results.\n<\/p>\n<p><i>Anti-dilutive impact of capped call transactions<\/i>. In connection with the issuance of its convertible senior notes due in 2023, New Relic entered into capped call transactions to offset potential dilution from the embedded conversion feature in the notes. Although New Relic cannot reflect the anti-dilutive impact of the capped call transactions under GAAP, New Relic does reflect the anti-dilutive impact of the capped call transactions in non-GAAP net income (loss) attributable to New Relic per share, basic and diluted, to provide investors with useful information in evaluating the financial performance of the company on a per share basis.\n<\/p>\n<p>\nAdditionally, New Relic\u2019s management believes that the non-GAAP financial measure free cash flow is meaningful to investors because management reviews cash flows generated from operations after taking into consideration capital expenditures and the capitalization of software development costs due to the fact that these expenditures are considered to be a necessary component of ongoing operations.\n<\/p>\n<p><b>Operating Metrics<\/b><\/p>\n<p><i>Active Customer Accounts.<\/i> New Relic defines an Active Customer Account at the end of any period as an individual account, as identified by a unique account identifier, aggregated at the parent hierarchy level, for which New Relic has recognized any revenue in the fiscal quarter. The number of Active Customer Accounts that is reported as of a particular date is rounded down to the nearest hundred.\n<\/p>\n<p><i>Number of Active Customer Accounts with Revenue Greater than $100,000. <\/i>As a measure of New Relic\u2019s ability to scale with its customers and attract large enterprises to its platform, New Relic counts the number of Active Customer Accounts for which it has recognized greater than $100,000 in revenue in the trailing 12-months.\n<\/p>\n<p><i>Percentage of Revenue from Active Customer Accounts Greater than $100,000<\/i>. New Relic also looks at its percentage of overall revenue it receives from its Active Customer Accounts with revenue greater than $100,000 in any given quarter as an indicator of its relative performance when selling to New Relic\u2019s large customer relationships or its smaller revenue accounts.\n<\/p>\n<p><i>Net Revenue Retention Rate (\u201cNRR\u201d). <\/i>NRR monitors the growth in use of New Relic\u2019s platform by its existing active customer accounts and allows New Relic to measure the health of its business and future growth prospects. To calculate NRR, New Relic first identifies the cohort of Active Customer Accounts that were Active Customer Accounts in the same quarter of the prior fiscal year. Next, New Relic identifies the measurement period as the 12-month period ending with the period reported and the prior comparison period as the corresponding period in the prior year. NRR is the quotient obtained by dividing the revenue generated from a cohort of Active Customer Accounts in the measurement period by the revenue generated from that same cohort in the prior comparison period.\n<\/p>\n<p>\nNew Relic is a registered trademark of New Relic, Inc.\n<\/p>\n<p>\nAll product and company names herein may be trademarks of their registered owners.\n<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0\" colspan=\"8\" rowspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Condensed Consolidated Statements of Operations<\/b><\/p>\n<p class=\"bwcellpmargin\">\n(In thousands, except per share data; unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"7\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwnowrap bwalignc\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Three Months Ended June 30,<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2021<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2020<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nRevenue\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n180,484\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n162,585\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCost of revenue\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n59,264\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n33,273\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nGross profit\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n121,220\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n129,312\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nOperating expenses:\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nResearch and development\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n48,730\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n40,844\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nSales and marketing\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n102,813\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n85,136\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nGeneral and administrative\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n43,565\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n29,434\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTotal operating expenses\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n195,108\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n155,414\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLoss from operations\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(73,888\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(26,102\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nOther income (expense):\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nInterest income\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n938\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,781\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nInterest expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,226\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(6,104\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nOther expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(336\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(395\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLoss before income taxes\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(74,512\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(29,820\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nIncome tax provision (benefit)\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(453\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n332\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet loss\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(74,059\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(30,152\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet loss and adjustment attributable to redeemable non-controlling interest\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(4,355\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n396\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet loss attributable to New Relic\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(78,414\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(29,756\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet loss attributable to New Relic per share, basic and diluted\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1.24\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(0.50\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nWeighted-average shares used to compute net loss per share, basic and diluted\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n63,339\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n59,927\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0\" colspan=\"8\" rowspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Condensed Consolidated Balance Sheets<\/b><\/p>\n<p class=\"bwcellpmargin\">\n(In thousands, except par value; unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwnowrap\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>June 30, 2021<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwnowrap\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>March 31, 2021<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Assets<\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCurrent assets:\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCash and cash equivalents\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n259,897\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n240,821\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nShort-term investments\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n557,223\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n575,254\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccounts receivable, net of allowances of $2,464 and $2,633, respectively\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n93,477\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n174,027\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPrepaid expenses and other current assets\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n22,172\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n21,944\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDeferred contract acquisition costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n33,032\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n36,210\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTotal current assets\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n965,801\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,048,256\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nProperty and equipment, net\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n84,645\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n91,308\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nRestricted cash\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,642\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,642\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nGoodwill\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n163,677\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n144,253\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nIntangible assets, net\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n21,610\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,986\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDeferred contract acquisition costs, non-current\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n25,707\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,579\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLease right-of-use assets\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n55,034\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n57,425\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nOther assets, non-current\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,976\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,170\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTotal assets\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,328,092\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,398,619\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Liabilities, redeemable non-controlling interest and stockholders\u2019 equity<\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCurrent liabilities:\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccounts payable\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n27,631\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n24,171\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccrued compensation and benefits\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,319\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n37,196\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nOther current liabilities\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n15,779\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n19,174\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDeferred revenue\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n316,458\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n373,594\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLease liabilities\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n7,714\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n7,886\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTotal current liabilities\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n399,901\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n462,021\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nConvertible senior notes, net\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n495,893\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n449,380\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLease liabilities, non-current\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n57,578\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n59,924\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDeferred revenue, non-current\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,044\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,674\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nOther liabilities, non-current\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n15,789\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n8,256\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTotal liabilities\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n970,205\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n981,255\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nRedeemable non-controlling interest\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n7,744\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n3,389\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nStockholders\u2019 equity:\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCommon stock, $0.001 par value\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n64\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n64\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTreasury stock &#8211; at cost (260 shares)\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(263\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(263\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAdditional paid-in capital\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n962,512\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,001,309\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccumulated other comprehensive loss\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(850\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(19\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccumulated deficit\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(611,320\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(587,116\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTotal stockholders\u2019 equity\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n350,143\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n413,975\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nTotal liabilities, redeemable non-controlling interest, and stockholders\u2019 equity\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,328,092\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,398,619\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0\" colspan=\"8\" rowspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Condensed Consolidated Statements of Cash Flows<\/b><\/p>\n<p class=\"bwcellpmargin\">\n(In thousands; unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"7\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwnowrap bwalignc\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Three Months Ended June 30,<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2021<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2020<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Cash flows from operating activities:<\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet loss attributable to New Relic\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(78,414\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(29,756\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet loss and adjustment attributable to redeemable non-controlling interest\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,355\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(396\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet loss:\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(74,059\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(30,152\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAdjustments to reconcile net loss to net cash provided by operating activities:\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDepreciation and amortization\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n23,025\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n21,051\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nStock-based compensation expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n42,187\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n31,208\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAmortization of debt discount and issuance costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n587\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,466\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nOther\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(922\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(222\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nChanges in operating assets and liabilities, net of acquisition of business:\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccounts receivable, net\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n80,550\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n36,065\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPrepaid expenses and other assets\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n18\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3,155\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDeferred contract acquisition costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(190\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(9,388\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLease right-of-use assets\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,692\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,249\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccounts payable\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,894\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3,923\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nAccrued compensation and benefits and other liabilities\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(8,627\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,573\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLease liabilities\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,517\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,347\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl6\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDeferred revenue\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(57,766\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(16,473\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Net cash provided by operating activities<\/b><\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n9,872\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n35,148\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Cash flows from investing activities:<\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPurchases of property and equipment\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,226\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(8,225\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCash paid for acquisition, net of cash acquired\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(7,192\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPurchases of short-term investments\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(23,828\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(73,422\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nProceeds from sale and maturity of short-term investments\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n40,513\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n13,100\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCapitalized software development costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,860\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3,668\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Net cash provided by (used in) investing activities<\/b><\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,407\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(72,215\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Cash flows from financing activities:<\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nProceeds from exercise of employee stock options\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,797\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,424\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Net cash provided by financing activities<\/b><\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,797\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,424\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNet increase (decrease) in cash, cash equivalents and restricted cash\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n19,076\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(35,643\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCash, cash equivalents and restricted cash at beginning of period\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n246,463\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n298,164\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCash, cash equivalents and restricted cash at end of period\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n265,539\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n262,521\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0\" colspan=\"8\" rowspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Reconciliation from GAAP to Non-GAAP Results <\/b><\/p>\n<p class=\"bwcellpmargin\">\n(In thousands, except per share data; unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"7\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwnowrap bwalignc\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Three Months Ended June 30,<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2021<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwalignc\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwalignc\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2020<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b><span class=\"bwuline\">Reconciliation of gross profit and gross margin:<\/span><\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP gross profit<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n121,220\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n129,312\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Stock-based compensation expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,072\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,502\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Amortization of purchased intangibles\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,676\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,276\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Amortization of stock-based compensation capitalized in software development costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n420\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n239\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Employer payroll tax on employee equity incentive plans\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n52\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n91\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP gross profit<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n124,440\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n132,420\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP gross margin<\/b><\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n67\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n80\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNon-GAAP adjustments\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP gross margin<\/b><\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n69\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n81\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b><span class=\"bwuline\">Reconciliation of operating expenses:<\/span><\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP research and development<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n48,730\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n40,844\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Stock-based compensation expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(10,964)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(8,804)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Employer payroll tax on employee equity incentive plans\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(299)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(349)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP research and development<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n37,467\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n31,691\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP sales and marketing<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n102,813\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n85,136\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Stock-based compensation expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(11,534)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(13,308)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Employer payroll tax on employee equity incentive plans\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(245)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(359)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Restructuring charges (1)\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(11,071)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP sales and marketing<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n79,963\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n71,469\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP general and administrative<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n43,565\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n29,434\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Stock-based compensation expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(18,617)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(7,594)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Transaction costs related to acquisitions\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(361)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Employer payroll tax on employee equity incentive plans\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(217)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(149)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nLess: Restructuring charges (1)\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,208)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP general and administrative<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n23,162\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n21,691\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b><span class=\"bwuline\">Reconciliation of income (loss) from operations and operating margin:<\/span><\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP loss from operations<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(73,888)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(26,102)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Stock-based compensation expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n42,187\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n31,208\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Amortization of purchased intangibles\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,676\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,276\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Transaction costs related to acquisitions\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n361\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Amortization of stock-based compensation capitalized in software development costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n420\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n239\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Employer payroll tax on employee equity incentive plans\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n813\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n948\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Restructuring charges (1)\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,279\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP income (loss) from operations<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(16,152)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n7,569\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP operating margin<\/b><\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(41)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(16)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nNon-GAAP adjustments\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n21\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP operating margin<\/b><\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(9)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignl bwcellpmargin\">\n%\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b><span class=\"bwuline\">Reconciliation of net income (loss):<\/span><\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>GAAP net loss attributable to New Relic<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(78,414)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(29,756)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Stock-based compensation expense\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n42,187\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n31,208\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Amortization of purchased intangibles\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,676\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,276\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Transaction costs related to acquisitions\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n361\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Amortization of stock-based compensation capitalized in software development costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n420\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n239\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Employer payroll tax on employee equity incentive plans\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n813\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n948\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Amortization of debt discount and issuance costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n587\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,466\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Adjustment to redeemable non-controlling interest\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,395\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nPlus: Restructuring charges (1)\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,279\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP net income (loss) attributable to New Relic<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(15,696)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n9,381\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Non-GAAP net income (loss) attributable to New Relic per share:<\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nBasic\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(0.25)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n0.16\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDiluted\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(0.25)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n0.15\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Shares used in non-GAAP per share calculations:<\/b><\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nBasic\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n63,339\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n59,927\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nDiluted\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n63,339\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n61,285\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<p>\n(1) Restructuring related charge for the stock-based compensation expense of $0.5 million is included on its respective line items.\n<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0\" colspan=\"8\" rowspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Reconciliation of GAAP Cash Flows from Operating Activities to Free Cash Flow<\/b><\/p>\n<p class=\"bwcellpmargin\">\n(In thousands; unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"7\" class=\"bwvertalignb bwsinglebottom bwnowrap bwalignc bwpadl3\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\"><b>Three Months Ended June 30,<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadr0 bwalignc bwpadl3\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2021<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwalignc bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"3\" class=\"bwvertalignb bwsinglebottom bwpadr0 bwalignc bwpadl3\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\"><b>2020<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Net cash provided by operating activities<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n9,872\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n35,148\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCapital expenditures\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,226\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(8,225\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl3\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\nCapitalized software development costs\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,860\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td colspan=\"2\" class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3,668\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Free cash flow (Non-GAAP)<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,786\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n23,255\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Net cash provided by (used in) investing activities<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,407\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(72,215\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\"><b>Net cash provided by financing activities<\/b><\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,797\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,424\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" rowspan=\"1\" colspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<p>\n\u00a0\n<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en\" style=\"width:0;height:0\" \/><span class=\"bwct31415\" \/><\/p>\n<p id=\"mmgallerylink\"><span id=\"mmgallerylink-phrase\">View source version on businesswire.com: <\/span><span id=\"mmgallerylink-link\"><a href=\"https:\/\/www.businesswire.com\/news\/home\/20210803006058\/en\/\" rel=\"nofollow\">https:\/\/www.businesswire.com\/news\/home\/20210803006058\/en\/<\/a><\/span><\/p>\n<p><b>Investor Contact<br \/>\n<\/b><br \/>Peter Goldmacher<br \/>\n<br \/>New Relic, Inc.<br \/>\n<br \/>503-336-9280<br \/>\n<br \/><a rel=\"nofollow\" href=\"mailto:IR@newrelic.com\">IR@newrelic.com <\/a><\/p>\n<p><b>Media Contact<br \/>\n<\/b><br \/>New Relic, Inc<br \/>\n<br \/><a rel=\"nofollow\" href=\"mailto:PR@newrelic.com\">PR@newrelic.com<br \/>\n<\/a><\/p>\n<p><b>KEYWORDS:<\/b> United States North America California<\/p>\n<p><b>INDUSTRY KEYWORDS:<\/b> Software Technology Internet Data Management<\/p>\n<p><b>MEDIA:<\/b><\/p>\n<table cellpadding=\"3\" cellspacing=\"3\">\n<tr>\n<td><font face=\"Arial\" size=\"2\"><b>Logo<\/b><\/font><\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/mms.businesswire.com\/media\/20210803006058\/en\/777477\/3\/newrelic_logo.jpg\" alt=\"Logo\" \/><\/td>\n<\/tr>\n<tr>\n<td><font face=\"Arial\" size=\"2\"><\/font><\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0New Relic Announces First Quarter Fiscal Year 2022 Results \u00a0First quarter revenue increased 11% year-over-year to $180 million Quarterly GAAP operating loss of $(73.9) million; Non-GAAP operating loss of $(16.2) million SAN FRANCISCO&#8211;(BUSINESS WIRE)&#8211; New Relic, Inc. (NYSE: NEWR), the observability company, today announced financial results for the first quarter of fiscal year 2022. \u201cWe aspire to help millions of developers and engineers build better software, faster and with less toil, by making observability a daily part of a data-driven engineering approach across the entire software lifecycle,\u201d said Bill Staples, CEO, New Relic. \u201cMy top priority is to return our revenue to market growth rates by making this vision a reality for engineers, and delivering unique value to our customers &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;New Relic Announces First Quarter Fiscal Year 2022 Results&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-522407","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Relic Announces First Quarter Fiscal Year 2022 Results - Market Newsdesk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Relic Announces First Quarter Fiscal Year 2022 Results - Market Newsdesk\" \/>\n<meta property=\"og:description\" content=\"\u00a0New Relic Announces First Quarter Fiscal Year 2022 Results \u00a0First quarter revenue increased 11% year-over-year to $180 million Quarterly GAAP operating loss of $(73.9) million; Non-GAAP operating loss of $(16.2) million SAN FRANCISCO&#8211;(BUSINESS WIRE)&#8211; New Relic, Inc. (NYSE: NEWR), the observability company, today announced financial results for the first quarter of fiscal year 2022. \u201cWe aspire to help millions of developers and engineers build better software, faster and with less toil, by making observability a daily part of a data-driven engineering approach across the entire software lifecycle,\u201d said Bill Staples, CEO, New Relic. \u201cMy top priority is to return our revenue to market growth rates by making this vision a reality for engineers, and delivering unique value to our customers &hellip; Continue reading &quot;New Relic Announces First Quarter Fiscal Year 2022 Results&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Market Newsdesk\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-03T20:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en\" \/>\n<meta name=\"author\" content=\"Newsdesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsdesk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/\"},\"author\":{\"name\":\"Newsdesk\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"headline\":\"New Relic Announces First Quarter Fiscal Year 2022 Results\",\"datePublished\":\"2021-08-03T20:09:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/\"},\"wordCount\":4264,\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/\",\"name\":\"New Relic Announces First Quarter Fiscal Year 2022 Results - Market Newsdesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en\",\"datePublished\":\"2021-08-03T20:09:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en\",\"contentUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/new-relic-announces-first-quarter-fiscal-year-2022-results\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Relic Announces First Quarter Fiscal Year 2022 Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#website\",\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/\",\"name\":\"Market Newsdesk\",\"description\":\"Latest Business News in Real Time\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/#\\\/schema\\\/person\\\/482f27a394d4fda80ecb5499e519d979\",\"name\":\"Newsdesk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g\",\"caption\":\"Newsdesk\"},\"url\":\"https:\\\/\\\/www.marketnewsdesk.com\\\/index.php\\\/author\\\/newsdesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Relic Announces First Quarter Fiscal Year 2022 Results - Market Newsdesk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/","og_locale":"en_US","og_type":"article","og_title":"New Relic Announces First Quarter Fiscal Year 2022 Results - Market Newsdesk","og_description":"\u00a0New Relic Announces First Quarter Fiscal Year 2022 Results \u00a0First quarter revenue increased 11% year-over-year to $180 million Quarterly GAAP operating loss of $(73.9) million; Non-GAAP operating loss of $(16.2) million SAN FRANCISCO&#8211;(BUSINESS WIRE)&#8211; New Relic, Inc. (NYSE: NEWR), the observability company, today announced financial results for the first quarter of fiscal year 2022. \u201cWe aspire to help millions of developers and engineers build better software, faster and with less toil, by making observability a daily part of a data-driven engineering approach across the entire software lifecycle,\u201d said Bill Staples, CEO, New Relic. \u201cMy top priority is to return our revenue to market growth rates by making this vision a reality for engineers, and delivering unique value to our customers &hellip; Continue reading \"New Relic Announces First Quarter Fiscal Year 2022 Results\"","og_url":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/","og_site_name":"Market Newsdesk","article_published_time":"2021-08-03T20:09:42+00:00","og_image":[{"url":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en","type":"","width":"","height":""}],"author":"Newsdesk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Newsdesk","Est. reading time":"21 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/#article","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/"},"author":{"name":"Newsdesk","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"headline":"New Relic Announces First Quarter Fiscal Year 2022 Results","datePublished":"2021-08-03T20:09:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/"},"wordCount":4264,"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/#primaryimage"},"thumbnailUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/","url":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/","name":"New Relic Announces First Quarter Fiscal Year 2022 Results - Market Newsdesk","isPartOf":{"@id":"https:\/\/www.marketnewsdesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/#primaryimage"},"image":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/#primaryimage"},"thumbnailUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en","datePublished":"2021-08-03T20:09:42+00:00","author":{"@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979"},"breadcrumb":{"@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/#primaryimage","url":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en","contentUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20210803006058r1&amp;sid=flmnd&amp;distro=nx&amp;lang=en"},{"@type":"BreadcrumbList","@id":"https:\/\/www.marketnewsdesk.com\/index.php\/new-relic-announces-first-quarter-fiscal-year-2022-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marketnewsdesk.com\/"},{"@type":"ListItem","position":2,"name":"New Relic Announces First Quarter Fiscal Year 2022 Results"}]},{"@type":"WebSite","@id":"https:\/\/www.marketnewsdesk.com\/#website","url":"https:\/\/www.marketnewsdesk.com\/","name":"Market Newsdesk","description":"Latest Business News in Real Time","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marketnewsdesk.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.marketnewsdesk.com\/#\/schema\/person\/482f27a394d4fda80ecb5499e519d979","name":"Newsdesk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d0bd5b0f0ca12a265a459b13169dac35f33776d8501eda5e68844a366f2f46?s=96&d=mm&r=g","caption":"Newsdesk"},"url":"https:\/\/www.marketnewsdesk.com\/index.php\/author\/newsdesk\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/522407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/comments?post=522407"}],"version-history":[{"count":0,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/posts\/522407\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/media?parent=522407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/categories?post=522407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marketnewsdesk.com\/index.php\/wp-json\/wp\/v2\/tags?post=522407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}